{"id":37516,"date":"2025-07-26T19:04:17","date_gmt":"2025-07-26T17:04:17","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/"},"modified":"2025-07-26T19:04:17","modified_gmt":"2025-07-26T17:04:17","slug":"la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/","title":{"rendered":"La corte dei Loggiati di San Domenico diventa piazza Andrea Camilleri. Inaugurazione con Zingaretti"},"content":{"rendered":"<p><em>Una targa in ottone con la dicitura &#8220;Andrea Camilleri &#8211; Scrittore e drammaturgo (1925 &#8211; 2019)&#8221; da oggi sar\u00e0 affissa alle pareti della corte interna dei Loggiati di San Domenico, di fronte alla biblioteca &#8220;Luzi&#8221;.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<div>Una targa in ottone con la dicitura<b>\u00a0&#8220;Andrea Camilleri &#8211; Scrittore e drammaturgo (1925 &#8211; 2019)&#8221;<\/b>\u00a0da oggi sar\u00e0 affissa alle pareti della corte interna dei\u00a0<b>Loggiati di San Domenico<\/b>, di fronte alla\u00a0<b>biblioteca &#8220;Luzi&#8221;<\/b>, a ricordare che questo spazio \u00e8 dedicato a uno degli intellettuali pi\u00f9 importanti del nostro tempo.\u00a0Nel centenario della sua nascita, il Comune di San Miniato ha voluto rendergli omaggio con l&#8217;intitolazione di una piazza del centro storico proprio durante la 79^ Festa del teatro, il cui spettacolo principale \u00e8\u00a0<i>&#8220;Autodifesa di Caino&#8221;<\/i>, interpretato da\u00a0<b>Luca Zingaretti<\/b>\u00a0che, insieme al sindaco, ha scoperto la targa. Il pomeriggio si \u00e8 aperto con un momento celebrativo in Sala del Consiglio, dove il sindaco\u00a0<b>Simone Giglioli<\/b>\u00a0e il presidente del Dramma Popolare\u00a0<b>Marzio Gabbanini<\/b>\u00a0hanno portato i saluti istituzionali, e poi alcuni ricordi, tra cui quello dell&#8217;ex sindaco<b>\u00a0Angelo Frosini,\u00a0<\/b>che\u00a0portato i ricordi degli anni di\u00a0<b>Prima del Teatro<\/b>\u00a0e e letto il suo racconto\u00a0<i>&#8220;L&#8217;ombrello di No\u00e8&#8221;<\/i>\u00a0proprio dedicato al suo personale incontro con Camilleri. Negli anni &#8217;50, il giovane scrittore siciliano era infatti stato a San Miniato per collaborare con il maestro Orazio Costa ad alcune messe in scena di spettacoli del Dramma, poi successivamente era tornato in veste di docente di Prima del teatro, la scuola di teatro organizzata dalla Fondazione Teatro di Pisa e dall&#8217;Accademia nazionale d&#8217;arte drammatica di Roma. I fili del suo legame con la Citt\u00e0 si sono poi riannodati nel 2024, quando nell\u2019archivio del Dramma Popolare \u00e8 spuntato un testo inedito del giovane Camilleri,\u00a0<i>\u201cIl santo nero\u201d<\/i>, inviato nella citt\u00e0 della Rocca dallo stesso scrittore siciliano, per un concorso bandito dall\u2019Istituto nel 1951, un ritrovamento che ha portato alla decisione di mettere in scena \u201cAutodifesa di Caino\u201d, il testo che avrebbe dovuto presentare lui stesso nel 2019, se la morte non lo avesse colto prima.<\/div>\n<div><i>&#8220;La scelta di dedicare questo spazio a Camilleri nasce da molte ragioni, ma soprattutto da un rapporto autentico, che questo grande autore ha mantenuto negli anni con la citt\u00e0 di San Miniato. Fu infatti pi\u00f9 volte ospite del nostro Dramma Popolare, contribuendo con la sua intelligenza e sensibilit\u00e0 alla riflessione pubblica sul ruolo del teatro, della parola e della memoria. La sua presenza qui, i suoi interventi, le sue relazioni con il nostro tessuto culturale hanno lasciato un segno profondo, umano prima ancora che artistico<\/i>\u00a0&#8211; commenta il sindaco di San Miniato,\u00a0<b>Simone Giglioli<\/b>\u00a0&#8211;\u00a0<i>\u00c8 anche in virt\u00f9 di questo legame concreto e affettuoso che abbiamo ritenuto giusto e doveroso consegnare alla citt\u00e0 un luogo che ne porti il nome, nel cuore del centro storico, in uno spazio di incontro, dialogo e bellezza, quale \u00e8 la corte dei Loggiati di San Domenico. Intitolare una piazza ad Andrea Camilleri significa affermare la centralit\u00e0 della cultura nella vita pubblica. Camilleri \u00e8 stato un intellettuale che ha saputo parlare a tutti, che ha trasformato la lingua in un ponte tra territori e generazioni, che ha restituito dignit\u00e0 narrativa a chi spesso non ha voce, con ironia, lucidit\u00e0 e profondo senso etico&#8221;.<\/i><\/div>\n<div><\/div>\n<p>&nbsp;<\/p>\n<p><b>Immagini e Video&nbsp;<\/b><\/p>\n<p><img src='https:\/\/comune.san-miniato.pi.it\/wp-content\/uploads\/2025\/07\/Piazza-Camilleri_2.jpeg' alt='image'><\/p>\n<p><img src='https:\/\/comune.san-miniato.pi.it\/wp-content\/uploads\/2025\/07\/Piazza-Camilleri_1.jpeg' alt='image'><\/p>\n<p><img src='https:\/\/comune.san-miniato.pi.it\/wp-content\/uploads\/2025\/07\/Piazza-Camilleri_5.jpeg' alt='image'><\/p>\n<p><img src='https:\/\/comune.san-miniato.pi.it\/wp-content\/uploads\/2025\/07\/Piazza-Camilleri_3.jpeg' alt='image'><\/p>\n<p><img src='https:\/\/comune.san-miniato.pi.it\/wp-content\/uploads\/2025\/07\/Piazza-Camilleri_4-1.jpeg' alt='image'><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una targa in ottone con la dicitura &#8220;Andrea Camilleri &#8211; Scrittore e drammaturgo (1925 &#8211; 2019)&#8221; da oggi sar\u00e0 affissa alle pareti della corte interna dei Loggiati di San Domenico, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37517,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-37516","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La corte dei Loggiati di San Domenico diventa piazza Andrea Camilleri. Inaugurazione con Zingaretti - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La corte dei Loggiati di San Domenico diventa piazza Andrea Camilleri. Inaugurazione con Zingaretti - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Una targa in ottone con la dicitura &#8220;Andrea Camilleri &#8211; Scrittore e drammaturgo (1925 &#8211; 2019)&#8221; da oggi sar\u00e0 affissa alle pareti della corte interna dei Loggiati di San Domenico, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-26T17:04:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/07\/Piazza-Camilleri_4.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/26\\\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/26\\\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"La corte dei Loggiati di San Domenico diventa piazza Andrea Camilleri. Inaugurazione con Zingaretti\",\"datePublished\":\"2025-07-26T17:04:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/26\\\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\\\/\"},\"wordCount\":548,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/26\\\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/07\\\/Piazza-Camilleri_4.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/26\\\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/26\\\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\\\/\",\"name\":\"La corte dei Loggiati di San Domenico diventa piazza Andrea Camilleri. Inaugurazione con Zingaretti - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/26\\\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/26\\\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/07\\\/Piazza-Camilleri_4.jpeg\",\"datePublished\":\"2025-07-26T17:04:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/26\\\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/26\\\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/26\\\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/07\\\/Piazza-Camilleri_4.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/07\\\/Piazza-Camilleri_4.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/07\\\/26\\\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La corte dei Loggiati di San Domenico diventa piazza Andrea Camilleri. Inaugurazione con Zingaretti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La corte dei Loggiati di San Domenico diventa piazza Andrea Camilleri. Inaugurazione con Zingaretti - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/","og_locale":"it_IT","og_type":"article","og_title":"La corte dei Loggiati di San Domenico diventa piazza Andrea Camilleri. Inaugurazione con Zingaretti - San Miniato","og_description":"Una targa in ottone con la dicitura &#8220;Andrea Camilleri &#8211; Scrittore e drammaturgo (1925 &#8211; 2019)&#8221; da oggi sar\u00e0 affissa alle pareti della corte interna dei Loggiati di San Domenico, [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-07-26T17:04:17+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/07\/Piazza-Camilleri_4.jpeg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"La corte dei Loggiati di San Domenico diventa piazza Andrea Camilleri. Inaugurazione con Zingaretti","datePublished":"2025-07-26T17:04:17+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/"},"wordCount":548,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/07\/Piazza-Camilleri_4.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/","url":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/","name":"La corte dei Loggiati di San Domenico diventa piazza Andrea Camilleri. Inaugurazione con Zingaretti - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/07\/Piazza-Camilleri_4.jpeg","datePublished":"2025-07-26T17:04:17+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/07\/Piazza-Camilleri_4.jpeg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/07\/Piazza-Camilleri_4.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/07\/26\/la-corte-dei-loggiati-di-san-domenico-diventa-piazza-andrea-camilleri-inaugurazione-con-zingaretti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"La corte dei Loggiati di San Domenico diventa piazza Andrea Camilleri. Inaugurazione con Zingaretti"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/sanminiato\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000021998"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=37516"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37516\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/37517"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=37516"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=37516"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=37516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}