{"id":37572,"date":"2025-08-30T12:00:00","date_gmt":"2025-08-30T10:00:00","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/"},"modified":"2025-09-01T09:03:51","modified_gmt":"2025-09-01T07:03:51","slug":"tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/30\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/","title":{"rendered":"Tesserini venatori 2025\/2026, da luned\u00ec 11 agosto al via la consegna"},"content":{"rendered":"<p><em>Consegna tesserini venatori dall&#8217;11 agosto al Comando di San Miniato, documenti necessari e app TosCaccia obbligatoria.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<div>\n<div>ll servizio\u00a0di Polizia Municipale informa che da luned\u00ec\u00a0<b>11 agosto<\/b> 2025 inizier\u00e0 la consegna dei tesserini venatori per la stagione di caccia 2025-202606. I cittadini interessati potranno recarsi al <b>Comando<\/b>\u00a0in piazza XX Settembre, 22 a San Miniato, dal luned\u00ec al sabato dalle 9.00 alle 12.00, previo appuntamento da prenotare telefonicamente (0571.406406), presentando i seguenti documenti:<\/div>\n<ul>\n<li>tesserino venatorio della stagione precedente oppure ricevuta di avvenuta restituzione. Se il cacciatore ha smarrito il tesserino dell\u2019anno precedente deve presentare denuncia di smarrimento in originale o copia conforme;<\/li>\n<li>licenza di porto di fucile per uso caccia in corso di validit\u00e0 (validit\u00e0 anni 5 dalla data del rilascio);<\/li>\n<li>attestazione del pagamento della ATC di residenza venatoria valida per la nuova stagione venatoria;<\/li>\n<li>attestazione del pagamento tassa di concessione governativa;<\/li>\n<li>attestazione del pagamento tassa provinciale;<\/li>\n<li>allegato alla licenza di caccia.<\/li>\n<\/ul>\n<p>Si ricorda che la Regione Toscana ha creato\u00a0<b>TosCaccia<\/b>\u00a0un\u2019applicazione per smartphone pensata per sostituire l\u2019attuale tesserino venatorio cartaceo. Si ricorda altres\u00ec che dalla stagione venatoria 2022-2023 \u00e8 obbligatorio l\u2019utilizzo della app per poter effettuare attivit\u00e0 venatoria in apertura anticipata della caccia e per il prelievo delle specie in deroga (piccione e tortora dal collare) come da deliberazioni della Giunta Regionale.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.regione.toscana.it\/-\/applicazione-toscaccia-specifiche-per-l-utilizzo-del-tesserino-venatorio-digitale\">Maggiori informazioni per scaricare l\u2019app TosCaccia<\/a><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Consegna tesserini venatori dall&#8217;11 agosto al Comando di San Miniato, documenti necessari e app TosCaccia obbligatoria.&nbsp; Descrizione&nbsp; ll servizio\u00a0di Polizia Municipale informa che da luned\u00ec\u00a011 agosto 2025 inizier\u00e0 la consegna [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37686,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-37572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tesserini venatori 2025\/2026, da luned\u00ec 11 agosto al via la consegna - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tesserini venatori 2025\/2026, da luned\u00ec 11 agosto al via la consegna - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Consegna tesserini venatori dall&#8217;11 agosto al Comando di San Miniato, documenti necessari e app TosCaccia obbligatoria.&nbsp; Descrizione&nbsp; ll servizio\u00a0di Polizia Municipale informa che da luned\u00ec\u00a011 agosto 2025 inizier\u00e0 la consegna [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-30T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-01T07:03:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/08\/tesserini_caccia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/08\\\/06\\\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/08\\\/06\\\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Tesserini venatori 2025\\\/2026, da luned\u00ec 11 agosto al via la consegna\",\"datePublished\":\"2025-08-30T10:00:00+00:00\",\"dateModified\":\"2025-09-01T07:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/08\\\/06\\\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\\\/\"},\"wordCount\":228,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/08\\\/06\\\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/09\\\/tesserini_caccia.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/08\\\/06\\\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/08\\\/06\\\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\\\/\",\"name\":\"Tesserini venatori 2025\\\/2026, da luned\u00ec 11 agosto al via la consegna - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/08\\\/06\\\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/08\\\/06\\\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/09\\\/tesserini_caccia.jpg\",\"datePublished\":\"2025-08-30T10:00:00+00:00\",\"dateModified\":\"2025-09-01T07:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/08\\\/06\\\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/08\\\/06\\\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/08\\\/06\\\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/09\\\/tesserini_caccia.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/09\\\/tesserini_caccia.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/08\\\/06\\\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tesserini venatori 2025\\\/2026, da luned\u00ec 11 agosto al via la consegna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tesserini venatori 2025\/2026, da luned\u00ec 11 agosto al via la consegna - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/","og_locale":"it_IT","og_type":"article","og_title":"Tesserini venatori 2025\/2026, da luned\u00ec 11 agosto al via la consegna - San Miniato","og_description":"Consegna tesserini venatori dall&#8217;11 agosto al Comando di San Miniato, documenti necessari e app TosCaccia obbligatoria.&nbsp; Descrizione&nbsp; ll servizio\u00a0di Polizia Municipale informa che da luned\u00ec\u00a011 agosto 2025 inizier\u00e0 la consegna [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-08-30T10:00:00+00:00","article_modified_time":"2025-09-01T07:03:51+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/08\/tesserini_caccia.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Tesserini venatori 2025\/2026, da luned\u00ec 11 agosto al via la consegna","datePublished":"2025-08-30T10:00:00+00:00","dateModified":"2025-09-01T07:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/"},"wordCount":228,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/09\/tesserini_caccia.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/","url":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/","name":"Tesserini venatori 2025\/2026, da luned\u00ec 11 agosto al via la consegna - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/09\/tesserini_caccia.jpg","datePublished":"2025-08-30T10:00:00+00:00","dateModified":"2025-09-01T07:03:51+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/09\/tesserini_caccia.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/09\/tesserini_caccia.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/08\/06\/tesserini-venatori-2025-2026-da-lunedi-11-agosto-al-via-la-consegna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Tesserini venatori 2025\/2026, da luned\u00ec 11 agosto al via la consegna"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/sanminiato\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000022035"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=37572"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37572\/revisions"}],"predecessor-version":[{"id":37685,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37572\/revisions\/37685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/37686"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=37572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=37572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=37572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}