{"id":37818,"date":"2025-09-13T13:05:06","date_gmt":"2025-09-13T11:05:06","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/"},"modified":"2025-09-13T13:05:06","modified_gmt":"2025-09-13T11:05:06","slug":"successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/","title":{"rendered":"Successo della premiazione dei centisti degli istituti di San Miniato"},"content":{"rendered":"<p><em>Con una cerimonia molto partecipata sono stati festeggiati i 18 studenti e studentesse dei due istituti superiori di San Miniato che si sono diplomati con 100 e 100 e lode.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<div>Con una cerimonia molto partecipata sono stati festeggiati i\u00a0<b>18\u00a0<\/b>studenti e studentesse dei due istituti superiori di San Miniato che si sono diplomati con 100 e 100 e lode. Ad accogliere queste menti eccellenti provenienti dall\u2019<b>IT \u201cCattaneo\u201d<\/b>\u00a0di San Miniato e dal\u00a0<b>Liceo \u201cMarconi\u201d<\/b>\u00a0di La Scala, sono stati il sindaco di San Miniato\u00a0<b>Simone Giglioli\u00a0<\/b>e all&#8217;assessore all&#8217;istruzione, insieme alle amministrazioni dei Comuni di residenza dei premiati, l&#8217;assessora <b>Valentina Fanella<\/b> del Comune di Santa Croce sull\u2019Arno, la sindaca <b>Emma Donnini<\/b> e l&#8217;assessore alla cultura<b> Alberto Cafaro<\/b> del Comune di Fucecchio, l&#8217;assessora <b>Kendra Fiuman\u00f2<\/b> del Comune di Montopoli in Val d&#8217;Arno e i due presidi,\u00a0<b>Luca Petrini<\/b>\u00a0del Liceo \u201cMarconi\u201d, ed\u00a0<b>Elena Casarosa<\/b>\u00a0dell&#8217;IT &#8220;Cattaneo&#8221;.<\/p>\n<div>Undici sono stati i centisti premiati del Liceo Marconi:\u00a0<b>Giacomo Astinenti<\/b>\u00a0(Montopoli in Val d&#8217;Arno),\u00a0<b>Stiven Qesimi Sotiraq<\/b>\u00a0(San Miniato, 100 e lode),\u00a0<b>Daniele Gelli<\/b>\u00a0(San Miniato),<b>\u00a0Irene Zaccagnino<\/b>\u00a0(San Miniato),\u00a0<b>Carolina Gentile<\/b>\u00a0(Fucecchio),\u00a0<b>Alice Caverni<\/b>\u00a0(San Miniato, 100 e lode),\u00a0<b>Elisa Taddei<\/b>\u00a0(San Miniato, 100 e lode),\u00a0<b>Lorenzo Benericetti<\/b>\u00a0(Fucecchio, 100 e lode),<b>\u00a0Alessandra Capone<\/b>\u00a0(San Miniato, 100 e lode),\u00a0<b>Fabio Grossi<\/b>\u00a0(San Miniato) e\u00a0<b>Gabriele Ottonelli<\/b>\u00a0(Santa Croce sull&#8217;Arno, 100 e lode).<\/div>\n<div>Sette sono stati i centisti dell&#8217;IT Cattaneo:\u00a0<b>Pierpaolo Buggiani\u00a0<\/b>(Fucecchio),\u00a0<b>Greta Rabazzi<\/b>\u00a0(Montopoli in Val d&#8217;Arno),\u00a0<b>Riccardo Scarselli\u00a0<\/b>(Montopoli in Val d&#8217;Arno, 100 e lode),\u00a0<b>Gabriele Mezzacapo<\/b>\u00a0(San Miniato),\u00a0<b>Elsina Hithi<\/b>\u00a0(Santa Croce sull&#8217;Arno),\u00a0<b>Cristhal Tatoni<\/b>\u00a0(Santa Croce sull&#8217;Arno) e\u00a0<b>Irene Sabatini<\/b>\u00a0(Santa Maria a Monte). Per tutti una pergamena celebrativa e una foto ricordo della giornata.<\/div>\n<div>Il Sindaco di San Miniato ha espresso grande orgoglio per i risultati ottenuti dagli studenti delle scuole superiori del territorio, sottolineando come il raggiungimento del punteggio massimo all&#8217;esame di maturit\u00e0 rappresenti non solo un traguardo personale di grande valore, ma anche un segnale positivo per tutta la comunit\u00e0.\u00a0Ha voluto evidenziare come questi giovani siano esempio di impegno, costanza e determinazione, qualit\u00e0 che devono essere riconosciute e celebrate pubblicamente. Ha aggiunto che il merito scolastico non \u00e8 soltanto un riconoscimento individuale, ma un investimento per il futuro della societ\u00e0, poich\u00e9 forma cittadini consapevoli, responsabili e pronti a contribuire con le proprie competenze.\u00a0Il Sindaco ha infine rivolto un ringraziamento particolare alle famiglie, ai docenti e a tutto il personale scolastico che ha accompagnato questi ragazzi nel loro percorso, ricordando quanto sia importante continuare a sostenere e valorizzare la scuola pubblica come motore di crescita e uguaglianza.<\/div>\n<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con una cerimonia molto partecipata sono stati festeggiati i 18 studenti e studentesse dei due istituti superiori di San Miniato che si sono diplomati con 100 e 100 e lode.&nbsp; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37819,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-37818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Successo della premiazione dei centisti degli istituti di San Miniato - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Successo della premiazione dei centisti degli istituti di San Miniato - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Con una cerimonia molto partecipata sono stati festeggiati i 18 studenti e studentesse dei due istituti superiori di San Miniato che si sono diplomati con 100 e 100 e lode.&nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-13T11:05:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/09\/Centisti-2025.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/13\\\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/13\\\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Successo della premiazione dei centisti degli istituti di San Miniato\",\"datePublished\":\"2025-09-13T11:05:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/13\\\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\\\/\"},\"wordCount\":424,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/13\\\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/09\\\/Centisti-2025.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/13\\\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/13\\\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\\\/\",\"name\":\"Successo della premiazione dei centisti degli istituti di San Miniato - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/13\\\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/13\\\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/09\\\/Centisti-2025.jpeg\",\"datePublished\":\"2025-09-13T11:05:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/13\\\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/13\\\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/13\\\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/09\\\/Centisti-2025.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/09\\\/Centisti-2025.jpeg\",\"width\":1200,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/13\\\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Successo della premiazione dei centisti degli istituti di San Miniato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Successo della premiazione dei centisti degli istituti di San Miniato - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/","og_locale":"it_IT","og_type":"article","og_title":"Successo della premiazione dei centisti degli istituti di San Miniato - San Miniato","og_description":"Con una cerimonia molto partecipata sono stati festeggiati i 18 studenti e studentesse dei due istituti superiori di San Miniato che si sono diplomati con 100 e 100 e lode.&nbsp; [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-09-13T11:05:06+00:00","og_image":[{"width":1200,"height":1600,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/09\/Centisti-2025.jpeg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Successo della premiazione dei centisti degli istituti di San Miniato","datePublished":"2025-09-13T11:05:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/"},"wordCount":424,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/09\/Centisti-2025.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/","url":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/","name":"Successo della premiazione dei centisti degli istituti di San Miniato - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/09\/Centisti-2025.jpeg","datePublished":"2025-09-13T11:05:06+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/09\/Centisti-2025.jpeg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/09\/Centisti-2025.jpeg","width":1200,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/13\/successo-della-premiazione-dei-centisti-degli-istituti-di-san-miniato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Successo della premiazione dei centisti degli istituti di San Miniato"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/sanminiato\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000022175"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=37818"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/37819"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=37818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=37818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=37818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}