{"id":37820,"date":"2025-09-16T12:12:41","date_gmt":"2025-09-16T10:12:41","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/"},"modified":"2025-12-31T09:33:51","modified_gmt":"2025-12-31T08:33:51","slug":"dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/","title":{"rendered":"Dal 16 settembre nel Comune di San Miniato lo stato civile diventa digitale"},"content":{"rendered":"<p><em>Il Comune di San Miniato segna un importante primato locale, diventando il primo Comune del Valdarno Inferiore a subentrare ufficialmente nell\u2019Archivio Nazionale Informatizzato dei Registri dello Stato Civile (ANSC)<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<div>Il\u00a0<b>Comune di San Miniato\u00a0<\/b>segna un importante primato locale, diventando il\u00a0<b>primo Comune<\/b>\u00a0del\u00a0<b>Valdarno Inferiore<\/b>\u00a0a subentrare ufficialmente nell\u2019<b>Archivio Nazionale Informatizzato dei Registri dello Stato Civile (ANSC)<\/b>. Il passaggio al sistema digitale, che utilizza esclusivamente i servizi messi a disposizione dal nuovo sistema per la formazione e l&#8217;iscrizione nell\u2019archivio nazionale degli atti dello stato civile, comporter\u00e0 la dismissione dei registri cartacei. Il\u00a0<b>16 settembre<\/b>, con un semplice click del sindaco\u00a0<b>Simone Giglioli<\/b>, si sono chiusi i registri cartacei e d&#8217;ora in poi gli atti saranno redatti e conservati solo in formato digitale. Con l\u2019ingresso nell\u2019Ansc gli atti di cittadinanza, nascita, matrimonio, unione civile, separazione, divorzio, morte e altri, saranno digitalizzati e centralizzati, accessibili agli ufficiali di stato civile in modo sicuro, da qualsiasi luogo e in qualsiasi momento.<\/div>\n<div>Il nuovo sistema avanzato, sostenuto dal Ministero dell\u2019Interno e dal Dipartimento per la Trasformazione Digitale della Presidenza del Consiglio dei Ministri, consente un\u2019ottimizzazione dei tempi di gestione e una riduzione dei margini di errore, garantendo cos\u00ec un servizio pi\u00f9 efficiente e affidabile per la comunit\u00e0.<br \/>\nGrazie a questo passaggio. gli atti di stato civile redatti tramite la piattaforma ANSC possono essere sottoscritti dai dichiaranti mediante l\u2019identificazione con strumenti di identit\u00e0 digitale (SPID o CIE); per particolari situazioni o per i cittadini sprovvisti di tali strumenti, resta comunque possibile apporre la firma autografa.<br \/>\nIl sindaco di San Miniato,\u00a0<b>Simone Giglioli<\/b>, ha ringraziato il personale dell&#8217;ufficio di stato civile e espresso soddisfazione per l\u2019adozione di strumenti innovativi che rafforzano l\u2019efficienza amministrativa e migliorano il rapporto tra cittadini e pubblica amministrazione, sottolineando l\u2019importanza di continuare a investire nella digitalizzazione dei servizi comunali.<\/div>\n<div><\/div>\n<p>&nbsp;<\/p>\n<p><b>Immagini e Video&nbsp;<\/b><\/p>\n<p><img src='https:\/\/comune.san-miniato.pi.it\/wp-content\/uploads\/2025\/09\/Stato-Civile-e-Sindaco.jpeg' alt='image'><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di San Miniato segna un importante primato locale, diventando il primo Comune del Valdarno Inferiore a subentrare ufficialmente nell\u2019Archivio Nazionale Informatizzato dei Registri dello Stato Civile (ANSC)&nbsp; Descrizione&nbsp; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38383,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-37820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dal 16 settembre nel Comune di San Miniato lo stato civile diventa digitale - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dal 16 settembre nel Comune di San Miniato lo stato civile diventa digitale - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Il Comune di San Miniato segna un importante primato locale, diventando il primo Comune del Valdarno Inferiore a subentrare ufficialmente nell\u2019Archivio Nazionale Informatizzato dei Registri dello Stato Civile (ANSC)&nbsp; Descrizione&nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-16T10:12:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-31T08:33:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/09\/Sindaco-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/16\\\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/16\\\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Dal 16 settembre nel Comune di San Miniato lo stato civile diventa digitale\",\"datePublished\":\"2025-09-16T10:12:41+00:00\",\"dateModified\":\"2025-12-31T08:33:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/16\\\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\\\/\"},\"wordCount\":328,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/16\\\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/12\\\/Sindaco.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/16\\\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/16\\\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\\\/\",\"name\":\"Dal 16 settembre nel Comune di San Miniato lo stato civile diventa digitale - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/16\\\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/16\\\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/12\\\/Sindaco.jpeg\",\"datePublished\":\"2025-09-16T10:12:41+00:00\",\"dateModified\":\"2025-12-31T08:33:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/16\\\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/16\\\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/16\\\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/12\\\/Sindaco.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/12\\\/Sindaco.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/09\\\/16\\\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dal 16 settembre nel Comune di San Miniato lo stato civile diventa digitale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dal 16 settembre nel Comune di San Miniato lo stato civile diventa digitale - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/","og_locale":"it_IT","og_type":"article","og_title":"Dal 16 settembre nel Comune di San Miniato lo stato civile diventa digitale - San Miniato","og_description":"Il Comune di San Miniato segna un importante primato locale, diventando il primo Comune del Valdarno Inferiore a subentrare ufficialmente nell\u2019Archivio Nazionale Informatizzato dei Registri dello Stato Civile (ANSC)&nbsp; Descrizione&nbsp; [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-09-16T10:12:41+00:00","article_modified_time":"2025-12-31T08:33:51+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/09\/Sindaco-1.jpeg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Dal 16 settembre nel Comune di San Miniato lo stato civile diventa digitale","datePublished":"2025-09-16T10:12:41+00:00","dateModified":"2025-12-31T08:33:51+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/"},"wordCount":328,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/12\/Sindaco.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/","url":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/","name":"Dal 16 settembre nel Comune di San Miniato lo stato civile diventa digitale - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/12\/Sindaco.jpeg","datePublished":"2025-09-16T10:12:41+00:00","dateModified":"2025-12-31T08:33:51+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/12\/Sindaco.jpeg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/12\/Sindaco.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/09\/16\/dal-16-settembre-nel-comune-di-san-miniato-lo-stato-civile-diventa-digitale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Dal 16 settembre nel Comune di San Miniato lo stato civile diventa digitale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/sanminiato\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000022179"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=37820"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37820\/revisions"}],"predecessor-version":[{"id":37823,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/37820\/revisions\/37823"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/38383"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=37820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=37820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=37820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}