{"id":38063,"date":"2025-10-28T11:02:48","date_gmt":"2025-10-28T10:02:48","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/"},"modified":"2025-10-29T09:04:42","modified_gmt":"2025-10-29T08:04:42","slug":"halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/","title":{"rendered":"Halloween a San Miniato, il 31 ottobre torna la pedonalizzazione del centro storico"},"content":{"rendered":"<p><em>In occasione della notte di halloween, il 31 ottobre, anche quest&#8217;anno verr\u00e0 realizzata la pedonalizzazione in centro storico, dalle 16 alle 21, mentre dalle 21 sar\u00e0 attiva regolarmente la Ztl fino alle 5.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<div>\n<div>In occasione della notte di halloween, il 31 ottobre, anche quest&#8217;anno verr\u00e0 realizzata la pedonalizzazione in centro storico, dalle 16 alle 21, mentre dalle 21 sar\u00e0 attiva regolarmente la Ztl fino alle 5. <i>\u201cVisto il successo dell&#8217;anno scorso quando tanti bambini, bambine e famiglie si sono riversati in strada per festeggiare questa ricorrenza, abbiamo deciso di chiudere le strade al traffico anche quest&#8217;anno<\/i>\u00a0\u2013 spiegano il sindaco di San Miniato,\u00a0<b>Simone Giglioli<\/b>\u00a0e la vicesindaca<b>\u00a0Azzurra Bonaccorsi<\/b>\u00a0-.\u00a0<i>E\u2019 una questione di sicurezza, che per noi resta la prima tutela da garantire. Sappiamo che ci saranno feste ed eventi in centro, per questo abbiamo ritenuto di chiudere al traffico, in modo da consentire lo svolgimento del consueto giro di casa in casa da parte dei bambini e delle bambine\u201d.<\/i><\/div>\n<p>L\u2019area pedonalizzata \u00e8 quella che dalla piazzetta del Fondo arriva fino a piazza Grifoni, passando per via Conti, piazza del Popolo, via Ser Ridolfo e via IV Novembre. Transitando da La Scala, tramite via sanminiatese, via Erti e via Fontevivo si accede al parcheggio di Fonti alle Fate e piazza Dante, mentre arrivando da San Miniato Basso, da via Moro, non sar\u00e0 possibile accedere al centro storico e al parcheggio di Palazzo Grifoni e non sar\u00e0 consentito il transito in via Roma, via Dalmazia e per la Valdegola. Salendo da La Catena e dalla Valdegola sar\u00e0 possibile accedere al parcheggio di piazza Benvenuti, Palazzo Grifoni e via Fornace Vecchia.<br \/>\n<i>\u201cLa pedonalizzazione in un giorno feriale pu\u00f2 comportare dei disagi, ne siamo consapevole<\/i>\u00a0\u2013 concludono gli amministratori &#8211;<i>; chiediamo per questo collaborazione e pazienza a chi dovr\u00e0 recarsi in centro storico nel pomeriggio di venerd\u00ec, certi che qualche ora di svago per i pi\u00f9 piccoli, in sicurezza, sia comunque la scelta migliore per tutti\u201d.<\/i><\/p>\n<div>Eccezionalmente, nei giorni 1 e 2 novembre, per la commemorazione dei defunti, la ZTL nel centro storico di San Miniato sar\u00e0 sospesa dalle 16 alle 21, per consentire una migliore circolazione in vista dell&#8217;accesso al cimitero comunale. Dalle 21 alle 5 i varchi entreranno regolarmente in funzione.<\/div>\n<\/div>\n<div><\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In occasione della notte di halloween, il 31 ottobre, anche quest&#8217;anno verr\u00e0 realizzata la pedonalizzazione in centro storico, dalle 16 alle 21, mentre dalle 21 sar\u00e0 attiva regolarmente la Ztl [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38075,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-38063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Halloween a San Miniato, il 31 ottobre torna la pedonalizzazione del centro storico - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Halloween a San Miniato, il 31 ottobre torna la pedonalizzazione del centro storico - San Miniato\" \/>\n<meta property=\"og:description\" content=\"In occasione della notte di halloween, il 31 ottobre, anche quest&#8217;anno verr\u00e0 realizzata la pedonalizzazione in centro storico, dalle 16 alle 21, mentre dalle 21 sar\u00e0 attiva regolarmente la Ztl [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-28T10:02:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T08:04:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/10\/halloween-4585684_12801.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/10\\\/28\\\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/10\\\/28\\\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Halloween a San Miniato, il 31 ottobre torna la pedonalizzazione del centro storico\",\"datePublished\":\"2025-10-28T10:02:48+00:00\",\"dateModified\":\"2025-10-29T08:04:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/10\\\/28\\\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\\\/\"},\"wordCount\":369,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/10\\\/28\\\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/10\\\/halloween-4585684_12801-2.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/10\\\/28\\\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/10\\\/28\\\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\\\/\",\"name\":\"Halloween a San Miniato, il 31 ottobre torna la pedonalizzazione del centro storico - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/10\\\/28\\\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/10\\\/28\\\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/10\\\/halloween-4585684_12801-2.jpg\",\"datePublished\":\"2025-10-28T10:02:48+00:00\",\"dateModified\":\"2025-10-29T08:04:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/10\\\/28\\\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/10\\\/28\\\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/10\\\/28\\\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/10\\\/halloween-4585684_12801-2.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/10\\\/halloween-4585684_12801-2.jpg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/10\\\/28\\\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Halloween a San Miniato, il 31 ottobre torna la pedonalizzazione del centro storico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Halloween a San Miniato, il 31 ottobre torna la pedonalizzazione del centro storico - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/","og_locale":"it_IT","og_type":"article","og_title":"Halloween a San Miniato, il 31 ottobre torna la pedonalizzazione del centro storico - San Miniato","og_description":"In occasione della notte di halloween, il 31 ottobre, anche quest&#8217;anno verr\u00e0 realizzata la pedonalizzazione in centro storico, dalle 16 alle 21, mentre dalle 21 sar\u00e0 attiva regolarmente la Ztl [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-10-28T10:02:48+00:00","article_modified_time":"2025-10-29T08:04:42+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/10\/halloween-4585684_12801.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Halloween a San Miniato, il 31 ottobre torna la pedonalizzazione del centro storico","datePublished":"2025-10-28T10:02:48+00:00","dateModified":"2025-10-29T08:04:42+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/"},"wordCount":369,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/10\/halloween-4585684_12801-2.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/","url":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/","name":"Halloween a San Miniato, il 31 ottobre torna la pedonalizzazione del centro storico - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/10\/halloween-4585684_12801-2.jpg","datePublished":"2025-10-28T10:02:48+00:00","dateModified":"2025-10-29T08:04:42+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/10\/halloween-4585684_12801-2.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/10\/halloween-4585684_12801-2.jpg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/10\/28\/halloween-a-san-miniato-il-31-ottobre-torna-la-pedonalizzazione-del-centro-storico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Halloween a San Miniato, il 31 ottobre torna la pedonalizzazione del centro storico"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/sanminiato\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000022328"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=38063"}],"version-history":[{"count":2,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38063\/revisions"}],"predecessor-version":[{"id":38074,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38063\/revisions\/38074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/38075"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=38063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=38063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=38063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}