{"id":38156,"date":"2025-11-07T14:50:09","date_gmt":"2025-11-07T13:50:09","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/"},"modified":"2025-11-07T14:50:09","modified_gmt":"2025-11-07T13:50:09","slug":"25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/","title":{"rendered":"#25Novembre \u2013 Giornata internazionale per l\u2019eliminazione della violenza contro le donne"},"content":{"rendered":"<p style='margin-bottom: 11px;padding-bottom: 0px'><b style='font-size: 16px;color: #333'>Dal 13 Novembre 2025<\/b> <b style='font-size: 16px;color: #333'>al 05 Dicembre 2025<\/b><\/p>\n<div style='margin-bottom: 20px;font-family: Arial, sans-serif'>\n<p style='margin-bottom: 7px;padding-bottom:0px'><b style='font-size: 18px;margin-bottom: 0px;padding-bottom:0px'>Date e orari dell&#8217;evento:<\/b><\/p>\n<ul style='list-style-type: disc;padding-left: 20px;margin-top: 0px!important'>\n<li style='margin-bottom: 10px'><b style='font-size: 16px;color: #333'>13 Nov 2025<\/b> &#8211; <span style='font-size: 14px;color: #555'>Ore: 21:15<\/span>\n<p><em style='font-size: 16px;color: #777;font-style: italic;margin-top: 5px'>\u201cDritti e rovesci, ma pari\u201d | Teatro Pacini di Fucecchio<\/em><\/p>\n<\/li>\n<li style='margin-bottom: 10px'><b style='font-size: 16px;color: #333'>15 Nov 2025<\/b> &#8211; <span style='font-size: 14px;color: #555'>Ore: 17:00<\/span>\n<p><em style='font-size: 16px;color: #777;font-style: italic;margin-top: 5px'>\u201cIl tramonto delle mutilazioni\u201d | Sala delle Sette Virt\u00f9, Palazzo Comunale<\/em><\/p>\n<\/li>\n<li style='margin-bottom: 10px'><b style='font-size: 16px;color: #333'>15 Nov 2025<\/b> &#8211; <span style='font-size: 14px;color: #555'>Ore: 10:30<\/span>\n<p><em style='font-size: 16px;color: #777;font-style: italic;margin-top: 5px'>Lettura animata e laboratorio | via dei Beccai n. 54<\/em><\/p>\n<\/li>\n<li style='margin-bottom: 10px'><b style='font-size: 16px;color: #333'>21 Nov 2025<\/b> &#8211; <span style='font-size: 14px;color: #555'>Ore: 16:30<\/span>\n<p><em style='font-size: 16px;color: #777;font-style: italic;margin-top: 5px'>\u201cI racconti di Parvana\u201d | Atelier Shalom<\/em><\/p>\n<\/li>\n<li style='margin-bottom: 10px'><b style='font-size: 16px;color: #333'>22 Nov 2025<\/b> &#8211; <span style='font-size: 14px;color: #555'>Ore: 17:30<\/span>\n<p><em style='font-size: 16px;color: #777;font-style: italic;margin-top: 5px'>\u201cTrame che uniscono, dialoghi sul femminismo islamico\u201d | Circolo Arci di Isola<\/em><\/p>\n<\/li>\n<li style='margin-bottom: 10px'><b style='font-size: 16px;color: #333'>24 Nov 2025<\/b> &#8211; <span style='font-size: 14px;color: #555'>Ore: 08:30<\/span>\n<p><em style='font-size: 16px;color: #777;font-style: italic;margin-top: 5px'>\u201cLa violenza \u00e8 la ragione di chi ha torto\u201d | Palestra Fontevivo<\/em><\/p>\n<\/li>\n<li style='margin-bottom: 10px'><b style='font-size: 16px;color: #333'>25 Nov 2025<\/b> &#8211; <span style='font-size: 14px;color: #555'>Ore: 10:00<\/span>\n<p><em style='font-size: 16px;color: #777;font-style: italic;margin-top: 5px'>Deposizione del mazzo di fiori alla panchina rossa | Piazza Vittime di femminicidio<\/em><\/p>\n<\/li>\n<li style='margin-bottom: 10px'><b style='font-size: 16px;color: #333'>25 Nov 2025<\/b> &#8211; <span style='font-size: 14px;color: #555'>Ore: 11:30<\/span>\n<p><em style='font-size: 16px;color: #777;font-style: italic;margin-top: 5px'>Flash mob | Scalinata del Santissimo Crocifisso, San Miniato<\/em><\/p>\n<\/li>\n<li style='margin-bottom: 10px'><b style='font-size: 16px;color: #333'>25 Nov 2025<\/b> &#8211; <span style='font-size: 14px;color: #555'>Ore: 12:30<\/span>\n<p><em style='font-size: 16px;color: #777;font-style: italic;margin-top: 5px'>Piantumazione di una nuova rosa nel \u201cRoseto delle donne\u201d | Vicolo Carbonaio<\/em><\/p>\n<\/li>\n<li style='margin-bottom: 10px'><b style='font-size: 16px;color: #333'>25 Nov 2025<\/b> &#8211; <span style='font-size: 14px;color: #555'>Ore: 17:00<\/span>\n<p><em style='font-size: 16px;color: #777;font-style: italic;margin-top: 5px'>Evento \u201cInsieme, corteo e dibattito\u201d | Loggiati di San Domenico e Biblioteca \u201cLuzi\u201d<\/em><\/p>\n<\/li>\n<li style='margin-bottom: 10px'><b style='font-size: 16px;color: #333'>26 Nov 2025<\/b> &#8211; <span style='font-size: 14px;color: #555'>Ore: 18:00<\/span>\n<p><em style='font-size: 16px;color: #777;font-style: italic;margin-top: 5px'>\u201cLa violenza invisibile. Il prezzo della violenza economica\u201d | Casa Culturale di San Miniato Basso<\/em><\/p>\n<\/li>\n<li style='margin-bottom: 10px'><b style='font-size: 16px;color: #333'>30 Nov 2025<\/b> &#8211; <span style='font-size: 14px;color: #555'>Ore: 18:00<\/span>\n<p><em style='font-size: 16px;color: #777;font-style: italic;margin-top: 5px'>Raccolta derrate alimentari | Circolo Arci Molino d\u2019Egola<\/em><\/p>\n<\/li>\n<li style='margin-bottom: 10px'><b style='font-size: 16px;color: #333'>05 Dic 2025<\/b> &#8211; <span style='font-size: 14px;color: #555'>Ore: 10:30<\/span>\n<p><em style='font-size: 16px;color: #777;font-style: italic;margin-top: 5px'>\u201cVoci contro la violenza\u201d | Sala delle Sette Virt\u00f9, Palazzo Comunale (San Miniato)<\/em><\/p>\n<\/li>\n<\/ul>\n<\/div>\n<p><em>In occasione della Giornata internazionale per l\u2019eliminazione della violenza contro le donne, il Comune di San Miniato e la Commissione Comunale Pari Opportunit\u00e0, promuovono un ricco calendario di appuntamenti per sensibilizzare la cittadinanza.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p data-start=\"328\" data-end=\"752\">In occasione del <strong data-start=\"345\" data-end=\"360\">25 novembre<\/strong>, <em data-start=\"362\" data-end=\"437\">Giornata internazionale per l\u2019eliminazione della violenza contro le donne<\/em>, il <strong data-start=\"442\" data-end=\"467\">Comune di San Miniato<\/strong> e la <strong data-start=\"473\" data-end=\"514\">Commissione Comunale Pari Opportunit\u00e0<\/strong>, in collaborazione con numerose realt\u00e0 associative del territorio, promuovono un ricco calendario di appuntamenti per sensibilizzare la cittadinanza e ribadire l\u2019impegno comune contro ogni forma di violenza e discriminazione di genere.<\/p>\n<p data-start=\"754\" data-end=\"971\">Le iniziative si svolgeranno dal <strong data-start=\"787\" data-end=\"816\">13 novembre al 5 dicembre<\/strong> e coinvolgeranno diversi luoghi e realt\u00e0 di San Miniato e delle frazioni, con momenti di approfondimento, riflessione, partecipazione e memoria condivisa.<\/p>\n<h3 data-start=\"978\" data-end=\"1018\">\ud83d\udcc5 <strong data-start=\"985\" data-end=\"1018\">Il programma delle iniziative<\/strong><\/h3>\n<p data-start=\"1020\" data-end=\"1287\"><strong data-start=\"1020\" data-end=\"1065\">13 novembre \u2013 \u201cDritti e rovesci, ma pari\u201d<\/strong><br data-start=\"1065\" data-end=\"1068\" \/>Ore 21.30, Teatro Pacini Fucecchio<br data-start=\"1102\" data-end=\"1105\" \/>A cura della Societ\u00e0 della Salute Empolese Valdarno Valdelsa (SDS EVV) e dei Centri Antiviolenza Lilith (Empoli) e Frida (San Miniato).<br data-start=\"1240\" data-end=\"1243\" \/>Ingresso gratuito, prenotazione consigliata.<\/p>\n<p data-start=\"1289\" data-end=\"1505\"><strong data-start=\"1289\" data-end=\"1338\">15 novembre \u2013 \u201cIl tramonto delle mutilazioni\u201d<\/strong><br data-start=\"1338\" data-end=\"1341\" \/>Ore 17.00, Sala delle Sette Virt\u00f9, Palazzo Comunale (San Miniato)<br data-start=\"1392\" data-end=\"1395\" \/>Presentazione del libro di Nura Musse Ali a cura della Commissione Pari Opportunit\u00e0. Modera Elisa Rinaldini.<\/p>\n<p data-start=\"1507\" data-end=\"1667\"><strong data-start=\"1507\" data-end=\"1554\">15 novembre \u2013 Lettura animata e laboratorio<\/strong><br data-start=\"1554\" data-end=\"1557\" \/>Ore 10.30, via dei Beccai n. 54<br data-start=\"1588\" data-end=\"1591\" \/>Attivit\u00e0 per bambine e bambini a cura del Centro Antiviolenza Frida Kahlo.<\/p>\n<p data-start=\"1669\" data-end=\"1831\"><strong data-start=\"1669\" data-end=\"1710\">21 novembre \u2013 \u201cI racconti di Parvana\u201d<\/strong><br data-start=\"1710\" data-end=\"1713\" \/>Ore 16.30, Atelier Shalom<br data-start=\"1738\" data-end=\"1741\" \/>Proiezione del cartone animato e momento di riflessione a cura del doposcuola di Shalom.<\/p>\n<p data-start=\"1833\" data-end=\"2015\"><strong data-start=\"1833\" data-end=\"1905\">22 novembre \u2013 \u201cTrame che uniscono, dialoghi sul femminismo islamico\u201d<\/strong><br data-start=\"1905\" data-end=\"1908\" \/>Ore 17.30, Circolo Arci di Isola<br data-start=\"1940\" data-end=\"1943\" \/>Dibattito e apericena a cura di Filo Rosso con esperte e associazioni.<\/p>\n<p data-start=\"2017\" data-end=\"2236\"><strong data-start=\"2017\" data-end=\"2077\">24 novembre \u2013 \u201cLa violenza \u00e8 la ragione di chi ha torto\u201d<\/strong><br data-start=\"2077\" data-end=\"2080\" \/>Ore 8.30-12.00, Palestra Fontevivo<br data-start=\"2114\" data-end=\"2117\" \/>Attivit\u00e0 con studenti e studentesse del Liceo \u201cMarconi\u201d di La Scala a cura dell\u2019associazione Dojo Kintsugi Judo Club.<\/p>\n<h3 data-start=\"2243\" data-end=\"2293\">\ud83c\udf39 <strong data-start=\"2250\" data-end=\"2293\">25 novembre \u2013 In ricordo di Elisa Amato<\/strong><\/h3>\n<p data-start=\"2295\" data-end=\"2352\">Una giornata dedicata alla memoria e alla partecipazione:<\/p>\n<ul data-start=\"2354\" data-end=\"2900\">\n<li data-start=\"2354\" data-end=\"2464\">\n<p data-start=\"2356\" data-end=\"2464\"><strong data-start=\"2356\" data-end=\"2369\">Ore 10.00<\/strong> \u2013 Deposizione di un <strong data-start=\"2390\" data-end=\"2408\">mazzo di fiori<\/strong> presso la panchina in Piazza Vittime di femminicidio.<\/p>\n<\/li>\n<li data-start=\"2465\" data-end=\"2566\">\n<p data-start=\"2467\" data-end=\"2566\"><strong data-start=\"2467\" data-end=\"2480\">Ore 11.30<\/strong> \u2013 <em data-start=\"2483\" data-end=\"2494\">Flash mob<\/em> organizzato dallo SPI CGIL sulle scalinate del Santissimo Crocifisso.<\/p>\n<\/li>\n<li data-start=\"2567\" data-end=\"2678\">\n<p data-start=\"2569\" data-end=\"2678\"><strong data-start=\"2569\" data-end=\"2582\">Ore 12.30<\/strong> \u2013 Piantumazione di una nuova rosa nel <strong data-start=\"2635\" data-end=\"2659\">\u201cRoseto delle donne\u201d<\/strong> in via Carbonai.<\/p>\n<\/li>\n<li data-start=\"2679\" data-end=\"2900\">\n<p data-start=\"2681\" data-end=\"2900\"><strong data-start=\"2681\" data-end=\"2694\">Ore 17.00<\/strong> \u2013 Evento <em data-start=\"2704\" data-end=\"2735\">\u201cInsieme, corteo e dibattito\u201d<\/em>, organizzato dalla Commissione Pari Opportunit\u00e0 con Frida, Nuovo Maschile e GasArti, con partenza dai Loggiati di San Domenico e conclusione in Biblioteca \u201cLuzi\u201d.<\/p>\n<\/li>\n<\/ul>\n<p data-start=\"2907\" data-end=\"3148\"><strong data-start=\"2907\" data-end=\"2985\">26 novembre \u2013 \u201cLa violenza invisibile. Il prezzo della violenza economica\u201d<\/strong><br data-start=\"2985\" data-end=\"2988\" \/>Ore 18.00, Casa Culturale di San Miniato Basso<br data-start=\"3034\" data-end=\"3037\" \/>Conferenza a cura del Soroptimist Valdarno Inferiore sul tema della dipendenza economica come forma di abuso.<\/p>\n<p data-start=\"3150\" data-end=\"3336\"><strong data-start=\"3150\" data-end=\"3206\">30 novembre \u2013 Raccolta derrate alimentari per Lilith<\/strong><br data-start=\"3206\" data-end=\"3209\" \/>Ore 18.00, Circolo Arci Molino d\u2019Egola<br data-start=\"3247\" data-end=\"3250\" \/>Evento conclusivo della raccolta solidale a sostegno del Centro Antiviolenza Lilith.<\/p>\n<p data-start=\"3338\" data-end=\"3530\"><strong data-start=\"3338\" data-end=\"3380\">5 dicembre \u2013 \u201cVoci contro la violenza\u201d<\/strong><br data-start=\"3380\" data-end=\"3383\" \/>Ore 10.30, Sala delle Sette Virt\u00f9, Palazzo Comunale (San Miniato)<br data-start=\"3427\" data-end=\"3430\" \/>Conferenza-dibattito organizzata da CA.TE.RI.NA con la partecipazione del gruppo \u201cOltre il canto\u201d.<\/p>\n<p data-start=\"3537\" data-end=\"3880\">Queste iniziative rappresentano un importante momento di condivisione, riflessione e impegno collettivo.<br data-start=\"3641\" data-end=\"3644\" \/>Il <strong data-start=\"3647\" data-end=\"3672\">Comune di San Miniato<\/strong> e la <strong data-start=\"3678\" data-end=\"3710\">Commissione Pari Opportunit\u00e0<\/strong> rinnovano l\u2019invito alla cittadinanza a partecipare e a sostenere ogni azione volta a costruire una comunit\u00e0 pi\u00f9 giusta, equa e rispettosa delle donne e delle differenze.<\/p>\n<p><\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>A chi \u00e8 rivolto:<\/b><\/p>\n<p><span style='font-size: 16px;color: #555'>Tutti e tutte.<\/span><\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>Costi:<\/b> <span style='font-size: 16px;color: #555'>Nessun costo.<\/span><\/p>\n<p><\/p>\n<p style='font-size: 16px;color: #2E3A46'><b>Contatti:<\/b><\/p>\n<ul style='list-style-type: disc;padding-left: 20px;margin-top: 0px!important'>\n<li style='margin-bottom: 5px'><span>Commissione comunale per le Pari Opportunit\u00e0<\/span><\/li>\n<p><span style='font-size: 15px'><b>Telefono<\/b>: 0571 406740<\/span><br \/><span style='font-size: 15px'><b>Email<\/b>: pariopportunita@comune.san-miniato.pi.it<\/span><\/ul>\n\t\t\t<h4>Inizio<\/h4>\n<p>13\/11\/2025 00:00<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>05\/12\/2025 00:00<\/p>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>Dal 13 Novembre 2025 al 05 Dicembre 2025 Date e orari dell&#8217;evento: 13 Nov 2025 &#8211; Ore: 21:15 \u201cDritti e rovesci, ma pari\u201d | Teatro Pacini di Fucecchio 15 Nov [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38195,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-38156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#25Novembre \u2013 Giornata internazionale per l\u2019eliminazione della violenza contro le donne - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#25Novembre \u2013 Giornata internazionale per l\u2019eliminazione della violenza contro le donne - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Dal 13 Novembre 2025 al 05 Dicembre 2025 Date e orari dell&#8217;evento: 13 Nov 2025 &#8211; Ore: 21:15 \u201cDritti e rovesci, ma pari\u201d | Teatro Pacini di Fucecchio 15 Nov [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-07T13:50:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/11\/25-novembre-donne-violenza.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1750\" \/>\n\t<meta property=\"og:image:height\" content=\"988\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/11\\\/07\\\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/11\\\/07\\\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"#25Novembre \u2013 Giornata internazionale per l\u2019eliminazione della violenza contro le donne\",\"datePublished\":\"2025-11-07T13:50:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/11\\\/07\\\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\\\/\"},\"wordCount\":715,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/11\\\/07\\\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/11\\\/25-novembre-donne-violenza-1.jpeg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/11\\\/07\\\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/11\\\/07\\\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\\\/\",\"name\":\"#25Novembre \u2013 Giornata internazionale per l\u2019eliminazione della violenza contro le donne - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/11\\\/07\\\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/11\\\/07\\\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/11\\\/25-novembre-donne-violenza-1.jpeg\",\"datePublished\":\"2025-11-07T13:50:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/11\\\/07\\\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/11\\\/07\\\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/11\\\/07\\\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/11\\\/25-novembre-donne-violenza-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2025\\\/11\\\/25-novembre-donne-violenza-1.jpeg\",\"width\":1750,\"height\":988},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/11\\\/07\\\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#25Novembre \u2013 Giornata internazionale per l\u2019eliminazione della violenza contro le donne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#25Novembre \u2013 Giornata internazionale per l\u2019eliminazione della violenza contro le donne - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/","og_locale":"it_IT","og_type":"article","og_title":"#25Novembre \u2013 Giornata internazionale per l\u2019eliminazione della violenza contro le donne - San Miniato","og_description":"Dal 13 Novembre 2025 al 05 Dicembre 2025 Date e orari dell&#8217;evento: 13 Nov 2025 &#8211; Ore: 21:15 \u201cDritti e rovesci, ma pari\u201d | Teatro Pacini di Fucecchio 15 Nov [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-11-07T13:50:09+00:00","og_image":[{"width":1750,"height":988,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/11\/25-novembre-donne-violenza.jpeg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"#25Novembre \u2013 Giornata internazionale per l\u2019eliminazione della violenza contro le donne","datePublished":"2025-11-07T13:50:09+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/"},"wordCount":715,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/11\/25-novembre-donne-violenza-1.jpeg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/","url":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/","name":"#25Novembre \u2013 Giornata internazionale per l\u2019eliminazione della violenza contro le donne - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/11\/25-novembre-donne-violenza-1.jpeg","datePublished":"2025-11-07T13:50:09+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/11\/25-novembre-donne-violenza-1.jpeg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/11\/25-novembre-donne-violenza-1.jpeg","width":1750,"height":988},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/11\/07\/25novembre-giornata-internazionale-per-leliminazione-della-violenza-contro-le-donne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"#25Novembre \u2013 Giornata internazionale per l\u2019eliminazione della violenza contro le donne"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/sanminiato\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"13\/11\/2025 00:00","cc4_eve_data_fine":"05\/12\/2025 00:00","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":"14"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000022376"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=38156"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38156\/revisions"}],"predecessor-version":[{"id":38194,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38156\/revisions\/38194"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/38195"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=38156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=38156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=38156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}