{"id":38362,"date":"2026-01-05T11:18:51","date_gmt":"2026-01-05T10:18:51","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/"},"modified":"2026-01-12T09:14:06","modified_gmt":"2026-01-12T08:14:06","slug":"bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/05\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/","title":{"rendered":"Bando affitti, il Comune stanzia oltre 90mila euro, il 25% in pi\u00f9 del 2024"},"content":{"rendered":"<p><em>Il Comune di San Miniato, per il 2025, ha stanziato 91.319 euro per coprire le domande pervenute al bando contributo affitti, aumentando in modo significativo le risorse rispetto allo scorso anno, quando furono stanziati 68.654 euro (+25%). <\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Il Comune di San Miniato, per il 2025, ha stanziato\u00a0<strong>91.319 euro<\/strong>\u00a0per coprire le domande pervenute al\u00a0<strong>bando contributo affitti<\/strong>, aumentando in modo significativo le risorse rispetto allo scorso anno, quando furono stanziati\u00a0<strong>68.654 euro\u00a0<\/strong>(<b>+25%<\/b>).<br \/>\n<i>&#8220;Abbiamo scelto di incrementare in maniera consistente le risorse perch\u00e9 il tema dell\u2019abitare \u00e8 oggi una delle principali emergenze sociali anche nel nostro territorio<\/i>\u00a0\u2013 dichiara\u00a0<strong>Matteo Squicciarini<\/strong>, assessore alle politiche socio-sanitarie ed abitative\u00a0\u2013.\u00a0<i>Di fronte all\u2019aumento dei costi degli affitti era necessario uno sforzo ulteriore, destinando pi\u00f9 risorse comunali a sostegno delle famiglie in difficolt\u00e0&#8221;.<br \/>\n<\/i><\/p>\n<div>Del totale stanziato,\u00a0<strong>3.904,36 euro<\/strong>\u00a0derivano dalle risorse del\u00a0<strong>5 per mille<\/strong>,\u00a0<strong>11.515 euro<\/strong>\u00a0dal contributo della\u00a0<strong>Regione Toscana<\/strong>, in linea con quanto ricevuto lo scorso anno, mentre la parte restante, pari a\u00a0<span style=\"color: #000000\"><span style=\"font-family: arial, sans-serif\"><b>75.9<\/b><\/span><\/span><span style=\"color: #000000\"><span><span style=\"font-family: arial, sans-serif\"><b>00 euro<\/b><\/span><span style=\"font-family: Verdana, sans-serif\">,\u00a0<\/span><\/span><\/span>\u00e8 coperta dal bilancio comunale. Il bando \u00e8 stato aperto\u00a0<strong>dal 21 ottobre al 20 novembre 2025\u00a0<\/strong>e le risorse stanziate consentiranno di dare risposta ai nuclei familiari che hanno presentato domanda, offrendo un sostegno concreto in una fase di particolare difficolt\u00e0 economica.<\/div>\n<div>&#8220;Continueremo a tenere alta l\u2019attenzione sul tema dell\u2019abitare, lavorando per rafforzare le politiche di sostegno e per non lasciare indietro nessuno. Un ringraziamento va anche agli\u00a0<strong>uffici comunali<\/strong>, che quotidianamente lavorano nell\u2019emergenza abitativa cercando di dare risposte concrete ai cittadini \u2013 conclude Squicciarini \u2013\u00a0<i>e agli\u00a0<strong>assistenti sociali della SDS<\/strong>, con cui il Comune opera in stretta collaborazione per accompagnare e sostenere i nuclei pi\u00f9 fragili&#8221;.<\/i><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di San Miniato, per il 2025, ha stanziato 91.319 euro per coprire le domande pervenute al bando contributo affitti, aumentando in modo significativo le risorse rispetto allo scorso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38397,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-38362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bando affitti, il Comune stanzia oltre 90mila euro, il 25% in pi\u00f9 del 2024 - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bando affitti, il Comune stanzia oltre 90mila euro, il 25% in pi\u00f9 del 2024 - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Il Comune di San Miniato, per il 2025, ha stanziato 91.319 euro per coprire le domande pervenute al bando contributo affitti, aumentando in modo significativo le risorse rispetto allo scorso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-05T10:18:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-12T08:14:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/12\/Affitto-1-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/12\\\/22\\\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/12\\\/22\\\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Bando affitti, il Comune stanzia oltre 90mila euro, il 25% in pi\u00f9 del 2024\",\"datePublished\":\"2026-01-05T10:18:51+00:00\",\"dateModified\":\"2026-01-12T08:14:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/12\\\/22\\\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\\\/\"},\"wordCount\":273,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/12\\\/22\\\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2026\\\/01\\\/Affitto-1-.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/12\\\/22\\\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/12\\\/22\\\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\\\/\",\"name\":\"Bando affitti, il Comune stanzia oltre 90mila euro, il 25% in pi\u00f9 del 2024 - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/12\\\/22\\\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/12\\\/22\\\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2026\\\/01\\\/Affitto-1-.png\",\"datePublished\":\"2026-01-05T10:18:51+00:00\",\"dateModified\":\"2026-01-12T08:14:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/12\\\/22\\\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/12\\\/22\\\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/12\\\/22\\\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2026\\\/01\\\/Affitto-1-.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2026\\\/01\\\/Affitto-1-.png\",\"width\":800,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2025\\\/12\\\/22\\\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bando affitti, il Comune stanzia oltre 90mila euro, il 25% in pi\u00f9 del 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bando affitti, il Comune stanzia oltre 90mila euro, il 25% in pi\u00f9 del 2024 - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/","og_locale":"it_IT","og_type":"article","og_title":"Bando affitti, il Comune stanzia oltre 90mila euro, il 25% in pi\u00f9 del 2024 - San Miniato","og_description":"Il Comune di San Miniato, per il 2025, ha stanziato 91.319 euro per coprire le domande pervenute al bando contributo affitti, aumentando in modo significativo le risorse rispetto allo scorso [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-01-05T10:18:51+00:00","article_modified_time":"2026-01-12T08:14:06+00:00","og_image":[{"width":800,"height":440,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2025\/12\/Affitto-1-.png","type":"image\/png"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Bando affitti, il Comune stanzia oltre 90mila euro, il 25% in pi\u00f9 del 2024","datePublished":"2026-01-05T10:18:51+00:00","dateModified":"2026-01-12T08:14:06+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/"},"wordCount":273,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/01\/Affitto-1-.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/","url":"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/","name":"Bando affitti, il Comune stanzia oltre 90mila euro, il 25% in pi\u00f9 del 2024 - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/01\/Affitto-1-.png","datePublished":"2026-01-05T10:18:51+00:00","dateModified":"2026-01-12T08:14:06+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/01\/Affitto-1-.png","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/01\/Affitto-1-.png","width":800,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2025\/12\/22\/bando-affitti-il-comune-stanzia-oltre-90mila-euro-il-25-in-piu-del-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Bando affitti, il Comune stanzia oltre 90mila euro, il 25% in pi\u00f9 del 2024"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/sanminiato\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000022534"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=38362"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38362\/revisions"}],"predecessor-version":[{"id":38396,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38362\/revisions\/38396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/38397"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=38362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=38362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=38362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}