{"id":38482,"date":"2026-01-31T10:31:59","date_gmt":"2026-01-31T09:31:59","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/?p=38482"},"modified":"2026-01-31T10:32:08","modified_gmt":"2026-01-31T09:32:08","slug":"al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/","title":{"rendered":"Al via \u201cCinema sotto la Rocca\u201d: sette proiezioni tra febbraio e marzo a San Miniato"},"content":{"rendered":"<p><em>Prende il via nel mese di febbraio \u201cCinema sotto la Rocca\u201d, una nuova rassegna cinematografica promossa dal Movimento Shalom in collaborazione con Arci Valdarno e con il patrocinio del Comune di San Miniato.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<div>\n<p>Prende il via nel mese di febbraio\u00a0<b>\u201cCinema sotto la Rocca\u201d<\/b>, una nuova rassegna cinematografica promossa dal Movimento Shalom in collaborazione con Arci Valdarno e con il patrocinio del Comune di San Miniato: sette appuntamenti tra febbraio e marzo per riscoprire il piacere del cinema in sala con una selezione di film recenti e di qualit\u00e0.<br \/>\n<i>\u00abLa cosa che ci preme sottolineare<\/i>\u00a0\u2013 dichiarano congiuntamente il sindaco di San Miniato\u00a0<b>Simone Giglioli<\/b>\u00a0e l\u2019assessore alla cultura\u00a0<b>Matteo Squicciarini<\/b>\u00a0\u2013\u00a0<i>\u00e8 il lavoro fatto per offrire delle proiezioni anche d\u2019inverno a San Miniato, citt\u00e0 del teatro e del cinema. Siamo felici di poter sostenere un\u2019iniziativa come questa, che vede impegnati Shalom e Arci Valdarno, con il supporto di Cr\u00e9dit Agricole, e che rappresenta una bella e importante offerta culturale e di intrattenimento per la nostra comunit\u00e0. Un\u2019iniziativa che si affianca a quella che, come Comune, proporremo nei mesi estivi con il Cinema all\u2019aperto. L\u2019invito \u00e8 a partecipare numerosi alle proiezioni\u00bb.<br \/>\n<\/i>La prima proiezione \u00e8 in programma mercoled\u00ec\u00a0<b>5 febbraio<\/b>\u00a0alle ore 21.00 con il film\u00a0<em>La grande ambizione<\/em>: racconto biografico della vita privata e pubblica di Enrico Berlinguer, dal viaggio a Sofia del 1973 fino al discorso della Festa Nazionale dell&#8217;Unit\u00e0 di Genova del 1978.<br \/>\nLe proiezioni proseguiranno nei mesi di febbraio e marzo con appuntamenti serali e pomeridiani pensati per offrire al pubblico storie diverse per stile e atmosfera, da vivere sul grande schermo. Il\u00a0<b>19 febbraio<\/b>\u00a0alle ore 21.00 viene proiettato\u00a0<em>Cinque secondi<\/em>, il nuovo film di Virz\u00ec con Valerio Mastandrea e Valeria Bruni Tedeschi che racconta, con lo sguardo ironico e toccante del regista, una storia profondamente umana sulle seconde occasioni. Sabato\u00a0<b>1 marzo<\/b>\u00a0alle ore 17.00 \u00e8 la volta di\u00a0<em>Conclave<\/em>, un thriller politico ambientato all\u2019interno del Vaticano durante l\u2019elezione di un nuovo Papa. Il\u00a0<b>5 marzo<\/b>\u00a0alle ore 21.00 arriva\u00a0<em>Le assaggiatrici<\/em>, tratto dall\u2019omonimo romanzo, che racconta la storia di un gruppo di donne costrette ad assaggiare i pasti destinati a Hitler durante la Seconda guerra mondiale. L\u2019appuntamento di sabato\u00a0<b>15 marzo<\/b>\u00a0alle ore 17.00 \u00e8 con\u00a0<em>Follemente<\/em>, una commedia sentimentale diretta da Paolo Genovese che esplora le dinamiche di coppia, le nevrosi quotidiane e il bisogno di sentirsi amati. Il\u00a0<b>19 marzo<\/b>\u00a0alle ore 21.00 sar\u00e0 proiettato\u00a0<em>Fuori<\/em>, interpretato da Valeria Golino, Matilda De Angelis ed Elodie, un film che affronta il tema dell\u2019identit\u00e0 e del sentirsi esclusi, seguendo il percorso di Goliarda Sapienza, scrittrice che deve ricostruirsi una vita dopo essere uscita dal carcere. La rassegna si chiude sabato\u00a0<b>29 marzo<\/b>\u00a0alle ore 17.00 con\u00a0<em>10 giorni con i suoi<\/em>, una commedia familiare che racconta l\u2019incontro-scontro tra generazioni e caratteri diversi, quando una giovane coppia \u00e8 costretta a convivere con la famiglia di lei. Situazioni esilaranti e momenti teneri accompagnano un racconto leggero, perfetto per concludere il calendario con il sorriso.<br \/>\nIl costo del biglietto \u00e8 di 5 euro per gli adulti e 3 euro per i bambini.<br \/>\nLa rassegna si svolge all\u2019Auditorium Cr\u00e9dit Agricole di piazza Buonaparte a San Miniato, gentilmente concesso dalla banca, da sempre vicina alle attivit\u00e0 culturali e sociali del territorio.<\/p>\n<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Prende il via nel mese di febbraio \u201cCinema sotto la Rocca\u201d, una nuova rassegna cinematografica promossa dal Movimento Shalom in collaborazione con Arci Valdarno e con il patrocinio del Comune [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38486,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-38482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Al via \u201cCinema sotto la Rocca\u201d: sette proiezioni tra febbraio e marzo a San Miniato - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al via \u201cCinema sotto la Rocca\u201d: sette proiezioni tra febbraio e marzo a San Miniato - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Prende il via nel mese di febbraio \u201cCinema sotto la Rocca\u201d, una nuova rassegna cinematografica promossa dal Movimento Shalom in collaborazione con Arci Valdarno e con il patrocinio del Comune [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-31T09:31:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-31T09:32:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/01\/Cinema-Shalom-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1199\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/01\\\/31\\\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/01\\\/31\\\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Al via \u201cCinema sotto la Rocca\u201d: sette proiezioni tra febbraio e marzo a San Miniato\",\"datePublished\":\"2026-01-31T09:31:59+00:00\",\"dateModified\":\"2026-01-31T09:32:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/01\\\/31\\\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\\\/\"},\"wordCount\":549,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/01\\\/31\\\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2026\\\/01\\\/Cinema-Shalom-1.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/01\\\/31\\\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/01\\\/31\\\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\\\/\",\"name\":\"Al via \u201cCinema sotto la Rocca\u201d: sette proiezioni tra febbraio e marzo a San Miniato - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/01\\\/31\\\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/01\\\/31\\\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2026\\\/01\\\/Cinema-Shalom-1.jpeg\",\"datePublished\":\"2026-01-31T09:31:59+00:00\",\"dateModified\":\"2026-01-31T09:32:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/01\\\/31\\\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/01\\\/31\\\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/01\\\/31\\\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2026\\\/01\\\/Cinema-Shalom-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2026\\\/01\\\/Cinema-Shalom-1.jpeg\",\"width\":1600,\"height\":1199},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/01\\\/31\\\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al via \u201cCinema sotto la Rocca\u201d: sette proiezioni tra febbraio e marzo a San Miniato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al via \u201cCinema sotto la Rocca\u201d: sette proiezioni tra febbraio e marzo a San Miniato - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/","og_locale":"it_IT","og_type":"article","og_title":"Al via \u201cCinema sotto la Rocca\u201d: sette proiezioni tra febbraio e marzo a San Miniato - San Miniato","og_description":"Prende il via nel mese di febbraio \u201cCinema sotto la Rocca\u201d, una nuova rassegna cinematografica promossa dal Movimento Shalom in collaborazione con Arci Valdarno e con il patrocinio del Comune [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-01-31T09:31:59+00:00","article_modified_time":"2026-01-31T09:32:08+00:00","og_image":[{"width":1600,"height":1199,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/01\/Cinema-Shalom-1.jpeg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Al via \u201cCinema sotto la Rocca\u201d: sette proiezioni tra febbraio e marzo a San Miniato","datePublished":"2026-01-31T09:31:59+00:00","dateModified":"2026-01-31T09:32:08+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/"},"wordCount":549,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/01\/Cinema-Shalom-1.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/","url":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/","name":"Al via \u201cCinema sotto la Rocca\u201d: sette proiezioni tra febbraio e marzo a San Miniato - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/01\/Cinema-Shalom-1.jpeg","datePublished":"2026-01-31T09:31:59+00:00","dateModified":"2026-01-31T09:32:08+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/01\/Cinema-Shalom-1.jpeg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/01\/Cinema-Shalom-1.jpeg","width":1600,"height":1199},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/01\/31\/al-via-cinema-sotto-la-rocca-sette-proiezioni-tra-febbraio-e-marzo-a-san-miniato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"Al via \u201cCinema sotto la Rocca\u201d: sette proiezioni tra febbraio e marzo a San Miniato"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/sanminiato\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000022621"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=38482"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38482\/revisions"}],"predecessor-version":[{"id":38485,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38482\/revisions\/38485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/38486"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=38482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=38482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=38482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}