{"id":38693,"date":"2026-03-31T13:04:13","date_gmt":"2026-03-31T11:04:13","guid":{"rendered":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/"},"modified":"2026-03-31T13:22:36","modified_gmt":"2026-03-31T11:22:36","slug":"san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/","title":{"rendered":"San Miniato, i giovani uniscono il mondo: dialogo e apertura oltre ogni confine"},"content":{"rendered":"<p><em>Dalla settimana di scambio di Intercultura un messaggio forte:  le nuove generazioni superano divisioni e stereotipi, trasformando l\u2019incontro tra culture in un\u2019occasione concreta di crescita e arricchimento per tutta la comunit\u00e0.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<div>Il nostro territorio ha vissuto un\u2019esperienza di apertura internazionale: il pomeriggio del 28 marzo, un gruppo di\u00a0<b>7\u00a0<\/b>adolescenti provenienti da tutto il mondo \u00e8 arrivato in citt\u00e0 per la\u00a0<b>\u201cSettimana di scambio\u201d<\/b>. Si tratta di studenti che stanno trascorrendo il loro anno scolastico in Italia con Intercultura e che hanno scelto proprio il nostro territorio come meta per scoprire un volto diverso del nostro Paese rispetto alla zona dove risiedono abitualmente. Non \u00e8 solo un viaggio, ma un\u2019immersione profonda nella nostra cultura, guidata dai volontari Intercultura del Centro locale di Pisa.<\/div>\n<p>Il cuore dell\u2019iniziativa \u00e8 stato il programma ideato dai volontari:\u00a0<b>\u201cL\u2019arte in Toscana\u201d<\/b>, pensato per valorizzare le eccellenze locali. Durante la settimana, i ragazzi sono stati coinvolti in attivit\u00e0 con le scuole, e hanno potuto visitare nel corso della settimana le citt\u00e0 di Pisa, Firenze e Lucca, scoprendo le bellezze della nostra terra Toscana.<\/p>\n<div><i>\u201cSiamo felici che l\u2019evento conclusivo si sia tenuto a San Miniato e vogliamo ringraziare per l&#8217;accoglienza\u00a0l&#8217;<wbr \/>Amministrazione comunale in particolare nelle persone dell&#8217;assessore Elena\u00a0Maggiorelli\u00a0che ci ha accolti\u00a0in Comune e dell&#8217;assessore Matteo\u00a0Squicciarini che ha accolto la nostra richiesta. Ringraziamo, altres\u00ec, per la preziosa collaborazione le scuole che hanno reso possibile questa bellissima giornata: il Liceo Marconi e l&#8217;istituto Cattaneo di San Miniato\u00a0per la loro presenza e l&#8217;istituto Carducci di Pisa per l&#8217;accoglienza dell&#8217;exchange student.\u00a0Ed un ringraziamento speciale va a tutti i ragazzi intervenuti che hanno accolto con entusiasmo questa iniziativa e alle famiglie ospitanti, che si sono immerse in questa nuova esperienza\u201d<\/i>, dichiara\u00a0<b>Roberta Carrai<\/b>, responsabile ospitalit\u00e0 per il Centro Locale di Intercultura AFS di Pisa.<\/div>\n<div><i>\u201cOspitare questi ragazzi non \u00e8 un evento straordinario fine a s\u00e9 stesso, ma un gesto quotidiano che trasforma profondamente la nostra comunit\u00e0\u201d<\/i>, dichiara\u00a0<b>Chiara Di Sano<\/b>, presidentessa del Centro locale di Intercultura di Pisa.\u00a0<i>\u201cQuando uno studente internazionale entra in una classe o in una famiglia, mette in moto un cambiamento positivo: i compagni di scuola scoprono nuovi punti di vista sulla realt\u00e0, le famiglie scoprono di avere \u2018molto pi\u00f9 spazio nel cuore\u2019 di quanto pensassero e l\u2019intera comunit\u00e0 si riscopre pi\u00f9 aperta e inclusiva. \u00c8 un\u2019opportunit\u00e0 per allargare lo sguardo dei giovani e per misurarci con le differenze, scoprendo che sono proprio queste a creare legami che durano una vita\u201d.<\/i><\/div>\n<div><i><br \/>\n<\/i>A guidare i nuovi arrivati alla scoperta della citt\u00e0 ci sono stati dei &#8220;ciceroni&#8221; d\u2019eccezione: gli studenti internazionali Natalia, Domingo, Arina e Guilherme provenienti da Polonia, Paraguay, Ucraina, Brasile, gi\u00e0 accolti da famiglie e dalle scuole del nostro territorio dal mese di settembre scorso. Questo scambio tra &#8220;pari&#8221; ha un alto valore formativo: permette agli studenti di confrontare usi, costumi e stili di vita differenti, arricchendo il loro sguardo sull\u2019Italia e sul mondo.<br \/>\nIn questo contesto, l&#8217;accoglienza trasforma l&#8217;educazione in un&#8217;azione concreta di pace: tra le guide figura infatti Arina, studentessa ucraina ospitata grazie a una borsa di studio per merito. Il progetto, in collaborazione con l&#8217;associazione nazionale presidi e le diplomazie estere, mira a restituire a questi giovani il diritto a un futuro di speranza oltre ogni conflitto.<\/div>\n<div><i>&#8220;In un mondo che troppo spesso sembra segnato da divisioni e separazioni, esperienze come questa dimostrano come siano proprio i giovani a superare ogni confine, costruendo relazioni autentiche e dimostrando che le differenze non sono barriere ma opportunit\u00e0<\/i>\u00a0\u2013 dichiarano l\u2019assessora\u00a0<b>Elena Maggiorelli<\/b>\u00a0e l\u2019assessore\u00a0<b>Matteo Squicciarini<\/b>\u00a0-.\u00a0<i>Questi momenti rappresentano un\u2019importante occasione di crescita per tutta la comunit\u00e0: i ragazzi, liberi da stereotipi, si aprono al dialogo e al confronto, dando vita a un vero scambio culturale capace di arricchire tutti, non solo chi arriva ma anche chi accoglie. \u00c8 da qui che nasce una cittadinanza pi\u00f9 consapevole, aperta e inclusiva. Non vediamo l\u2019ora di poterli accogliere nuovamente a San Miniato per continuare insieme questo percorso di apertura e condivisione&#8221;.<\/i><\/div>\n<p>&nbsp;<\/p>\n<p><b>Immagini e Video&nbsp;<\/b><\/p>\n<p><img src='https:\/\/comune.san-miniato.pi.it\/wp-content\/uploads\/2026\/03\/Intercultura_3-1.jpg' alt='image'><\/p>\n<p><img src='https:\/\/comune.san-miniato.pi.it\/wp-content\/uploads\/2026\/03\/Intercultura_2.jpg' alt='image'><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dalla settimana di scambio di Intercultura un messaggio forte: le nuove generazioni superano divisioni e stereotipi, trasformando l\u2019incontro tra culture in un\u2019occasione concreta di crescita e arricchimento per tutta la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38696,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-38693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Miniato, i giovani uniscono il mondo: dialogo e apertura oltre ogni confine - San Miniato<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Miniato, i giovani uniscono il mondo: dialogo e apertura oltre ogni confine - San Miniato\" \/>\n<meta property=\"og:description\" content=\"Dalla settimana di scambio di Intercultura un messaggio forte: le nuove generazioni superano divisioni e stereotipi, trasformando l\u2019incontro tra culture in un\u2019occasione concreta di crescita e arricchimento per tutta la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/\" \/>\n<meta property=\"og:site_name\" content=\"San Miniato\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-31T11:04:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-31T11:22:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/03\/Intercultura_1-e1774954997796-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"820\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/03\\\/31\\\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/03\\\/31\\\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"San Miniato, i giovani uniscono il mondo: dialogo e apertura oltre ogni confine\",\"datePublished\":\"2026-03-31T11:04:13+00:00\",\"dateModified\":\"2026-03-31T11:22:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/03\\\/31\\\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\\\/\"},\"wordCount\":686,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/03\\\/31\\\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2026\\\/03\\\/Intercultura_1-e1774954997796-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/03\\\/31\\\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/03\\\/31\\\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\\\/\",\"name\":\"San Miniato, i giovani uniscono il mondo: dialogo e apertura oltre ogni confine - San Miniato\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/03\\\/31\\\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/03\\\/31\\\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2026\\\/03\\\/Intercultura_1-e1774954997796-1.jpg\",\"datePublished\":\"2026-03-31T11:04:13+00:00\",\"dateModified\":\"2026-03-31T11:22:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/03\\\/31\\\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/03\\\/31\\\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/03\\\/31\\\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2026\\\/03\\\/Intercultura_1-e1774954997796-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2026\\\/03\\\/Intercultura_1-e1774954997796-1.jpg\",\"width\":1200,\"height\":820},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/2026\\\/03\\\/31\\\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Miniato, i giovani uniscono il mondo: dialogo e apertura oltre ogni confine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"name\":\"San Miniato\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanminiato\\\/wp-content\\\/uploads\\\/sites\\\/195\\\/2021\\\/01\\\/Giunta-senza.jpg\",\"width\":1024,\"height\":768,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanminiato\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Miniato, i giovani uniscono il mondo: dialogo e apertura oltre ogni confine - San Miniato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/","og_locale":"it_IT","og_type":"article","og_title":"San Miniato, i giovani uniscono il mondo: dialogo e apertura oltre ogni confine - San Miniato","og_description":"Dalla settimana di scambio di Intercultura un messaggio forte: le nuove generazioni superano divisioni e stereotipi, trasformando l\u2019incontro tra culture in un\u2019occasione concreta di crescita e arricchimento per tutta la [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/","og_site_name":"San Miniato","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-03-31T11:04:13+00:00","article_modified_time":"2026-03-31T11:22:36+00:00","og_image":[{"width":1200,"height":820,"url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/03\/Intercultura_1-e1774954997796-1.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"San Miniato, i giovani uniscono il mondo: dialogo e apertura oltre ogni confine","datePublished":"2026-03-31T11:04:13+00:00","dateModified":"2026-03-31T11:22:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/"},"wordCount":686,"publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/03\/Intercultura_1-e1774954997796-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/","url":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/","name":"San Miniato, i giovani uniscono il mondo: dialogo e apertura oltre ogni confine - San Miniato","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/03\/Intercultura_1-e1774954997796-1.jpg","datePublished":"2026-03-31T11:04:13+00:00","dateModified":"2026-03-31T11:22:36+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/#primaryimage","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/03\/Intercultura_1-e1774954997796-1.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2026\/03\/Intercultura_1-e1774954997796-1.jpg","width":1200,"height":820},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanminiato\/2026\/03\/31\/san-miniato-i-giovani-uniscono-il-mondo-dialogo-e-apertura-oltre-ogni-confine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanminiato\/"},{"@type":"ListItem","position":2,"name":"San Miniato, i giovani uniscono il mondo: dialogo e apertura oltre ogni confine"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanminiato\/#website","url":"https:\/\/comunicacity.net\/sanminiato\/","name":"San Miniato","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanminiato\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanminiato\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanminiato\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/","url":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanminiato\/wp-content\/uploads\/sites\/195\/2021\/01\/Giunta-senza.jpg","width":1024,"height":768,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanminiato\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/sanminiato\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"000022824"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/comments?post=38693"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38693\/revisions"}],"predecessor-version":[{"id":38695,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/posts\/38693\/revisions\/38695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media\/38696"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/media?parent=38693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/categories?post=38693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanminiato\/wp-json\/wp\/v2\/tags?post=38693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}