{"id":140,"date":"2015-03-27T13:59:33","date_gmt":"2015-03-27T13:59:33","guid":{"rendered":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/?p=140"},"modified":"2015-03-27T13:59:33","modified_gmt":"2015-03-27T13:59:33","slug":"conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/","title":{"rendered":"Conferenza stampa di fine anno. Papa: ormai appartiene alla tradizione."},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><\/strong>La conferenza stampa di fine anno dopo ben sei anni \u00e8 diventata un appuntamento atteso dai numerosi operatori dell\u2019informazione che \u2018raccontano\u2019 la storia minima dell\u2019intero comprensorio e partitamente di questa cittadina che si sta imponendo sempre pi\u00f9 come l\u2019ammiraglia di tutte le realt\u00e0 amministrative locali che gravitano nella zona del Basso Volturno.<\/p>\n<p style=\"text-align: justify;\">Una conferenza stampa di fine anno che svolgendosi regolarmente agli inizi del mese di gennaio assume anche i tratti di un vero e proprio momento programmatico per l\u2019anno che si va svolgendo, come ha sottolineato il sindaco Antonio Papa negli indirizzi di saluto ai giornalisti presenti.<\/p>\n<p style=\"text-align: justify;\">L\u2019ambiente, i lavori pubblici, la gestione dei beni confiscati alla criminalit\u00e0 organizzata: questi gli argomenti pi\u00f9 attesi dell\u2019incontro della Giunta Papa con gli operatori dell\u2019informazione.<\/p>\n<p style=\"text-align: justify;\">Hanno illustrato i risultati raggiunti nell\u2019anno trascorso il vice sindaco Salvatore Luiso (con delega ai lavori pubblici e al cimitero); il consigliere capogruppo della Maggioranza Salvatore Russo (con delega alla gestione dei beni confiscati e al bilanci comunale). Il sindaco Papa per l\u2019assente per motivi di lavoro assessore alla cultura e allo sport Nino Minolfi. Lo stesso Papa ha poi relazionato circa lo stato dell\u2019ambiente che gestisce ad interim.<\/p>\n<p style=\"text-align: justify;\">Lo svuotamento del sito \u2013 discarica di Ferrandelle; la realizzazione dell\u2019isola ecologica (che si prevede sar\u00e0 consegnata entro la fine del mese di gennaio);la realizzazione di impianti di trattamento della frazione umida sia in localit\u00e0 Ferrandelle sia nei pressi della discarica di Parco Saurino (la cui messa in sicurezza \u00e8 ormai cosa certa): questi gli obiettivi realizzati o da realizzare nel prossimo futuro da parte dell\u2019amministrazione retta da Papa.<\/p>\n<p style=\"text-align: justify;\">Russo ha relazionato circa l\u2019utilizzazione dei beni confiscati. Sono in totale 121, di cui 39 con progetti di recupero finanziati dai seguenti Enti: 7 dal Ministero dell\u2019Interno; 14 dalla Regione Campania; 2 dal Ministero dell\u2019Ambiente; 3 da Agrorinasce, Comuni soci, cooperative sociali; 1 dalla Fondazione Vodafone, 12 dalla Fondazione con il Sud.<\/p>\n<p style=\"text-align: justify;\">Dei 121 beni confiscati alla camorra (il numero si riferisce a singole particelle catastali) nella disponibilit\u00e0 di Agrorinasce , 18 sono nella disponibilit\u00e0 del comune di Casal di Principe, 4 a Casapesenna, 2 a S.Cipriano d\u2019Aversa, 95 a Santa Maria La Fossa, (di cui 12 finanziati, 31 attivi, 2 lavori in corso, 2 finanziamenti approvati e 61 in corso di assegnazione definitiva).<\/p>\n<p style=\"text-align: justify;\">Infine Salvatore Russo ha dichiarato che per l\u2019anno 2014 sono state mantenute ai minimi l\u2019IMU (4 per mille) e la TASI (1 per mille). Nonostante la spending review per l\u2019anno 2014, il taglio dei trasferimenti dallo stato dai \u20ac 555.921,10 del 2011 agli attuali \u20ac 431.279,55 del 2014 e il mancato gettito delle entrate fiscali da parte dell\u2019Ente, dovuto alla crisi che incide sulle famiglie. Per la TARI 2014 si \u00e8 assistito ad un aumento dovuto a cause non imputabili all\u2019Amministrazione, ma all\u2019aumento dei costi del servizio di smaltimento, arrivati a circa \u20ac 400.000,00, causato soprattutto dall\u2019incremento del costo di conferimento dell\u2019indifferenziato presso la GISEC.<\/p>\n<p style=\"text-align: justify;\">Gli sforzi dell\u2019amministrazione sono stati premiati con il rispetto del patto di stabilit\u00e0 e con un avanzo di amministrazione di circa \u20ac 15.000.00.<\/p>\n<p style=\"text-align: justify;\">il Vice sindaco Salvatore Luiso che ha presentato un lungo elenco di lavori e progettazioni riguardanti l\u2019anno 2014, tra i quali si segnala: un progetto di recupero ad uso sociale e produttivo dell\u2019area confiscata a Schiavone Francesco, Sandokan, sito in Santa Maria La Fossa, localit\u00e0 Ferrandelle, ovvero un progetto di realizzazione centro di documentazione ed educazione ambientale e isola ecologica \u2013 localit\u00e0 Ferrandelle, strada provinciale via Vaticale per un importo complessivo di \u20ac 1.479.000,00; e il Forum in localit\u00e0 ex Capys.<\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"<p>La conferenza stampa di fine anno dopo ben sei anni \u00e8 diventata un appuntamento atteso dai numerosi operatori dell\u2019informazione che \u2018raccontano\u2019 la storia minima dell\u2019intero comprensorio e partitamente di questa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":141,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conferenza stampa di fine anno. Papa: ormai appartiene alla tradizione. - Santa Maria La Fossa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conferenza stampa di fine anno. Papa: ormai appartiene alla tradizione. - Santa Maria La Fossa\" \/>\n<meta property=\"og:description\" content=\"La conferenza stampa di fine anno dopo ben sei anni \u00e8 diventata un appuntamento atteso dai numerosi operatori dell\u2019informazione che \u2018raccontano\u2019 la storia minima dell\u2019intero comprensorio e partitamente di questa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria La Fossa\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-27T13:59:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/03\/fine-anno.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"184\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/03\\\/27\\\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/03\\\/27\\\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Conferenza stampa di fine anno. Papa: ormai appartiene alla tradizione.\",\"datePublished\":\"2015-03-27T13:59:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/03\\\/27\\\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\\\/\"},\"wordCount\":581,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/03\\\/27\\\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2015\\\/03\\\/fine-anno.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/03\\\/27\\\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/03\\\/27\\\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\\\/\",\"name\":\"Conferenza stampa di fine anno. Papa: ormai appartiene alla tradizione. - Santa Maria La Fossa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/03\\\/27\\\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/03\\\/27\\\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2015\\\/03\\\/fine-anno.jpg\",\"datePublished\":\"2015-03-27T13:59:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/03\\\/27\\\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/03\\\/27\\\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/03\\\/27\\\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2015\\\/03\\\/fine-anno.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2015\\\/03\\\/fine-anno.jpg\",\"width\":300,\"height\":184},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/03\\\/27\\\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conferenza stampa di fine anno. Papa: ormai appartiene alla tradizione.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/\",\"name\":\"Santa Maria La Fossa\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conferenza stampa di fine anno. Papa: ormai appartiene alla tradizione. - Santa Maria La Fossa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/","og_locale":"it_IT","og_type":"article","og_title":"Conferenza stampa di fine anno. Papa: ormai appartiene alla tradizione. - Santa Maria La Fossa","og_description":"La conferenza stampa di fine anno dopo ben sei anni \u00e8 diventata un appuntamento atteso dai numerosi operatori dell\u2019informazione che \u2018raccontano\u2019 la storia minima dell\u2019intero comprensorio e partitamente di questa [&hellip;]","og_url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/","og_site_name":"Santa Maria La Fossa","article_published_time":"2015-03-27T13:59:33+00:00","og_image":[{"width":300,"height":184,"url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/03\/fine-anno.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Conferenza stampa di fine anno. Papa: ormai appartiene alla tradizione.","datePublished":"2015-03-27T13:59:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/"},"wordCount":581,"image":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/03\/fine-anno.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/","url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/","name":"Conferenza stampa di fine anno. Papa: ormai appartiene alla tradizione. - Santa Maria La Fossa","isPartOf":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/03\/fine-anno.jpg","datePublished":"2015-03-27T13:59:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/#primaryimage","url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/03\/fine-anno.jpg","contentUrl":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/03\/fine-anno.jpg","width":300,"height":184},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/03\/27\/conferenza-stampa-di-fine-anno-papa-ormai-appartiene-alla-tradizione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/"},{"@type":"ListItem","position":2,"name":"Conferenza stampa di fine anno. Papa: ormai appartiene alla tradizione."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#website","url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/","name":"Santa Maria La Fossa","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts\/140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/comments?post=140"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts\/140\/revisions"}],"predecessor-version":[{"id":142,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts\/140\/revisions\/142"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/media\/141"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/media?parent=140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/categories?post=140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/tags?post=140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}