{"id":1647,"date":"2025-05-28T15:01:46","date_gmt":"2025-05-28T13:01:46","guid":{"rendered":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/"},"modified":"2025-05-28T16:32:33","modified_gmt":"2025-05-28T14:32:33","slug":"referendum-8-e-9-giugno","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/","title":{"rendered":"Referendum 8 e 9 Giugno"},"content":{"rendered":"<p><em>Elettori fisicamente impediti<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><strong>ASSEGNAZIONE DEI FUNZIONARI MEDICI ASL CE DSS21<\/strong><\/p>\n<p>Per il rilascio della certificazione sanitaria ad elettori fisicamente impediti nei giorni di Domenica 08 Giugno alle ore 07.00 alle ore 23.00 e Luned\u00ec 09 Giugno dalle 07.00 alle 15.00, che intendono esercitare il diritto al voto, \u00e8 stato comunicato il nominativo del Funzionario Medico del DSS21 e i suoi contatti:<br \/>\nDott.ssa Antonietta Vaio<br \/>\nantonietta.vaio@aslcaserta.it<\/p>\n<p><strong>VOTO DEGLI ELETTORI AFFETTI DA INFERMITA\u2019 FISICA<\/strong><\/p>\n<p>Gli elettori\u00a0<strong>impossibilitati<\/strong> ad esprimere personalmente il voto per grave infermit\u00e0 e che necessitano di un accompagnatore, se muniti di apposita certificazione medica rilasciata dal Distretto Sanitario di appartenenza, possono esercitare il diritto di voto con l\u2019aiuto di un elettore volontariamente scelto iscritto nelle liste elettorali in un qualsiasi Comune della Repubblica.<\/p>\n<p><strong>Se l\u2019impedimento \u00e8 a carattere permanente<\/strong>, la Legge 5 febbraio 2003 n.17 ha previsto, su richiesta dell\u2019interessato corredata della relativa documentazione, l\u2019apposizione sulla propria tessera elettorale di uno \u201cspecifico simbolo\u201d.<\/p>\n<p><strong>In tal caso l\u2019elettore \u00e8 sempre ammesso al voto con l\u2019aiuto di un accompagnatore senza avere pi\u00f9 l\u2019obbligo di munirsi dell\u2019apposita certificazione medica.<\/strong><\/p>\n<p><strong>NORME INTESE A FAVORIRE LA VOTAZIONE DEGLI ELETTORI PORTATORI DI HANDICAP ED ELETTORI NON DEAMBULANTI (Legge 15\/1\/1991, n. 15)<\/strong><br \/>\nGli\u00a0<strong>elettori non deambulanti<\/strong>, quando la sede della sezione elettorale nella quale sono iscritti non \u00e8 accessibile, possono esercitare il diritto di voto in un\u2019altra sezione del Comune ubicata in sede esente da barriere architettoniche,\u00a0<strong>previa esibizione di una attestazione medica rilasciata dal Distretto Sanitario anche in precedenza per altri scopi<\/strong>\u00a0(es. verbale invalidit\u00e0 civile, causa di servizio, infortunio, ecc), purch\u00e8 dalla documentazione esibita risulti l\u2019impossibilit\u00e0 o la capacit\u00e0 di deambulazione gravemente ridotta.<br \/>\n<strong>L\u2019art. 41 del T.U. 570\/60<\/strong>\u00a0prevede la facolt\u00e0 di esprimere il voto, a mezzo di accompagnatore, per coloro che si trovino fisicamente impossibilitati ad esercitare autonomamente il diritto di voto.<br \/>\nAi sensi della citata normativa sono da considerare elettori fisicamente impediti i ciechi, gli amputati delle mani, gli affetti da paralisi oda altro impedimento di analoga gravit\u00e0.<\/p>\n<p>Gli impedimenti che legittimano l\u2019assistenza nella votazione devono essere riconducibili alla capacit\u00e0 visiva del soggetto o al movimento degli arti superiori, non consentendo l\u2019ammissione al \u201cvoto assistito\u201d infermit\u00e0 che non influiscono su tali capacit\u00e0 ma riguardano la sfera psichica dell\u2019individuo (stato demenziale, demenza senile, rammollimento cerebrale, ecc.).<\/p>\n<p><strong>Le certificazioni mediche per gli elettori fisicamente impediti ad esprimere il voto e per gli elettori non deambulanti<\/strong>\u00a0sono rilasciate, nelle sedi e agli orari individuati dai Direttori di Distretto.<\/p>\n<p><strong>Per rendere pi\u00f9 agevole l\u2019esercizio del diritto di voto, le unit\u00e0 sanitarie locali, nei tre giorni precedenti la consultazione elettorale, garantiscono in ogni comune la disponibilit\u00e0 di un adeguato numero di medici autorizzati per il rilascio dei certificati di accompagnamento e dell\u2019attestazione medica di cui all\u2019articolo 1 della legge 15 gennaio 1991, n. 15 (L.104\/92 art. 29, comma 2)<\/strong><\/p>\n<p><strong>VOTO DOMICILIARE PER GLI ELETTORI IN DIPENDENZA VITALE DA APPARECCHIATURE ELETTROMEDICALI<\/strong>\u00a0<strong>(Legge 27 gennaio 2006, n. 22 e Legge 7 maggio 2009, n.4)<\/strong><br \/>\nLa vigente normativa, Legge n. 22\/2006 e succ. modifiche introdotte dalla Legge 4\/2009, ha previsto la possibilit\u00e0 di\u00a0<strong>voto domiciliare per gli elettori in dipendenza vitale da apparecchiature elettromedicali.<br \/>\n<\/strong>Gli interessati sono tenuti a far pervenire al Sindaco apposita istanza corredata, tra l\u2019altro, da certificato medico da cui risulti \u201c<strong><em>l\u2019esistenza di una infermit\u00e0 fisica che comporta la dipendenza continuativa e vitale da apparecchiature elettromedicali tale da impedire all\u2019elettore di recarsi al seggio<\/em><\/strong>\u201d.<br \/>\nRelativamente alle apparecchiature elettromedicali si chiarisce che trattasi di apparecchiature attinenti le funzioni vitali e necessarie all\u2019esistenza in vita. Sono da ritenersi riconducibili a questa fattispecie quelle vicarianti la funzione respiratoria (ventilatori, concentratori di ossigeno, broncoaspiratori, ecc.), la funzione urinaria (dialisi a domicilio) e la funzione alimentare (pompe enterali, infusori, ecc.). Non sono, invece, inclusi gli apparecchi utili alla autonomia personale, quali servoscala, piattaforme elevatrici, caricabatteria per carrozzine, ascensori ed altri, non indispensabili all\u2019esistenza in vita.<br \/>\n<strong>Le certificazioni mediche per gli elettori in dipendenza vitale da apparecchiature elettromedicali<\/strong>\u00a0sono rilasciate, nelle sedi e agli orari individuati dai Direttori di Distretto.<\/p>\n<p><strong>Il certificato potr\u00e0 anche contenere, qualora ne ricorra la condizione, l\u2019eventuale necessit\u00e0 di un accompagnatore per l\u2019esercizio del voto.<br \/>\n<\/strong><\/p>\n<p><strong>VOTO DOMICILIARE PER GLI ELETTORI AFFETTI DA GRAVISSIME INFERMITA\u2019 TALI\u00a0 CHE L\u2019ALLONTANAMENTO DALLE ABITAZIONI IN CUI DIMORANO RISULTI IMPOSSIBILE ANCHE CON L\u2019AUSILIO DEI SERVIZI DI TRASPORTO PUBBLICO (Legge del 7 maggio 2009, n. 46)<\/strong><br \/>\nAi sensi della Legge n. 46 del 7 maggio 2009\u00a0 sono ammessi al\u00a0<strong>voto domiciliare<\/strong>\u00a0anche gli\u00a0<strong>elettori affetti da gravissime infermit\u00e0<\/strong>\u00a0tali che l\u2019allontanamento dalle abitazioni in cui dimorano risulti impossibile anche con l\u2019ausilio dei servizi di trasporto pubblico previsti dall\u2019art. 29 della legge 5 febbraio 1992, n. 104 (trasporto pubblico che i comuni organizzano in occasione di consultazioni per facilitare agli elettori disabili il raggiungimento del seggio elettorale).<br \/>\n<strong>Per essere ammessi al voto a domicilio il medico dovr\u00e0 certificare l\u2019assoluta intrasportabilit\u00e0 del richiedente<\/strong>.<br \/>\nIn ordine alla certificazione della assoluta intrasportabilit\u00e0 si chiarisce che detto\u00a0 parametro deve essere riferito al complesso e alla gravit\u00e0 delle situazioni cliniche in atto che rendono\u00a0<strong>rischioso e pericoloso<\/strong>\u00a0per il paziente lo spostamento dello stesso dal proprio domicilio. Si precisa, altres\u00ec, che detta condizione non viene esclusivamente legata alla capacit\u00e0 di deambulare.<\/p>\n<p>Le certificazioni mediche per gli elettori affetti da gravissime infermit\u00e0 tali che l\u2019allontanamento dalle abitazioni in cui dimorano risulti impossibile anche con l\u2019ausilio dei servizi di trasporto pubblico sono rilasciate, nelle sedi e agli orari individuati dai Direttori di Distretto.<\/p>\n<p><strong>MODALITA&#8217; DI ACCESSO ALLA PRESTAZIONE<br \/>\n<\/strong>Ai fini del diritto di esercizio del voto gli elettori fisicamente impediti possono rivolgersi al\u00a0<strong>Distretto Sanitario di appartenenza<\/strong>.<br \/>\n<strong>Il certificato rilasciato dalla ASL \u00e8 gratuito<\/strong>\u00a0ed \u00e8 rilasciato, in esenzione da qualsiasi diritto o applicazione di marche, dai medici designati dalla ASL ai sensi dell\u2019art. 41 del T.U. 570\/60.<br \/>\nPer l\u2019effettuazione della visita ai fini del rilascio della certificazione medica \u00e8 necessario che il richiedente esibisca documento d\u2019identit\u00e0 in corso di validit\u00e0 (che dovr\u00e0 essere sempre riportato sulla certificazione medica) ed ogni idonea documentazione attestante la patologia.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_1652\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2025\/05\/NOMINA_MEDICO_REFERENDUM.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2025\/05\/NOMINA_MEDICO_REFERENDUM.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>NOMINA_MEDICO_REFERENDUM<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Elettori fisicamente impediti&nbsp; Descrizione&nbsp; ASSEGNAZIONE DEI FUNZIONARI MEDICI ASL CE DSS21 Per il rilascio della certificazione sanitaria ad elettori fisicamente impediti nei giorni di Domenica 08 Giugno alle ore 07.00 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1651,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-1647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Referendum 8 e 9 Giugno - Santa Maria La Fossa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Referendum 8 e 9 Giugno - Santa Maria La Fossa\" \/>\n<meta property=\"og:description\" content=\"Elettori fisicamente impediti&nbsp; Descrizione&nbsp; ASSEGNAZIONE DEI FUNZIONARI MEDICI ASL CE DSS21 Per il rilascio della certificazione sanitaria ad elettori fisicamente impediti nei giorni di Domenica 08 Giugno alle ore 07.00 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria La Fossa\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-28T13:01:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-28T14:32:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2025\/05\/voto-domicilare.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1196\" \/>\n\t<meta property=\"og:image:height\" content=\"718\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/05\\\/28\\\/referendum-8-e-9-giugno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/05\\\/28\\\/referendum-8-e-9-giugno\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Referendum 8 e 9 Giugno\",\"datePublished\":\"2025-05-28T13:01:46+00:00\",\"dateModified\":\"2025-05-28T14:32:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/05\\\/28\\\/referendum-8-e-9-giugno\\\/\"},\"wordCount\":985,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/05\\\/28\\\/referendum-8-e-9-giugno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/05\\\/voto-domicilare.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/05\\\/28\\\/referendum-8-e-9-giugno\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/05\\\/28\\\/referendum-8-e-9-giugno\\\/\",\"name\":\"Referendum 8 e 9 Giugno - Santa Maria La Fossa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/05\\\/28\\\/referendum-8-e-9-giugno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/05\\\/28\\\/referendum-8-e-9-giugno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/05\\\/voto-domicilare.jpg\",\"datePublished\":\"2025-05-28T13:01:46+00:00\",\"dateModified\":\"2025-05-28T14:32:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/05\\\/28\\\/referendum-8-e-9-giugno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/05\\\/28\\\/referendum-8-e-9-giugno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/05\\\/28\\\/referendum-8-e-9-giugno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/05\\\/voto-domicilare.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/05\\\/voto-domicilare.jpg\",\"width\":1196,\"height\":718},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/05\\\/28\\\/referendum-8-e-9-giugno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referendum 8 e 9 Giugno\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/\",\"name\":\"Santa Maria La Fossa\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Referendum 8 e 9 Giugno - Santa Maria La Fossa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/","og_locale":"it_IT","og_type":"article","og_title":"Referendum 8 e 9 Giugno - Santa Maria La Fossa","og_description":"Elettori fisicamente impediti&nbsp; Descrizione&nbsp; ASSEGNAZIONE DEI FUNZIONARI MEDICI ASL CE DSS21 Per il rilascio della certificazione sanitaria ad elettori fisicamente impediti nei giorni di Domenica 08 Giugno alle ore 07.00 [&hellip;]","og_url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/","og_site_name":"Santa Maria La Fossa","article_published_time":"2025-05-28T13:01:46+00:00","article_modified_time":"2025-05-28T14:32:33+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2025\/05\/voto-domicilare.jpg","height":718,"width":1196,"type":""}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Referendum 8 e 9 Giugno","datePublished":"2025-05-28T13:01:46+00:00","dateModified":"2025-05-28T14:32:33+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/"},"wordCount":985,"image":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2025\/05\/voto-domicilare.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/","url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/","name":"Referendum 8 e 9 Giugno - Santa Maria La Fossa","isPartOf":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2025\/05\/voto-domicilare.jpg","datePublished":"2025-05-28T13:01:46+00:00","dateModified":"2025-05-28T14:32:33+00:00","author":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/#primaryimage","url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2025\/05\/voto-domicilare.jpg","contentUrl":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2025\/05\/voto-domicilare.jpg","width":1196,"height":718},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/05\/28\/referendum-8-e-9-giugno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/"},{"@type":"ListItem","position":2,"name":"Referendum 8 e 9 Giugno"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#website","url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/","name":"Santa Maria La Fossa","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001905"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts\/1647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/comments?post=1647"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts\/1647\/revisions"}],"predecessor-version":[{"id":1649,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts\/1647\/revisions\/1649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/media\/1651"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/media?parent=1647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/categories?post=1647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/tags?post=1647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}