{"id":1780,"date":"2025-09-22T11:08:00","date_gmt":"2025-09-22T09:08:00","guid":{"rendered":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/?p=1780"},"modified":"2025-09-22T11:08:04","modified_gmt":"2025-09-22T09:08:04","slug":"avviso-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/","title":{"rendered":"Avviso"},"content":{"rendered":"<p><em>Manifestazione di interesse allo scorrimento di graduatoria concorsuale per l&#8217;assunzione a tempo parziale e determinato di istruttore di vigilanza  agenti di polizi ex cat. c \u2013 area istruttori <\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><strong>Il responsabile area amministrativa<\/strong><\/p>\n<p><strong>Visti: <\/strong><\/p>\n<ul>\n<li>i vigenti Contratti Collettivi Nazionali di Lavoro per il personale del comparto Regioni e Autonomie locali, ora Comparto Funzioni Locali;<\/li>\n<li>il vigente \u201cRegolamento comunale sull\u2019Ordinamento generale degli Uffici e dei Servizi\u201d, approvato con delibera di G.C. n. 1 del 10\/01\/2008, e ss.mm.ii.;<\/li>\n<li>il vigente \u201cRegolamento comunale sull\u2019Accesso agli Impieghi\u201d approvato con delibera di G.C. n. 112 del 21\/10\/2009, e ss.mm.ii.;<\/li>\n<li>la Deliberazione di Giunta Comunale n. 34 del 17\/04\/2025 ad oggetto: \u201c<em>PIANO INTEGRATO DI ATTIVITA\u2019 E ORGANIZZAZIONE (P.I.A.O.) 2025-2027. APPROVAZIONE<\/em>\u201d veniva approvato il Piao;<\/li>\n<li>la Deliberazione di Giunta Comunale n. 76 del 02.09.2025 si procedeva alla modifica del PIAO;<\/li>\n<li>la determina dirigenziale n. di approvazione del presente avviso;<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>rende noto<\/strong><\/p>\n<p>Che il Comune di Santa Maria La Fossa intende procedere all\u2019assunzione a tempo parziale (50%) e determinato di due unit\u00e0 per il profilo professionale di \u201cISTRUTTORE VIGILANZA\u201d (Cat. \u201cC\u201d \u2013 posizione economica C.1) mediante l\u2019utilizzo di graduatorie in corso di validit\u00e0, approvate da altri Enti del Comparto Funzioni Locali, relative a concorsi pubblici espletati per la copertura a tempo indeterminato per categoria e profilo professionale analogo o equivalente a quello che questo Ente deve ricoprire.<\/p>\n<p>&nbsp;<\/p>\n<p>Il Comune di Santa Maria La Fossa, per l\u2019assunzione a tempo pieno e indeterminato di n. 2 unit\u00e0 per il profilo professionale di Istruttore di Vigilanza\/Agente di Polizia locale Cat. C \u2013 posizione economica C\/1, intende procedere mediante l\u2019utilizzo di graduatorie in corso di validit\u00e0, approvate da altri Enti del Comparto Funzioni Locali, relative a concorsi pubblici espletati per la copertura a tempo pieno e indeterminato per categoria e profilo professionale corrispondenti a quello che questo Ente deve ricoprire.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Destinatari <\/strong>Sono invitati a segnalare la graduatoria presentando manifestazione di interesse, utilizzando lo schema allegato al presente avviso, i soggetti idonei, interessati all\u2019assunzione presso il Comune di Santa Maria La Fossa, collocati nelle graduatorie in corso di validit\u00e0, approvate da Enti del Comparto Funzioni Locali, in seguito all\u2019espletamento di concorsi pubblici per la copertura di posti a tempo pieno e indeterminato, in profilo professionale analogo a quello che si intende ricoprire. Non saranno prese in considerazione le graduatorie relative a concorsi banditi per posti a tempo parziale o determinato<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Modalit\u00e0 e termini di presentazione della domanda<\/strong><\/p>\n<p>La manifestazione di interesse da parte del soggetto idoneo, redatta in carta semplice utilizzando il modello allegato al presente avviso, dovr\u00e0 pervenire entro e non oltre il quindicesimo giorno dalla pubblicazione del presente avviso all\u2019Albo pretorio on line del Comune. Le domande dovranno essere indirizzate a: Comune di Santa Maria La Fossa<\/p>\n<p>\u2013 Area Amministrativa, Piazza Europa, 4 &#8211; 81050 SANTA MARIA LA FOSSA (CE). Le domande potranno pervenire anche tramite posta elettronica certificata, al seguente indirizzo: protocollo.santamarialafossa@asmepec.it. Sulla busta della domanda o nell&#8217;oggetto della PEC dovr\u00e0 essere riportata la dicitura \u201c<strong><u>SCORRIMENTO GRADUATORIE CONCORSUALI \u2013 ISTRUTTORI DI VIGILANZA<\/u><\/strong>\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Con riferimento alla trasmissione tramite PEC, si precisa che la domanda di partecipazione verr\u00e0 accettata soltanto nel caso di invio da casella di posta elettronica certificata rilasciata personalmente al candidato. La domanda di partecipazione pu\u00f2 essere sottoscritta e scansionata ovvero sottoscritta con firma digitale ed i relativi allegati saranno ritenuti validi solo se inviati in formato pdf, senza macroistruzioni o codici eseguibili. La data e l\u2019ora di presentazione saranno attestate dalla ricevuta di accettazione registrata dal sistema elettronico. Non sar\u00e0 ritenuto valido, con conseguente esclusione dei candidati dalla procedura in oggetto, l\u2019invio da casella di posta elettronica semplice\/ordinaria, in quanto non idoneo all&#8217;acquisizione della domanda di partecipazione al protocollo, anche se effettuato all\u2019indirizzo di posta elettronica certificata dell\u2019Ente, ovvero l&#8217;invio, attraverso PEC, ad indirizzi di posta elettronica del Comune diversi dalla casella di posta elettronica certificata sopra indicata.<\/p>\n<p>L\u2019Amministrazione non assume alcuna responsabilit\u00e0 per il caso di dispersione di comunicazioni dipendente da inesatte indicazioni del recapito nella domanda dei candidati oppure da mancata o tardiva comunicazione del cambiamento dell\u2019indirizzo indicato nella domanda medesima, n\u00e9 per eventuali disguidi postali o telegrafici o comunque imputabili a fatto di terzi, a caso fortuito o forza maggiore non imputabili all\u2019Amministrazione stessa.<\/p>\n<p>La manifestazione di interesse \u2013 tra le altre informazioni \u2013 dovr\u00e0 indicare:<\/p>\n<p>&#8211; nome, cognome, luogo e data di nascita, codice fiscale e titolo di studio del candidato;<\/p>\n<p>&#8211; residenza, recapito telefonico, indirizzo mail e\/o pec se posseduto;<\/p>\n<p>&#8211; dichiarazione in merito alla manifestazione d\u2019interesse all\u2019assunzione;<\/p>\n<p>&#8211; dichiarazione della posizione (tra gli idonei non ancora assunti) in vigente graduatoria concorsuale per assunzione a tempo indeterminato;<\/p>\n<p>&#8211; Amministrazione che ha approvato la graduatoria e data di approvazione della stessa. Scaduti i termini per la presentazione delle manifestazioni di interesse, il competente ufficio comunale contatter\u00e0 le Amministrazioni detentrici delle graduatorie segnalate dai candidati interessati all\u2019assunzione presso il Comune di Santa Maria La Fossa, al fine di verificare la disponibilit\u00e0 dei medesimi Enti all\u2019utilizzo delle proprie graduatorie; agli Enti detentori delle graduatorie \u00e8 assegnato un termine non inferiore a 10 giorni per comunicare la propria disponibilit\u00e0 in merito all\u2019utilizzo da parte del Comune di Santa Maria La Fossa delle proprie graduatorie.<\/p>\n<p><strong>Criteri di utilizzo graduatorie a<\/strong>cquisite le disponibilit\u00e0 da parte degli Enti detentori delle graduatorie, si proceder\u00e0 alla scelta della graduatoria da utilizzare secondo i seguenti criteri di priorit\u00e0:<\/p>\n<ol>\n<li>a) graduatorie di Enti del comparto confinanti con il Comune di Santa Maria La Fossa;<\/li>\n<\/ol>\n<p>b)in mancanza, graduatorie di Enti del comparto aventi sede nella Provincia Di Caserta;<\/p>\n<ol>\n<li>c) graduatorie di Enti del comparto aventi sede in altre province della Regione Campania;<\/li>\n<li>d) graduatorie di Enti del comparto aventi sede nazionale;<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>A parit\u00e0 di criteri di priorit\u00e0, sar\u00e0 preferita la graduatoria pi\u00f9 recente, avuto riguardo alla data di approvazione della stessa.<\/p>\n<p><strong>Scorrmento della graduatoria<\/strong>\u00a0Individuata la graduatoria della quale avvalersi ai fini della copertura dei posti indicati nel presente avviso, si proceder\u00e0 al suo utilizzo previo accordo (convenzione) con l&#8217;Ente detentore, mediante scorrimento, in rigoroso ordine di graduatoria, dei soggetti utilmente collocati (compresi coloro che non abbiano presentato la manifestazione di interesse), ai quali \u00e8 assegnato un termine di 5 giorni per manifestare la propria disponibilit\u00e0 all&#8217;assunzione da parte del Comune di Santa Maria La Fossa.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel caso in cui il l\u2019Ente titolare della graduatoria non detenga o non comunichi, per qualunque motivo, i recapiti dei soggetti utilmente collocati, si proceder\u00e0 a pubblicazione della richiesta di disponibilit\u00e0 all\u2019Albo Pretorio, nel rispetto delle disposizioni in materia di privacy, con indicazione del numero d\u2019ordine in graduatoria e dei riferimenti alla graduatoria stessa, per durata non inferiore a 10 giorni, decorsi i quali la disponibilit\u00e0 si intender\u00e0 non espressa.<\/p>\n<p>Ai fini della copertura dei posti previsti dal presente avviso, in caso di esaurimento della graduatoria, si proceder\u00e0 all\u2019utilizzo di altre graduatorie, selezionate secondo l\u2019ordine di priorit\u00e0 sopra indicato.<\/p>\n<p>Non verranno tenute in considerazione graduatorie impugnate o non ancora definitivamente efficaci ovvero graduatorie oggetto di contenzioso.<\/p>\n<p>La presente procedura non costituisce alcun titolo e diritto per gli idonei inseriti nelle graduatorie degli Enti che hanno manifestato la disponibilit\u00e0 all\u2019utilizzo delle proprie graduatorie da parte del Comune di Santa Maria La Fossa e non vincola l\u2019Amministrazione Comunale a procedere all\u2019assunzione.<\/p>\n<p>In ogni caso \u00e8 facolt\u00e0 del Comune di Santa Maria La Fossa di non dar seguito alla procedura.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Informazioni sul procedimento<\/strong>\u00a0Ai sensi della vigente normativa in materia, si informa che i dati forniti sui candidati in graduatoria saranno utilizzati dal Servizio Risorse Umane per le finalit\u00e0 di gestione della presente procedura e saranno trattati, anche successivamente all\u2019eventuale instaurazione del rapporto di lavoro, per le finalit\u00e0 inerenti alla gestione del rapporto, anche mediante trattamento informatico. Il conferimento di tali dati \u00e8 obbligatorio ai fini della valutazione dei requisiti di partecipazione.<\/p>\n<p>Il presente avviso sar\u00e0 pubblicato per un periodo di 15 giorni all\u2019Albo Pretorio e sul sito istituzionale del Comune di Santa Maria La Fossa nelle sezioni \u201cNews\u201d e \u201cBandi di Concorso\u201d. Ogni altra informazione relativa al presente avviso pu\u00f2 essere richiesta all\u2019Area Amministrativa \u2013 Servizio Risorse Umane (parte giuridica) del Comune di Santa Maria La Fossa (pec: protocollo.santamarialafossa@asmepec.it \u2013 telefono: 0823993749).<\/p>\n<p>Il Responsabile del procedimento \u00e8 l\u2019avv. Anna Ciancio.<\/p>\n<p>Il\u00a0 Responsabile AREA AMMINISTRATIVA<\/p>\n<p>F.to Avv. Anna Ciancio<\/p>\n<p>(Firma Autografa omessa Ai sensi dell\u2019art.3 del D.lgs. 39\/93)<\/p>\n<p>&nbsp;&nbsp;<\/p>\n<p><b>Video&nbsp;<\/b><\/p>\n<div style=\"border:1px solid black\">\n                    <a href=\"http:\/\/comune.santamarialafossa.ce.it\/wp-content\/uploads\/2025\/09\/allegato-a-modello-di-manifestazione-di-interesse.pdf\">Apri il Video<\/a>\n                    <\/div>\n<hr style=\"color:#999\">\n","protected":false},"excerpt":{"rendered":"<p>Manifestazione di interesse allo scorrimento di graduatoria concorsuale per l&#8217;assunzione a tempo parziale e determinato di istruttore di vigilanza agenti di polizi ex cat. c \u2013 area istruttori &nbsp; Descrizione&nbsp; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1783,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-1780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bandi-e-concorsi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso - Santa Maria La Fossa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso - Santa Maria La Fossa\" \/>\n<meta property=\"og:description\" content=\"Manifestazione di interesse allo scorrimento di graduatoria concorsuale per l&#8217;assunzione a tempo parziale e determinato di istruttore di vigilanza agenti di polizi ex cat. c \u2013 area istruttori &nbsp; Descrizione&nbsp; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria La Fossa\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-22T09:08:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-22T09:08:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2025\/09\/bando_di_concorso-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/09\\\/22\\\/avviso-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/09\\\/22\\\/avviso-2\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Avviso\",\"datePublished\":\"2025-09-22T09:08:00+00:00\",\"dateModified\":\"2025-09-22T09:08:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/09\\\/22\\\/avviso-2\\\/\"},\"wordCount\":1397,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/09\\\/22\\\/avviso-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/09\\\/bando_di_concorso-1.jpg\",\"articleSection\":[\"Bandi e Concorsi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/09\\\/22\\\/avviso-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/09\\\/22\\\/avviso-2\\\/\",\"name\":\"Avviso - Santa Maria La Fossa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/09\\\/22\\\/avviso-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/09\\\/22\\\/avviso-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/09\\\/bando_di_concorso-1.jpg\",\"datePublished\":\"2025-09-22T09:08:00+00:00\",\"dateModified\":\"2025-09-22T09:08:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/09\\\/22\\\/avviso-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/09\\\/22\\\/avviso-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/09\\\/22\\\/avviso-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/09\\\/bando_di_concorso-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/09\\\/bando_di_concorso-1.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2025\\\/09\\\/22\\\/avviso-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/\",\"name\":\"Santa Maria La Fossa\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"],\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/author\\\/comunicadmin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso - Santa Maria La Fossa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso - Santa Maria La Fossa","og_description":"Manifestazione di interesse allo scorrimento di graduatoria concorsuale per l&#8217;assunzione a tempo parziale e determinato di istruttore di vigilanza agenti di polizi ex cat. c \u2013 area istruttori &nbsp; Descrizione&nbsp; [&hellip;]","og_url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/","og_site_name":"Santa Maria La Fossa","article_published_time":"2025-09-22T09:08:00+00:00","article_modified_time":"2025-09-22T09:08:04+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2025\/09\/bando_di_concorso-1.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Avviso","datePublished":"2025-09-22T09:08:00+00:00","dateModified":"2025-09-22T09:08:04+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/"},"wordCount":1397,"image":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2025\/09\/bando_di_concorso-1.jpg","articleSection":["Bandi e Concorsi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/","url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/","name":"Avviso - Santa Maria La Fossa","isPartOf":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2025\/09\/bando_di_concorso-1.jpg","datePublished":"2025-09-22T09:08:00+00:00","dateModified":"2025-09-22T09:08:04+00:00","author":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/#primaryimage","url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2025\/09\/bando_di_concorso-1.jpg","contentUrl":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2025\/09\/bando_di_concorso-1.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2025\/09\/22\/avviso-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/"},{"@type":"ListItem","position":2,"name":"Avviso"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#website","url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/","name":"Santa Maria La Fossa","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"],"url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/author\/comunicadmin\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001995"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts\/1780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/comments?post=1780"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts\/1780\/revisions"}],"predecessor-version":[{"id":1782,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts\/1780\/revisions\/1782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/media\/1783"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/media?parent=1780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/categories?post=1780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/tags?post=1780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}