{"id":308,"date":"2015-05-19T11:34:42","date_gmt":"2015-05-19T11:34:42","guid":{"rendered":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/?p=308"},"modified":"2015-05-19T11:34:42","modified_gmt":"2015-05-19T11:34:42","slug":"il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/","title":{"rendered":"IL SINDACO PAPA E IL SANTA MARIA LA FOSSA: \u201cSTAGIONE FENOMENALE, UNITI E VINCENTI PER LO SPORT\u201d"},"content":{"rendered":"<p>Coppa e campionato. Bastano queste due semplici parole per spiegare la stagione del Santa Maria La Fossa e il primo cittadino della citt\u00e0 con il vessillo gialloverde \u00e8 il primo tifoso della squadra del tecnico Fischetti. <strong>Antonio Papa<\/strong>, il sindaco-tifoso, innamorato di Santa Maria e del Santa Maria La Fossa calcio, racconta la sua esperienza da amante del calcio e del suo paese che guida dal 2009 grazie al secondo mandato.<\/p>\n<p><strong>La stagione.\u00a0<\/strong>La matricola terribile del campionato ha sorpreso tutti portando a casa due trofei: <em>\u201cVincere Coppa e campionato come recita uno spot pubblicitario \u201cNon ha prezzo\u201d. Le nostre sono state delle vittorie storiche, non solo per il nostro paese di sole 3000 anime, ma per tutto il comprensorio del basso Volturno. A memoria storica questi risultati non sono stati mai raggiunti, non \u00e8 un caso se vengono portati a termine durante il mio secondo mandato. Come amministrazione siamo sempre stati vicini allo sport, riqualificando il campo sportivo e la palestra comunale mettendole a disposizione per le societ\u00e0 di Santa Maria la Fossa e Grazzanise. Non sono solo un tifoso del Santa Maria La Fossa calcio, ma soprattutto e per sempre del mio paese.\u201d<\/em><\/p>\n<p><strong>La squadra.\u00a0<\/strong>I gialloverdi sono stati la rivelazione del campionato, detengono le migliori statistiche del campionato:\u00a0<em>\u201cInutile sottolineare ancora il grande gruppo coeso del Santa Maria, siamo una grande squadra con solamente sei calciatori provenienti dai territori limitrofi che insieme ai fossatari doc costituiscono questo grande gruppo. E\u2019 il secondo campionato consecutivo che vinciamo, siamo partiti dalla Seconda Categoria lo scorso anno e vincere subito il campionato di Prima e la Coppa era quasi impensabile, ma raccogliamo i frutti di un grande lavoro della societ\u00e0. Dopo i dovuti festeggiamenti, il presidente <\/em><em>Roberto Martino<\/em><em>, insieme al grande direttore sportivo <\/em><em>Lorenzo Parente<\/em><em> si metteranno al lavoro per la prossima annata per aggiungere qualche tassello alla gi\u00e0 preziosa rosa del tecnico <\/em><em>Fischetti<\/em><em><strong>.<\/strong> Il tecnico ha saputo prendere la squadra in corsa facendola letteralmente volare ai vertici del calcio campano, ogni ragazzo della squadra merita un grande elogio per il lavoro svolto in questa stagione.\u201d<\/em><\/p>\n<p><strong>Il futuro e l\u2019impegno.\u00a0<\/strong>Occhi proiettati al futuro, la prossima stagione non \u00e8 poi cos\u00ec lontana:\u00a0<em>\u201cSappiamo benissimo che il campionato di Promozione \u00e8 molto pi\u00f9 impegnativo di questo avvincente campionato di Prima categoria che sta per terminare. Come sindaco, ringrazio pubblicamente tutti i Consiglieri Comunali di Maggioranza che hanno dato l\u2019anima per la nostra squadra ed in particolare l\u2019assessore allo sport<\/em> <em>Nino Minolfi<\/em><em><strong>,<\/strong> so che il nostro impegno nel miglioramento delle strutture non deve finire, abbiamo reso il nostro campo sportivo un piccolo gioiellino invidiato da tanti. Lo sport \u00e8 un collante sociale per noi, rappresenta il vivere sociale ed aggregazione per il territorio di Santa Maria La Fossa e Grazzanise, due comunit\u00e0 che hanno saputo lavorare insieme per il bene comune. La societ\u00e0 del Santa Maria La Fossa non \u00e8 una semplice societ\u00e0, \u00e8 una grande famiglia dove ognuno svolge il proprio compito nel modo pi\u00f9 encomiabile possibile e contribuisce al raggiungimento degli obiettivi prefissati. Voglio ringraziare tutti coloro che ci hanno consentito di raggiungere questi traguardi: calciatori, dirigenti, sponsor, ma soprattutto i nostri tifosi che si sono appassionati all\u2019annata gialloverde, spero che aumentino il prossimo anno. E concludo con gli hashtag associati ai miei selfie: #adelante #statesereni \u201c<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-309\" src=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/05\/22437_100513323311487_5608812_n.jpg\" alt=\"22437_100513323311487_5608812_n\" width=\"160\" height=\"160\" srcset=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/05\/22437_100513323311487_5608812_n.jpg 160w, https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/05\/22437_100513323311487_5608812_n-150x150.jpg 150w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coppa e campionato. Bastano queste due semplici parole per spiegare la stagione del Santa Maria La Fossa e il primo cittadino della citt\u00e0 con il vessillo gialloverde \u00e8 il primo [&hellip;]<\/p>\n","protected":false},"author":50,"featured_media":309,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IL SINDACO PAPA E IL SANTA MARIA LA FOSSA: \u201cSTAGIONE FENOMENALE, UNITI E VINCENTI PER LO SPORT\u201d - Santa Maria La Fossa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IL SINDACO PAPA E IL SANTA MARIA LA FOSSA: \u201cSTAGIONE FENOMENALE, UNITI E VINCENTI PER LO SPORT\u201d - Santa Maria La Fossa\" \/>\n<meta property=\"og:description\" content=\"Coppa e campionato. Bastano queste due semplici parole per spiegare la stagione del Santa Maria La Fossa e il primo cittadino della citt\u00e0 con il vessillo gialloverde \u00e8 il primo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria La Fossa\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-19T11:34:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/05\/22437_100513323311487_5608812_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"160\" \/>\n\t<meta property=\"og:image:height\" content=\"160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"antoniopapa\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"antoniopapa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/05\\\/19\\\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/05\\\/19\\\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\\\/\"},\"author\":{\"name\":\"antoniopapa\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#\\\/schema\\\/person\\\/e811cf02296bf807fadee613763660e0\"},\"headline\":\"IL SINDACO PAPA E IL SANTA MARIA LA FOSSA: \u201cSTAGIONE FENOMENALE, UNITI E VINCENTI PER LO SPORT\u201d\",\"datePublished\":\"2015-05-19T11:34:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/05\\\/19\\\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\\\/\"},\"wordCount\":558,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/05\\\/19\\\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2015\\\/05\\\/22437_100513323311487_5608812_n.jpg\",\"articleSection\":[\"Sport\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/05\\\/19\\\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/05\\\/19\\\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\\\/\",\"name\":\"IL SINDACO PAPA E IL SANTA MARIA LA FOSSA: \u201cSTAGIONE FENOMENALE, UNITI E VINCENTI PER LO SPORT\u201d - Santa Maria La Fossa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/05\\\/19\\\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/05\\\/19\\\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2015\\\/05\\\/22437_100513323311487_5608812_n.jpg\",\"datePublished\":\"2015-05-19T11:34:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#\\\/schema\\\/person\\\/e811cf02296bf807fadee613763660e0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/05\\\/19\\\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/05\\\/19\\\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/05\\\/19\\\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2015\\\/05\\\/22437_100513323311487_5608812_n.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2015\\\/05\\\/22437_100513323311487_5608812_n.jpg\",\"width\":160,\"height\":160},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/2015\\\/05\\\/19\\\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IL SINDACO PAPA E IL SANTA MARIA LA FOSSA: \u201cSTAGIONE FENOMENALE, UNITI E VINCENTI PER LO SPORT\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/\",\"name\":\"Santa Maria La Fossa\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/#\\\/schema\\\/person\\\/e811cf02296bf807fadee613763660e0\",\"name\":\"antoniopapa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/178688a9b95db603c3d404eb181d20ee17144df19f3b472427e9b9c6242659fe?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/178688a9b95db603c3d404eb181d20ee17144df19f3b472427e9b9c6242659fe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/178688a9b95db603c3d404eb181d20ee17144df19f3b472427e9b9c6242659fe?s=96&d=mm&r=g\",\"caption\":\"antoniopapa\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/santa-maria-la-fossa\\\/author\\\/antoniopapa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IL SINDACO PAPA E IL SANTA MARIA LA FOSSA: \u201cSTAGIONE FENOMENALE, UNITI E VINCENTI PER LO SPORT\u201d - Santa Maria La Fossa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/","og_locale":"it_IT","og_type":"article","og_title":"IL SINDACO PAPA E IL SANTA MARIA LA FOSSA: \u201cSTAGIONE FENOMENALE, UNITI E VINCENTI PER LO SPORT\u201d - Santa Maria La Fossa","og_description":"Coppa e campionato. Bastano queste due semplici parole per spiegare la stagione del Santa Maria La Fossa e il primo cittadino della citt\u00e0 con il vessillo gialloverde \u00e8 il primo [&hellip;]","og_url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/","og_site_name":"Santa Maria La Fossa","article_published_time":"2015-05-19T11:34:42+00:00","og_image":[{"width":160,"height":160,"url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/05\/22437_100513323311487_5608812_n.jpg","type":"image\/jpeg"}],"author":"antoniopapa","twitter_misc":{"Scritto da":"antoniopapa","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/"},"author":{"name":"antoniopapa","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#\/schema\/person\/e811cf02296bf807fadee613763660e0"},"headline":"IL SINDACO PAPA E IL SANTA MARIA LA FOSSA: \u201cSTAGIONE FENOMENALE, UNITI E VINCENTI PER LO SPORT\u201d","datePublished":"2015-05-19T11:34:42+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/"},"wordCount":558,"image":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/05\/22437_100513323311487_5608812_n.jpg","articleSection":["Sport"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/","url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/","name":"IL SINDACO PAPA E IL SANTA MARIA LA FOSSA: \u201cSTAGIONE FENOMENALE, UNITI E VINCENTI PER LO SPORT\u201d - Santa Maria La Fossa","isPartOf":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/05\/22437_100513323311487_5608812_n.jpg","datePublished":"2015-05-19T11:34:42+00:00","author":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#\/schema\/person\/e811cf02296bf807fadee613763660e0"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/#primaryimage","url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/05\/22437_100513323311487_5608812_n.jpg","contentUrl":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-content\/uploads\/sites\/24\/2015\/05\/22437_100513323311487_5608812_n.jpg","width":160,"height":160},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/2015\/05\/19\/il-sindaco-papa-e-il-santa-maria-la-fossa-stagione-fenomenale-uniti-e-vincenti-per-lo-sport\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/"},{"@type":"ListItem","position":2,"name":"IL SINDACO PAPA E IL SANTA MARIA LA FOSSA: \u201cSTAGIONE FENOMENALE, UNITI E VINCENTI PER LO SPORT\u201d"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#website","url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/","name":"Santa Maria La Fossa","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/#\/schema\/person\/e811cf02296bf807fadee613763660e0","name":"antoniopapa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/178688a9b95db603c3d404eb181d20ee17144df19f3b472427e9b9c6242659fe?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/178688a9b95db603c3d404eb181d20ee17144df19f3b472427e9b9c6242659fe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/178688a9b95db603c3d404eb181d20ee17144df19f3b472427e9b9c6242659fe?s=96&d=mm&r=g","caption":"antoniopapa"},"url":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/author\/antoniopapa\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts\/308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/comments?post=308"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts\/308\/revisions"}],"predecessor-version":[{"id":310,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/posts\/308\/revisions\/310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/media\/309"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/media?parent=308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/categories?post=308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/santa-maria-la-fossa\/wp-json\/wp\/v2\/tags?post=308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}