{"id":381,"date":"2020-04-12T10:46:35","date_gmt":"2020-04-12T08:46:35","guid":{"rendered":"https:\/\/comunicacity.net\/santamariacapuavetere\/?p=381"},"modified":"2020-04-12T10:46:35","modified_gmt":"2020-04-12T08:46:35","slug":"salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/","title":{"rendered":"Salutiamo l&#8217;Italia illuminando con il tricolore le nostre bellezze. Buona Pasqua!"},"content":{"rendered":"<p>Siamo una grande Citt\u00e0!<\/p>\n<p>Lo racconta la nostra storia.<br \/>\nLo dimostreremo vincendo anche questa sfida!<\/p>\n<div class=\"text_exposed_show\">\n<p>Vogliamo salutare l\u2019Italia illuminando con il tricolore le nostre bellezze.<\/p>\n<p>Vogliamo testimoniare anche cos\u00ec la nostra vicinanza alle famiglie che hanno perso i loro cari, ai contagiati, a tutto il personale sanitario che lotta in prima linea per salvare vite, alle forze dell\u2019ordine e al mondo del volontariato.<\/p>\n<p>Un sentito grazie a tutti voi cittadini che, con senso di responsabilit\u00e0 e non senza sacrificio, restate a casa.<\/p>\n<p>Buona Pasqua Santa Maria Capua Vetere.<br \/>\nBuona Pasqua Italia!<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p>Si ringrazia, per la realizzazione di tale iniziativa, la Direzione Regionale dei Musei, la Sovrintendenza Archeologia belle arti e paesaggio per le province di Caserta e Benevento, la Presidenza del Tribunale, e per la proposta e collaborazione tecnica gratuita Francesco Loria, Valerio Uccella e Vincenzo Santonastaso.<\/p>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-383\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92538532_2535341396689601_1360904832059179008_o-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92538532_2535341396689601_1360904832059179008_o-300x200.jpg 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92538532_2535341396689601_1360904832059179008_o-1024x683.jpg 1024w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92538532_2535341396689601_1360904832059179008_o-768x512.jpg 768w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92538532_2535341396689601_1360904832059179008_o-1536x1024.jpg 1536w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92538532_2535341396689601_1360904832059179008_o-680x453.jpg 680w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92538532_2535341396689601_1360904832059179008_o.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-384\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92547595_2535341270022947_6626025796215504896_o-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92547595_2535341270022947_6626025796215504896_o-300x200.jpg 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92547595_2535341270022947_6626025796215504896_o-1024x683.jpg 1024w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92547595_2535341270022947_6626025796215504896_o-768x512.jpg 768w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92547595_2535341270022947_6626025796215504896_o-1536x1024.jpg 1536w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92547595_2535341270022947_6626025796215504896_o-680x453.jpg 680w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92547595_2535341270022947_6626025796215504896_o.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-385\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92550118_2535341246689616_1247576695410524160_o-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92550118_2535341246689616_1247576695410524160_o-300x200.jpg 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92550118_2535341246689616_1247576695410524160_o-1024x682.jpg 1024w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92550118_2535341246689616_1247576695410524160_o-768x512.jpg 768w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92550118_2535341246689616_1247576695410524160_o-1536x1024.jpg 1536w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92550118_2535341246689616_1247576695410524160_o-680x453.jpg 680w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92550118_2535341246689616_1247576695410524160_o.jpg 1772w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-386\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92570269_2535341376689603_8779622342318882816_o-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92570269_2535341376689603_8779622342318882816_o-300x200.jpg 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92570269_2535341376689603_8779622342318882816_o-1024x682.jpg 1024w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92570269_2535341376689603_8779622342318882816_o-768x512.jpg 768w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92570269_2535341376689603_8779622342318882816_o-1536x1024.jpg 1536w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92570269_2535341376689603_8779622342318882816_o-680x453.jpg 680w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92570269_2535341376689603_8779622342318882816_o.jpg 1772w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-387\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92571388_2535341476689593_9074784138556342272_o-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92571388_2535341476689593_9074784138556342272_o-300x200.jpg 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92571388_2535341476689593_9074784138556342272_o-1024x682.jpg 1024w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92571388_2535341476689593_9074784138556342272_o-768x512.jpg 768w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92571388_2535341476689593_9074784138556342272_o-1536x1024.jpg 1536w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92571388_2535341476689593_9074784138556342272_o-680x453.jpg 680w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92571388_2535341476689593_9074784138556342272_o.jpg 1772w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-388\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92670520_2535341100022964_8254010845999136768_o-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92670520_2535341100022964_8254010845999136768_o-300x200.jpg 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92670520_2535341100022964_8254010845999136768_o-1024x682.jpg 1024w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92670520_2535341100022964_8254010845999136768_o-768x512.jpg 768w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92670520_2535341100022964_8254010845999136768_o-1536x1024.jpg 1536w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92670520_2535341100022964_8254010845999136768_o-680x453.jpg 680w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92670520_2535341100022964_8254010845999136768_o.jpg 1772w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-389\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92696158_2535406236683117_7087562363368374272_o-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92696158_2535406236683117_7087562363368374272_o-200x300.jpg 200w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92696158_2535406236683117_7087562363368374272_o.jpg 640w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-390\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92784158_2535403206683420_1505816599129489408_o-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92784158_2535403206683420_1505816599129489408_o-300x200.jpg 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92784158_2535403206683420_1505816599129489408_o-1024x682.jpg 1024w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92784158_2535403206683420_1505816599129489408_o-768x512.jpg 768w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92784158_2535403206683420_1505816599129489408_o-1536x1024.jpg 1536w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92784158_2535403206683420_1505816599129489408_o-680x453.jpg 680w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92784158_2535403206683420_1505816599129489408_o.jpg 1772w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-391\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92948246_2535341486689592_3012748326387843072_o-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92948246_2535341486689592_3012748326387843072_o-300x200.jpg 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92948246_2535341486689592_3012748326387843072_o-1024x683.jpg 1024w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92948246_2535341486689592_3012748326387843072_o-768x512.jpg 768w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92948246_2535341486689592_3012748326387843072_o-1536x1024.jpg 1536w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92948246_2535341486689592_3012748326387843072_o-680x453.jpg 680w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92948246_2535341486689592_3012748326387843072_o.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-392\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92956923_2535341076689633_8606553121843314688_o-300x126.jpg\" alt=\"\" width=\"300\" height=\"126\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92956923_2535341076689633_8606553121843314688_o-300x126.jpg 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92956923_2535341076689633_8606553121843314688_o-1024x432.jpg 1024w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92956923_2535341076689633_8606553121843314688_o-768x324.jpg 768w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92956923_2535341076689633_8606553121843314688_o-1536x647.jpg 1536w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92956923_2535341076689633_8606553121843314688_o-680x287.jpg 680w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92956923_2535341076689633_8606553121843314688_o.jpg 2005w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-393\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/93113172_2535341120022962_4133107708238757888_o-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/93113172_2535341120022962_4133107708238757888_o-300x200.jpg 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/93113172_2535341120022962_4133107708238757888_o-1024x683.jpg 1024w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/93113172_2535341120022962_4133107708238757888_o-768x512.jpg 768w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/93113172_2535341120022962_4133107708238757888_o-1536x1024.jpg 1536w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/93113172_2535341120022962_4133107708238757888_o-680x453.jpg 680w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/93113172_2535341120022962_4133107708238757888_o.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siamo una grande Citt\u00e0! Lo racconta la nostra storia. Lo dimostreremo vincendo anche questa sfida! Vogliamo salutare l\u2019Italia illuminando con il tricolore le nostre bellezze. Vogliamo testimoniare anche cos\u00ec la [&hellip;]<\/p>\n","protected":false},"author":305,"featured_media":382,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salutiamo l&#039;Italia illuminando con il tricolore le nostre bellezze. Buona Pasqua! - Santa Maria Capua Vetere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salutiamo l&#039;Italia illuminando con il tricolore le nostre bellezze. Buona Pasqua! - Santa Maria Capua Vetere\" \/>\n<meta property=\"og:description\" content=\"Siamo una grande Citt\u00e0! Lo racconta la nostra storia. Lo dimostreremo vincendo anche questa sfida! Vogliamo salutare l\u2019Italia illuminando con il tricolore le nostre bellezze. Vogliamo testimoniare anche cos\u00ec la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria Capua Vetere\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-12T08:46:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92509259_2535341470022927_5804148185962119168_o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1772\" \/>\n\t<meta property=\"og:image:height\" content=\"1181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vinalti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"vinalti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/12\\\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/12\\\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\\\/\"},\"author\":{\"name\":\"vinalti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\"},\"headline\":\"Salutiamo l&#8217;Italia illuminando con il tricolore le nostre bellezze. Buona Pasqua!\",\"datePublished\":\"2020-04-12T08:46:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/12\\\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\\\/\"},\"wordCount\":151,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/12\\\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/04\\\/92509259_2535341470022927_5804148185962119168_o.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/12\\\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/12\\\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\\\/\",\"name\":\"Salutiamo l'Italia illuminando con il tricolore le nostre bellezze. Buona Pasqua! - Santa Maria Capua Vetere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/12\\\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/12\\\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/04\\\/92509259_2535341470022927_5804148185962119168_o.jpg\",\"datePublished\":\"2020-04-12T08:46:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/12\\\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/12\\\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/12\\\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/04\\\/92509259_2535341470022927_5804148185962119168_o.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/04\\\/92509259_2535341470022927_5804148185962119168_o.jpg\",\"width\":1772,\"height\":1181},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/12\\\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salutiamo l&#8217;Italia illuminando con il tricolore le nostre bellezze. Buona Pasqua!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"name\":\"Santa Maria Capua Vetere\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\",\"name\":\"vinalti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"caption\":\"vinalti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/author\\\/vinalti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salutiamo l'Italia illuminando con il tricolore le nostre bellezze. Buona Pasqua! - Santa Maria Capua Vetere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/","og_locale":"it_IT","og_type":"article","og_title":"Salutiamo l'Italia illuminando con il tricolore le nostre bellezze. Buona Pasqua! - Santa Maria Capua Vetere","og_description":"Siamo una grande Citt\u00e0! Lo racconta la nostra storia. Lo dimostreremo vincendo anche questa sfida! Vogliamo salutare l\u2019Italia illuminando con il tricolore le nostre bellezze. Vogliamo testimoniare anche cos\u00ec la [&hellip;]","og_url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/","og_site_name":"Santa Maria Capua Vetere","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-04-12T08:46:35+00:00","og_image":[{"width":1772,"height":1181,"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92509259_2535341470022927_5804148185962119168_o.jpg","type":"image\/jpeg"}],"author":"vinalti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"vinalti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/"},"author":{"name":"vinalti","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78"},"headline":"Salutiamo l&#8217;Italia illuminando con il tricolore le nostre bellezze. Buona Pasqua!","datePublished":"2020-04-12T08:46:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/"},"wordCount":151,"publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92509259_2535341470022927_5804148185962119168_o.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/","name":"Salutiamo l'Italia illuminando con il tricolore le nostre bellezze. Buona Pasqua! - Santa Maria Capua Vetere","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92509259_2535341470022927_5804148185962119168_o.jpg","datePublished":"2020-04-12T08:46:35+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/#primaryimage","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92509259_2535341470022927_5804148185962119168_o.jpg","contentUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/92509259_2535341470022927_5804148185962119168_o.jpg","width":1772,"height":1181},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/12\/salutiamo-litalia-illuminando-con-il-tricolore-le-nostre-bellezze-buona-pasqua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santamariacapuavetere\/"},{"@type":"ListItem","position":2,"name":"Salutiamo l&#8217;Italia illuminando con il tricolore le nostre bellezze. Buona Pasqua!"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","name":"Santa Maria Capua Vetere","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santamariacapuavetere\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78","name":"vinalti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","caption":"vinalti"},"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/author\/vinalti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/comments?post=381"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/381\/revisions"}],"predecessor-version":[{"id":394,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/381\/revisions\/394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media\/382"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media?parent=381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/categories?post=381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/tags?post=381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}