{"id":401,"date":"2020-04-14T17:04:41","date_gmt":"2020-04-14T15:04:41","guid":{"rendered":"https:\/\/comunicacity.net\/santamariacapuavetere\/?p=401"},"modified":"2020-04-14T17:04:41","modified_gmt":"2020-04-14T15:04:41","slug":"emergenza-coronavirus-misure-per-gli-esercizi-commerciali","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/","title":{"rendered":"Emergenza Coronavirus. Misure per gli esercizi commerciali"},"content":{"rendered":"<p>Gli esercizi commerciali la cui attivit\u00e0 non \u00e8 sospesa ai sensi del DPCM del 10 aprile 2020 sono tenuti ad assicurare, oltre alla distanza interpersonale di un metro, che gli ingressi avvengano in modo dilazionato e che venga impedito di sostare all\u2019interno dei locali pi\u00f9 del tempo necessario all\u2019acquisto dei beni.<\/p>\n<p>Si raccomanda inoltre l\u2019applicazione delle ulteriori misure, di cui all&#8217;allegato 5 dello stesso decreto, di seguito elencate:<\/p>\n<ol>\n<li>Mantenimento in tutte le attivit\u00e0 e le loro fasi del distanziamento interpersonale<\/li>\n<li>Garanzia di pulizia e igiene ambientale con frequenza almeno due volte al giorno ed in funzione dell\u2019orario di apertura<\/li>\n<li>Garanzia di adeguata aereazione naturale e ricambio d\u2019aria<\/li>\n<li>Ampia disponibilit\u00e0 e accessibilit\u00e0 a sistemi per la disinfezione delle mani. In particolare, detti sistemi devono essere disponibili accanto a tastiere, schermi touch e sistemi di pagamento<\/li>\n<li>Utilizzo di mascherine nei luoghi o ambienti chiusi e comunque in tutte le possibili fasi lavorative laddove non sia possibile garantire il distanziamento interpersonale<\/li>\n<li>Uso dei guanti (usa e getta) nelle attivit\u00e0 di acquisto, particolarmente per l\u2019acquisto di alimenti e bevande<\/li>\n<li>Accessi regolamentati e scaglionati secondo le seguenti modalit\u00e0: a) Attraverso ampliamenti delle fasce orarie; b) Per locali fino a 40 mq pu\u00f2 accedere una persona alla volta, oltre a un massimo di due operatori; c) Per locali di dimensioni superiori di quelli di cui al punto precedente l\u2019accesso \u00e8 regolamentato in funzione degli spazi disponibili, differenziando, ove possibile, i percorsi di entrata e di uscita<\/li>\n<li>Informazione per garantire il distanziamento dei clienti in attesa di entrata<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Gli esercizi commerciali la cui attivit\u00e0 non \u00e8 sospesa ai sensi del DPCM del 10 aprile 2020 sono tenuti ad assicurare, oltre alla distanza interpersonale di un metro, che gli [&hellip;]<\/p>\n","protected":false},"author":305,"featured_media":368,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Emergenza Coronavirus. Misure per gli esercizi commerciali - Santa Maria Capua Vetere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Emergenza Coronavirus. Misure per gli esercizi commerciali - Santa Maria Capua Vetere\" \/>\n<meta property=\"og:description\" content=\"Gli esercizi commerciali la cui attivit\u00e0 non \u00e8 sospesa ai sensi del DPCM del 10 aprile 2020 sono tenuti ad assicurare, oltre alla distanza interpersonale di un metro, che gli [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria Capua Vetere\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-14T15:04:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/Misure-in-vigore.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"940\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vinalti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"vinalti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/14\\\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/14\\\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\\\/\"},\"author\":{\"name\":\"vinalti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\"},\"headline\":\"Emergenza Coronavirus. Misure per gli esercizi commerciali\",\"datePublished\":\"2020-04-14T15:04:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/14\\\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\\\/\"},\"wordCount\":259,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/14\\\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/04\\\/Misure-in-vigore.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/14\\\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/14\\\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\\\/\",\"name\":\"Emergenza Coronavirus. Misure per gli esercizi commerciali - Santa Maria Capua Vetere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/14\\\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/14\\\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/04\\\/Misure-in-vigore.jpg\",\"datePublished\":\"2020-04-14T15:04:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/14\\\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/14\\\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/14\\\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/04\\\/Misure-in-vigore.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/04\\\/Misure-in-vigore.jpg\",\"width\":940,\"height\":940},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/04\\\/14\\\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Emergenza Coronavirus. Misure per gli esercizi commerciali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"name\":\"Santa Maria Capua Vetere\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\",\"name\":\"vinalti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"caption\":\"vinalti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/author\\\/vinalti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Emergenza Coronavirus. Misure per gli esercizi commerciali - Santa Maria Capua Vetere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/","og_locale":"it_IT","og_type":"article","og_title":"Emergenza Coronavirus. Misure per gli esercizi commerciali - Santa Maria Capua Vetere","og_description":"Gli esercizi commerciali la cui attivit\u00e0 non \u00e8 sospesa ai sensi del DPCM del 10 aprile 2020 sono tenuti ad assicurare, oltre alla distanza interpersonale di un metro, che gli [&hellip;]","og_url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/","og_site_name":"Santa Maria Capua Vetere","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-04-14T15:04:41+00:00","og_image":[{"width":940,"height":940,"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/Misure-in-vigore.jpg","type":"image\/jpeg"}],"author":"vinalti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"vinalti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/"},"author":{"name":"vinalti","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78"},"headline":"Emergenza Coronavirus. Misure per gli esercizi commerciali","datePublished":"2020-04-14T15:04:41+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/"},"wordCount":259,"publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/Misure-in-vigore.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/","name":"Emergenza Coronavirus. Misure per gli esercizi commerciali - Santa Maria Capua Vetere","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/Misure-in-vigore.jpg","datePublished":"2020-04-14T15:04:41+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/#primaryimage","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/Misure-in-vigore.jpg","contentUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/04\/Misure-in-vigore.jpg","width":940,"height":940},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/04\/14\/emergenza-coronavirus-misure-per-gli-esercizi-commerciali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santamariacapuavetere\/"},{"@type":"ListItem","position":2,"name":"Emergenza Coronavirus. Misure per gli esercizi commerciali"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","name":"Santa Maria Capua Vetere","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santamariacapuavetere\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78","name":"vinalti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","caption":"vinalti"},"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/author\/vinalti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/comments?post=401"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/401\/revisions"}],"predecessor-version":[{"id":402,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/401\/revisions\/402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media\/368"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media?parent=401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/categories?post=401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/tags?post=401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}