{"id":474,"date":"2020-05-08T09:29:16","date_gmt":"2020-05-08T07:29:16","guid":{"rendered":"https:\/\/comunicacity.net\/santamariacapuavetere\/?p=474"},"modified":"2020-05-08T09:29:16","modified_gmt":"2020-05-08T07:29:16","slug":"giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/","title":{"rendered":"Giornata Mondiale della Croce Rossa: sventola la bandiera nel nostro Comune"},"content":{"rendered":"<p style=\"background: white;margin: 0cm 0cm 4.5pt 0cm\"><span style=\"color: #1c1e21\">La nostra Citt\u00e0 si tinge di rosso per celebrare gli oltre 150 anni dell\u2019associazione umanitaria pi\u00f9 grande del mondo. <\/span><\/p>\n<p style=\"background: white;margin: 0cm 0cm 4.5pt 0cm\"><span style=\"color: #1c1e21\">Oggi \u00e8 la Giornata Mondiale della Croce Rossa, non ci sar\u00e0 nessuna iniziativa in piazza quest\u2019anno ma non vogliamo far mancare, in questo particolare momento, la nostra vicinanza ai circa 160.000 volontari italiani che, quotidianamente, sono presenti per aiutare chi soffre. <\/span><\/p>\n<p style=\"background: white;margin: 0cm 0cm 4.5pt 0cm\"><span style=\"color: #1c1e21\">La bandiera della Croce Rossa sta sventolando nel nostro Comune; un gesto simbolico per dire \u201cgrazie\u201d e richiamare l\u2019attenzione della cittadinanza a quei principi di altissimo valore sociale che contraddistinguono i volontari sammaritani la cui abnegazione, anche in questo periodo di grande emergenza, \u00e8 stata e continua ad essere encomiabile.<\/span><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-475\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-1-300x300.jpeg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-1-300x300.jpeg 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-1-1024x1024.jpeg 1024w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-1-150x150.jpeg 150w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-1-768x768.jpeg 768w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-1-680x680.jpeg 680w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-1.jpeg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-476\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-300x300.jpeg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-300x300.jpeg 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-1024x1024.jpeg 1024w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-150x150.jpeg 150w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-768x768.jpeg 768w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-680x680.jpeg 680w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03.jpeg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nostra Citt\u00e0 si tinge di rosso per celebrare gli oltre 150 anni dell\u2019associazione umanitaria pi\u00f9 grande del mondo. Oggi \u00e8 la Giornata Mondiale della Croce Rossa, non ci sar\u00e0 [&hellip;]<\/p>\n","protected":false},"author":305,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-474","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giornata Mondiale della Croce Rossa: sventola la bandiera nel nostro Comune - Santa Maria Capua Vetere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giornata Mondiale della Croce Rossa: sventola la bandiera nel nostro Comune - Santa Maria Capua Vetere\" \/>\n<meta property=\"og:description\" content=\"La nostra Citt\u00e0 si tinge di rosso per celebrare gli oltre 150 anni dell\u2019associazione umanitaria pi\u00f9 grande del mondo. Oggi \u00e8 la Giornata Mondiale della Croce Rossa, non ci sar\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria Capua Vetere\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-08T07:29:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-1-300x300.jpeg\" \/>\n<meta name=\"author\" content=\"vinalti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"vinalti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/05\\\/08\\\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/05\\\/08\\\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\\\/\"},\"author\":{\"name\":\"vinalti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\"},\"headline\":\"Giornata Mondiale della Croce Rossa: sventola la bandiera nel nostro Comune\",\"datePublished\":\"2020-05-08T07:29:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/05\\\/08\\\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\\\/\"},\"wordCount\":120,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/05\\\/08\\\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/05\\\/WhatsApp-Image-2020-05-06-at-13.39.03-1-300x300.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/05\\\/08\\\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/05\\\/08\\\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\\\/\",\"name\":\"Giornata Mondiale della Croce Rossa: sventola la bandiera nel nostro Comune - Santa Maria Capua Vetere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/05\\\/08\\\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/05\\\/08\\\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/05\\\/WhatsApp-Image-2020-05-06-at-13.39.03-1-300x300.jpeg\",\"datePublished\":\"2020-05-08T07:29:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/05\\\/08\\\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/05\\\/08\\\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/05\\\/08\\\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\\\/#primaryimage\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/05\\\/WhatsApp-Image-2020-05-06-at-13.39.03-1-300x300.jpeg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/05\\\/WhatsApp-Image-2020-05-06-at-13.39.03-1-300x300.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/05\\\/08\\\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giornata Mondiale della Croce Rossa: sventola la bandiera nel nostro Comune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"name\":\"Santa Maria Capua Vetere\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\",\"name\":\"vinalti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"caption\":\"vinalti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/author\\\/vinalti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giornata Mondiale della Croce Rossa: sventola la bandiera nel nostro Comune - Santa Maria Capua Vetere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/","og_locale":"it_IT","og_type":"article","og_title":"Giornata Mondiale della Croce Rossa: sventola la bandiera nel nostro Comune - Santa Maria Capua Vetere","og_description":"La nostra Citt\u00e0 si tinge di rosso per celebrare gli oltre 150 anni dell\u2019associazione umanitaria pi\u00f9 grande del mondo. Oggi \u00e8 la Giornata Mondiale della Croce Rossa, non ci sar\u00e0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/","og_site_name":"Santa Maria Capua Vetere","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-05-08T07:29:16+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-1-300x300.jpeg","type":"","width":"","height":""}],"author":"vinalti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"vinalti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/"},"author":{"name":"vinalti","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78"},"headline":"Giornata Mondiale della Croce Rossa: sventola la bandiera nel nostro Comune","datePublished":"2020-05-08T07:29:16+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/"},"wordCount":120,"publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-1-300x300.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/","name":"Giornata Mondiale della Croce Rossa: sventola la bandiera nel nostro Comune - Santa Maria Capua Vetere","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-1-300x300.jpeg","datePublished":"2020-05-08T07:29:16+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/#primaryimage","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-1-300x300.jpeg","contentUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/05\/WhatsApp-Image-2020-05-06-at-13.39.03-1-300x300.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/05\/08\/giornata-mondiale-della-croce-rossa-sventola-la-bandiera-nel-nostro-comune\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santamariacapuavetere\/"},{"@type":"ListItem","position":2,"name":"Giornata Mondiale della Croce Rossa: sventola la bandiera nel nostro Comune"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","name":"Santa Maria Capua Vetere","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santamariacapuavetere\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78","name":"vinalti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","caption":"vinalti"},"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/author\/vinalti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/comments?post=474"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/474\/revisions"}],"predecessor-version":[{"id":477,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/474\/revisions\/477"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media?parent=474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/categories?post=474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/tags?post=474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}