{"id":501,"date":"2020-06-10T09:58:31","date_gmt":"2020-06-10T07:58:31","guid":{"rendered":"https:\/\/comunicacity.net\/santamariacapuavetere\/?p=501"},"modified":"2020-06-10T09:58:31","modified_gmt":"2020-06-10T07:58:31","slug":"edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/06\/10\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\/","title":{"rendered":"Edilizia Residenziale Pubblica, prorogati i termini per le istanze di regolarizzazione. SCARICA QUI IL MODULO"},"content":{"rendered":"<p>Nell\u2019ambito di un pi\u00f9 ampio iter volto al rilancio delle politiche abitative, avviato gi\u00e0 lo scorso mese di novembre dall\u2019amministrazione Mirra con lo schema di convenzione che prevede il passaggio dal diritto di superficie al diritto di propriet\u00e0 per tutti gli assegnatari di abitazioni realizzate per l\u2019edilizia economica e popolare, l\u2019organo esecutivo di Palazzo Lucarelli con l\u2019assessore al ramo Francesco Petrella ha approvato adesso una delibera di giunta che, recependo le rinnovate linee guida della Regione Campania in seguito all\u2019emergenza sanitaria da Covid-19, modifica i termini per la presentazione delle istanze di regolarizzazione da parte dei nuclei familiari che occupino senza titolo legittimo gli alloggi di Edilizia Residenziale Pubblica.<\/p>\n<p>Il nuovo termine per la presentazione delle istanze \u00e8 fissato al 20 luglio 2020.<\/p>\n<p><strong>Il modulo \u00e8 allegato a questa nota\u00a0<\/strong><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_502\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/06\/istanza-allegato.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/06\/istanza-allegato.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Istanza di regolarizzazione<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nell\u2019ambito di un pi\u00f9 ampio iter volto al rilancio delle politiche abitative, avviato gi\u00e0 lo scorso mese di novembre dall\u2019amministrazione Mirra con lo schema di convenzione che prevede il passaggio [&hellip;]<\/p>\n","protected":false},"author":305,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-501","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Edilizia Residenziale Pubblica, prorogati i termini per le istanze di regolarizzazione. SCARICA QUI IL MODULO - Santa Maria Capua Vetere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/06\/10\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Edilizia Residenziale Pubblica, prorogati i termini per le istanze di regolarizzazione. SCARICA QUI IL MODULO - Santa Maria Capua Vetere\" \/>\n<meta property=\"og:description\" content=\"Nell\u2019ambito di un pi\u00f9 ampio iter volto al rilancio delle politiche abitative, avviato gi\u00e0 lo scorso mese di novembre dall\u2019amministrazione Mirra con lo schema di convenzione che prevede il passaggio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/06\/10\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria Capua Vetere\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-10T07:58:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"vinalti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"vinalti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/06\\\/10\\\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/06\\\/10\\\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\\\/\"},\"author\":{\"name\":\"vinalti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\"},\"headline\":\"Edilizia Residenziale Pubblica, prorogati i termini per le istanze di regolarizzazione. SCARICA QUI IL MODULO\",\"datePublished\":\"2020-06-10T07:58:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/06\\\/10\\\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\\\/\"},\"wordCount\":147,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/06\\\/10\\\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/06\\\/10\\\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\\\/\",\"name\":\"Edilizia Residenziale Pubblica, prorogati i termini per le istanze di regolarizzazione. SCARICA QUI IL MODULO - Santa Maria Capua Vetere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\"},\"datePublished\":\"2020-06-10T07:58:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/06\\\/10\\\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/06\\\/10\\\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/06\\\/10\\\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Edilizia Residenziale Pubblica, prorogati i termini per le istanze di regolarizzazione. SCARICA QUI IL MODULO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"name\":\"Santa Maria Capua Vetere\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\",\"name\":\"vinalti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"caption\":\"vinalti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/author\\\/vinalti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Edilizia Residenziale Pubblica, prorogati i termini per le istanze di regolarizzazione. SCARICA QUI IL MODULO - Santa Maria Capua Vetere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/06\/10\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\/","og_locale":"it_IT","og_type":"article","og_title":"Edilizia Residenziale Pubblica, prorogati i termini per le istanze di regolarizzazione. SCARICA QUI IL MODULO - Santa Maria Capua Vetere","og_description":"Nell\u2019ambito di un pi\u00f9 ampio iter volto al rilancio delle politiche abitative, avviato gi\u00e0 lo scorso mese di novembre dall\u2019amministrazione Mirra con lo schema di convenzione che prevede il passaggio [&hellip;]","og_url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/06\/10\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\/","og_site_name":"Santa Maria Capua Vetere","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-06-10T07:58:31+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"vinalti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"vinalti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/06\/10\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/06\/10\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\/"},"author":{"name":"vinalti","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78"},"headline":"Edilizia Residenziale Pubblica, prorogati i termini per le istanze di regolarizzazione. SCARICA QUI IL MODULO","datePublished":"2020-06-10T07:58:31+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/06\/10\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\/"},"wordCount":147,"publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/06\/10\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\/","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/06\/10\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\/","name":"Edilizia Residenziale Pubblica, prorogati i termini per le istanze di regolarizzazione. SCARICA QUI IL MODULO - Santa Maria Capua Vetere","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website"},"datePublished":"2020-06-10T07:58:31+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/06\/10\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/06\/10\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/06\/10\/edilizia-residenziale-pubblica-prorogati-i-termini-per-le-istanze-di-regolarizzazione-scarica-qui-il-modulo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santamariacapuavetere\/"},{"@type":"ListItem","position":2,"name":"Edilizia Residenziale Pubblica, prorogati i termini per le istanze di regolarizzazione. SCARICA QUI IL MODULO"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","name":"Santa Maria Capua Vetere","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santamariacapuavetere\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78","name":"vinalti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","caption":"vinalti"},"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/author\/vinalti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/comments?post=501"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/501\/revisions"}],"predecessor-version":[{"id":503,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/501\/revisions\/503"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media?parent=501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/categories?post=501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/tags?post=501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}