{"id":640,"date":"2020-10-22T13:37:30","date_gmt":"2020-10-22T11:37:30","guid":{"rendered":"https:\/\/comunicacity.net\/santamariacapuavetere\/?p=640"},"modified":"2020-10-22T13:37:30","modified_gmt":"2020-10-22T11:37:30","slug":"aggiornamento-covid-del-22-ottobre-2020","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/","title":{"rendered":"Aggiornamento Covid del 22 ottobre 2020"},"content":{"rendered":"<p>Sulla base dell\u2019ultimo rapporto trasmesso dall\u2019Asl, risultano 72 cittadini attualmente positivi.<\/p>\n<p>Da verifiche effettuate dal Sindaco Antonio Mirra e dal Centro Operativo Comunale risultano, da questo stesso elenco, gi\u00e0 10 cittadini guariti.<\/p>\n<p>Si resta per\u00f2 in attesa della comunicazione degli esami a cui si sono sottoposti diversi cittadini presso i laboratori privati.<\/p>\n<p>Sabato mattina aggiornamento video con il Sindaco Antonio Mirra rispetto alla situazione delle scuole, alle nuove misure e al cimitero comunale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sulla base dell\u2019ultimo rapporto trasmesso dall\u2019Asl, risultano 72 cittadini attualmente positivi. Da verifiche effettuate dal Sindaco Antonio Mirra e dal Centro Operativo Comunale risultano, da questo stesso elenco, gi\u00e0 10 [&hellip;]<\/p>\n","protected":false},"author":305,"featured_media":641,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aggiornamento Covid del 22 ottobre 2020 - Santa Maria Capua Vetere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aggiornamento Covid del 22 ottobre 2020 - Santa Maria Capua Vetere\" \/>\n<meta property=\"og:description\" content=\"Sulla base dell\u2019ultimo rapporto trasmesso dall\u2019Asl, risultano 72 cittadini attualmente positivi. Da verifiche effettuate dal Sindaco Antonio Mirra e dal Centro Operativo Comunale risultano, da questo stesso elenco, gi\u00e0 10 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria Capua Vetere\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-22T11:37:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/10\/22.10-Aggiornamento-Covid.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vinalti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"vinalti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/10\\\/22\\\/aggiornamento-covid-del-22-ottobre-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/10\\\/22\\\/aggiornamento-covid-del-22-ottobre-2020\\\/\"},\"author\":{\"name\":\"vinalti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\"},\"headline\":\"Aggiornamento Covid del 22 ottobre 2020\",\"datePublished\":\"2020-10-22T11:37:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/10\\\/22\\\/aggiornamento-covid-del-22-ottobre-2020\\\/\"},\"wordCount\":77,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/10\\\/22\\\/aggiornamento-covid-del-22-ottobre-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/10\\\/22.10-Aggiornamento-Covid.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/10\\\/22\\\/aggiornamento-covid-del-22-ottobre-2020\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/10\\\/22\\\/aggiornamento-covid-del-22-ottobre-2020\\\/\",\"name\":\"Aggiornamento Covid del 22 ottobre 2020 - Santa Maria Capua Vetere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/10\\\/22\\\/aggiornamento-covid-del-22-ottobre-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/10\\\/22\\\/aggiornamento-covid-del-22-ottobre-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/10\\\/22.10-Aggiornamento-Covid.jpg\",\"datePublished\":\"2020-10-22T11:37:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/10\\\/22\\\/aggiornamento-covid-del-22-ottobre-2020\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/10\\\/22\\\/aggiornamento-covid-del-22-ottobre-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/10\\\/22\\\/aggiornamento-covid-del-22-ottobre-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/10\\\/22.10-Aggiornamento-Covid.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2020\\\/10\\\/22.10-Aggiornamento-Covid.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2020\\\/10\\\/22\\\/aggiornamento-covid-del-22-ottobre-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aggiornamento Covid del 22 ottobre 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"name\":\"Santa Maria Capua Vetere\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\",\"name\":\"vinalti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"caption\":\"vinalti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/author\\\/vinalti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aggiornamento Covid del 22 ottobre 2020 - Santa Maria Capua Vetere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/","og_locale":"it_IT","og_type":"article","og_title":"Aggiornamento Covid del 22 ottobre 2020 - Santa Maria Capua Vetere","og_description":"Sulla base dell\u2019ultimo rapporto trasmesso dall\u2019Asl, risultano 72 cittadini attualmente positivi. Da verifiche effettuate dal Sindaco Antonio Mirra e dal Centro Operativo Comunale risultano, da questo stesso elenco, gi\u00e0 10 [&hellip;]","og_url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/","og_site_name":"Santa Maria Capua Vetere","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-10-22T11:37:30+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/10\/22.10-Aggiornamento-Covid.jpg","type":"image\/jpeg"}],"author":"vinalti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"vinalti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/"},"author":{"name":"vinalti","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78"},"headline":"Aggiornamento Covid del 22 ottobre 2020","datePublished":"2020-10-22T11:37:30+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/"},"wordCount":77,"publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/10\/22.10-Aggiornamento-Covid.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/","name":"Aggiornamento Covid del 22 ottobre 2020 - Santa Maria Capua Vetere","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/10\/22.10-Aggiornamento-Covid.jpg","datePublished":"2020-10-22T11:37:30+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/#primaryimage","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/10\/22.10-Aggiornamento-Covid.jpg","contentUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2020\/10\/22.10-Aggiornamento-Covid.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2020\/10\/22\/aggiornamento-covid-del-22-ottobre-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santamariacapuavetere\/"},{"@type":"ListItem","position":2,"name":"Aggiornamento Covid del 22 ottobre 2020"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","name":"Santa Maria Capua Vetere","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santamariacapuavetere\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78","name":"vinalti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","caption":"vinalti"},"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/author\/vinalti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/comments?post=640"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/640\/revisions"}],"predecessor-version":[{"id":642,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/640\/revisions\/642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media\/641"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media?parent=640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/categories?post=640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/tags?post=640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}