{"id":797,"date":"2021-03-03T11:21:11","date_gmt":"2021-03-03T10:21:11","guid":{"rendered":"https:\/\/comunicacity.net\/santamariacapuavetere\/?p=797"},"modified":"2021-03-03T11:21:11","modified_gmt":"2021-03-03T10:21:11","slug":"avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/03\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\/","title":{"rendered":"Avviso alla cittadinanza | Lavori alla rete idrica: via Brennero e via Generoso Iodice"},"content":{"rendered":"<p>A causa di un improvviso guasto alla rete idrica, nel tratto di via Brennero e via Generoso Iodice con annesse traverse, \u00e8 attualmente in corso un intervento di riparazione.<\/p>\n<p>Per tali motivi \u00e8 prevista la riduzione della pressione in via Brennero e la sospensione dell\u2019erogazione, per l\u2019intera durata dell\u2019intervento, in via Generoso Iodice e traverse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A causa di un improvviso guasto alla rete idrica, nel tratto di via Brennero e via Generoso Iodice con annesse traverse, \u00e8 attualmente in corso un intervento di riparazione. Per [&hellip;]<\/p>\n","protected":false},"author":305,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-797","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso alla cittadinanza | Lavori alla rete idrica: via Brennero e via Generoso Iodice - Santa Maria Capua Vetere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/03\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso alla cittadinanza | Lavori alla rete idrica: via Brennero e via Generoso Iodice - Santa Maria Capua Vetere\" \/>\n<meta property=\"og:description\" content=\"A causa di un improvviso guasto alla rete idrica, nel tratto di via Brennero e via Generoso Iodice con annesse traverse, \u00e8 attualmente in corso un intervento di riparazione. Per [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/03\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria Capua Vetere\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-03T10:21:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"vinalti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"vinalti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/03\\\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/03\\\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\\\/\"},\"author\":{\"name\":\"vinalti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\"},\"headline\":\"Avviso alla cittadinanza | Lavori alla rete idrica: via Brennero e via Generoso Iodice\",\"datePublished\":\"2021-03-03T10:21:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/03\\\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\\\/\"},\"wordCount\":69,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/03\\\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/03\\\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\\\/\",\"name\":\"Avviso alla cittadinanza | Lavori alla rete idrica: via Brennero e via Generoso Iodice - Santa Maria Capua Vetere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\"},\"datePublished\":\"2021-03-03T10:21:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/03\\\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/03\\\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/03\\\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso alla cittadinanza | Lavori alla rete idrica: via Brennero e via Generoso Iodice\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"name\":\"Santa Maria Capua Vetere\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\",\"name\":\"vinalti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"caption\":\"vinalti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/author\\\/vinalti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso alla cittadinanza | Lavori alla rete idrica: via Brennero e via Generoso Iodice - Santa Maria Capua Vetere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/03\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso alla cittadinanza | Lavori alla rete idrica: via Brennero e via Generoso Iodice - Santa Maria Capua Vetere","og_description":"A causa di un improvviso guasto alla rete idrica, nel tratto di via Brennero e via Generoso Iodice con annesse traverse, \u00e8 attualmente in corso un intervento di riparazione. Per [&hellip;]","og_url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/03\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\/","og_site_name":"Santa Maria Capua Vetere","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-03-03T10:21:11+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"vinalti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"vinalti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/03\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/03\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\/"},"author":{"name":"vinalti","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78"},"headline":"Avviso alla cittadinanza | Lavori alla rete idrica: via Brennero e via Generoso Iodice","datePublished":"2021-03-03T10:21:11+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/03\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\/"},"wordCount":69,"publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/03\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\/","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/03\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\/","name":"Avviso alla cittadinanza | Lavori alla rete idrica: via Brennero e via Generoso Iodice - Santa Maria Capua Vetere","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website"},"datePublished":"2021-03-03T10:21:11+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/03\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/03\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/03\/avviso-alla-cittadinanza-lavori-alla-rete-idrica-via-brennero-e-via-generoso-iodice\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santamariacapuavetere\/"},{"@type":"ListItem","position":2,"name":"Avviso alla cittadinanza | Lavori alla rete idrica: via Brennero e via Generoso Iodice"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","name":"Santa Maria Capua Vetere","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santamariacapuavetere\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78","name":"vinalti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","caption":"vinalti"},"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/author\/vinalti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/comments?post=797"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/797\/revisions"}],"predecessor-version":[{"id":798,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/797\/revisions\/798"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media?parent=797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/categories?post=797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/tags?post=797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}