{"id":863,"date":"2021-03-26T13:00:53","date_gmt":"2021-03-26T12:00:53","guid":{"rendered":"https:\/\/comunicacity.net\/santamariacapuavetere\/?p=863"},"modified":"2021-03-26T13:00:53","modified_gmt":"2021-03-26T12:00:53","slug":"ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/","title":{"rendered":"Ordinanza 51 del Sindaco Mirra. Riapertura controllata delle attivit\u00e0 mercatali limitatamente al settore alimentare"},"content":{"rendered":"<p>In ottemperanza all\u2019Ordinanza 11 del Presidente De Luca e alla luce dell&#8217;attuale situazione in citt\u00e0 con il doppio indice del sistema di alert dell&#8217;Unit\u00e0 di Crisi &#8220;sotto soglia&#8221; rispetto a quello regionale, il Sindaco Antonio Mirra ha disposto, fino al 5 aprile, lo svolgimento della fiera bisettimanale di via Righi, limitatamente al settore alimentare e subordinatamente al rigoroso rispetto del seguente Protocollo di Sicurezza:<\/p>\n<ol>\n<li>L\u2019accesso all\u2019area mercatale \u00e8 cos\u00ec regolato:<\/li>\n<\/ol>\n<ul>\n<li>Operatori concessionari: dalle 6.00 alle 6.30 da via Santella<\/li>\n<li>Operatori spuntisti: dalle 6.30 alle 7.00 da via Santella<\/li>\n<li>Clienti: dalle 7.00 alle 13.00 da via Santella e via Righi<\/li>\n<\/ul>\n<ol start=\"2\">\n<li>Il percorso dar\u00e0 bidirezionale con entrata ed uscita da via Santella e da via Righi, con priorit\u00e0 di accesso ai diversamente abili e alle donne in stato di gravidanza<\/li>\n<li>Il posizionamento dei singoli operatori dovr\u00e0 rispettare il distanziamento evidenziato tra gli stessi con specifica segnaletica orizzontale di colore bianco<\/li>\n<li>Agli operatori il divieto di somministrazione, in modalit\u00e0 self-service, di prodotti non confezionati fermo restando l\u2019uso obbligatorio di guanti e mascherine<\/li>\n<li>Considerata la dimensione dell\u2019area, \u00e8 prevista la possibilit\u00e0 di accesso contemporaneo fino a 300 persone<\/li>\n<li>Gli operatori dovranno attenersi rigorosamente agli obblighi previsti dalle Linee Guida della Regione Campania<\/li>\n<li>E\u2019 fatto divieto di fumare nell\u2019area citata, stante l\u2019obbligo della mascherina<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>In ottemperanza all\u2019Ordinanza 11 del Presidente De Luca e alla luce dell&#8217;attuale situazione in citt\u00e0 con il doppio indice del sistema di alert dell&#8217;Unit\u00e0 di Crisi &#8220;sotto soglia&#8221; rispetto a [&hellip;]<\/p>\n","protected":false},"author":305,"featured_media":864,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ordinanza 51 del Sindaco Mirra. Riapertura controllata delle attivit\u00e0 mercatali limitatamente al settore alimentare - Santa Maria Capua Vetere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ordinanza 51 del Sindaco Mirra. Riapertura controllata delle attivit\u00e0 mercatali limitatamente al settore alimentare - Santa Maria Capua Vetere\" \/>\n<meta property=\"og:description\" content=\"In ottemperanza all\u2019Ordinanza 11 del Presidente De Luca e alla luce dell&#8217;attuale situazione in citt\u00e0 con il doppio indice del sistema di alert dell&#8217;Unit\u00e0 di Crisi &#8220;sotto soglia&#8221; rispetto a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria Capua Vetere\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-26T12:00:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/26.03-Mercato.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"vinalti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"vinalti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/26\\\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/26\\\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\\\/\"},\"author\":{\"name\":\"vinalti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\"},\"headline\":\"Ordinanza 51 del Sindaco Mirra. Riapertura controllata delle attivit\u00e0 mercatali limitatamente al settore alimentare\",\"datePublished\":\"2021-03-26T12:00:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/26\\\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\\\/\"},\"wordCount\":218,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/26\\\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2021\\\/03\\\/26.03-Mercato.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/26\\\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/26\\\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\\\/\",\"name\":\"Ordinanza 51 del Sindaco Mirra. Riapertura controllata delle attivit\u00e0 mercatali limitatamente al settore alimentare - Santa Maria Capua Vetere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/26\\\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/26\\\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2021\\\/03\\\/26.03-Mercato.png\",\"datePublished\":\"2021-03-26T12:00:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/26\\\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/26\\\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/26\\\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2021\\\/03\\\/26.03-Mercato.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2021\\\/03\\\/26.03-Mercato.png\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/26\\\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ordinanza 51 del Sindaco Mirra. Riapertura controllata delle attivit\u00e0 mercatali limitatamente al settore alimentare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"name\":\"Santa Maria Capua Vetere\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\",\"name\":\"vinalti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"caption\":\"vinalti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/author\\\/vinalti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ordinanza 51 del Sindaco Mirra. Riapertura controllata delle attivit\u00e0 mercatali limitatamente al settore alimentare - Santa Maria Capua Vetere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/","og_locale":"it_IT","og_type":"article","og_title":"Ordinanza 51 del Sindaco Mirra. Riapertura controllata delle attivit\u00e0 mercatali limitatamente al settore alimentare - Santa Maria Capua Vetere","og_description":"In ottemperanza all\u2019Ordinanza 11 del Presidente De Luca e alla luce dell&#8217;attuale situazione in citt\u00e0 con il doppio indice del sistema di alert dell&#8217;Unit\u00e0 di Crisi &#8220;sotto soglia&#8221; rispetto a [&hellip;]","og_url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/","og_site_name":"Santa Maria Capua Vetere","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-03-26T12:00:53+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/26.03-Mercato.png","type":"image\/png"}],"author":"vinalti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"vinalti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/"},"author":{"name":"vinalti","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78"},"headline":"Ordinanza 51 del Sindaco Mirra. Riapertura controllata delle attivit\u00e0 mercatali limitatamente al settore alimentare","datePublished":"2021-03-26T12:00:53+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/"},"wordCount":218,"publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/26.03-Mercato.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/","name":"Ordinanza 51 del Sindaco Mirra. Riapertura controllata delle attivit\u00e0 mercatali limitatamente al settore alimentare - Santa Maria Capua Vetere","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/26.03-Mercato.png","datePublished":"2021-03-26T12:00:53+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/#primaryimage","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/26.03-Mercato.png","contentUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/26.03-Mercato.png","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/26\/ordinanza-51-del-sindaco-mirra-riapertura-controllata-delle-attivita-mercatali-limitatamente-al-settore-alimentare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santamariacapuavetere\/"},{"@type":"ListItem","position":2,"name":"Ordinanza 51 del Sindaco Mirra. Riapertura controllata delle attivit\u00e0 mercatali limitatamente al settore alimentare"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","name":"Santa Maria Capua Vetere","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santamariacapuavetere\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78","name":"vinalti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","caption":"vinalti"},"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/author\/vinalti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/comments?post=863"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/863\/revisions"}],"predecessor-version":[{"id":865,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/863\/revisions\/865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media\/864"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media?parent=863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/categories?post=863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/tags?post=863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}