{"id":868,"date":"2021-03-30T12:59:35","date_gmt":"2021-03-30T10:59:35","guid":{"rendered":"https:\/\/comunicacity.net\/santamariacapuavetere\/?p=868"},"modified":"2021-03-30T12:59:35","modified_gmt":"2021-03-30T10:59:35","slug":"aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/","title":{"rendered":"Aggiornamento Covid &#8211; Indici del sistema di alert dell&#8217;Unit\u00e0 di Crisi"},"content":{"rendered":"<p>La situazione in Citt\u00e0 all\u2019ultimo report del sistema di alert dell\u2019Unit\u00e0 di Crisi regionale relativo alla settimana 22 \u2013 28 marzo 2021<\/p>\n<p>Per la seconda settimana consecutiva la nostra Citt\u00e0 \u00e8 al di sotto di entrambi gli indici regionali: la percentuale di nuovi positivi sui tamponi effettuati (10,02% rispetto a 10,59% regionale); il tasso di incidenza (194,11 contro 233,85 regionale) che consiste nel rapporto tra nuovi positivi in 7 giorni con il numero di abitanti. Ad oggi gli attuali positivi sono 218.<\/p>\n<p>63 \u00e8 il numero dei positivi nella settimana 22 \u2013 28 marzo; in discesa rispetto alle precedenti settimane (90 positivi nella settimana 8 \u2013 14 marzo; 69 positivi nella settimana 15 \u2013 21 marzo) ma comunque ancora alto considerato che la media \u00e8 di 9 positivi al giorno.<\/p>\n<p>Fasce d\u2019et\u00e0 con il maggior numero di positivi nella settimana 22 \u2013 28 marzo:<\/p>\n<ul>\n<li>50\/64 anni: 16 positivi<\/li>\n<li>27\/35 anni: 9 positivi<\/li>\n<li>36\/49 anni: 7 positivi<\/li>\n<li>19\/26 anni: 6 positivi<\/li>\n<li>14\/18 anni: 5 positivi<\/li>\n<li>65\/80 anni: 4 positivi<\/li>\n<li>81 a salire: 4 positivi<\/li>\n<li>11\/13 anni: 3 positivi<\/li>\n<li>6\/10 anni: 2 positivi<\/li>\n<li>0\/5 anni: 2 positivi<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-870\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/8-2.png\" alt=\"\" width=\"640\" height=\"537\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/8-2.png 940w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/8-2-300x251.png 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/8-2-768x644.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-871\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/9-2.png\" alt=\"\" width=\"640\" height=\"537\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/9-2.png 940w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/9-2-300x251.png 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/9-2-768x644.png 768w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La situazione in Citt\u00e0 all\u2019ultimo report del sistema di alert dell\u2019Unit\u00e0 di Crisi regionale relativo alla settimana 22 \u2013 28 marzo 2021 Per la seconda settimana consecutiva la nostra Citt\u00e0 [&hellip;]<\/p>\n","protected":false},"author":305,"featured_media":869,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aggiornamento Covid - Indici del sistema di alert dell&#039;Unit\u00e0 di Crisi - Santa Maria Capua Vetere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aggiornamento Covid - Indici del sistema di alert dell&#039;Unit\u00e0 di Crisi - Santa Maria Capua Vetere\" \/>\n<meta property=\"og:description\" content=\"La situazione in Citt\u00e0 all\u2019ultimo report del sistema di alert dell\u2019Unit\u00e0 di Crisi regionale relativo alla settimana 22 \u2013 28 marzo 2021 Per la seconda settimana consecutiva la nostra Citt\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria Capua Vetere\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-30T10:59:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/7-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"vinalti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"vinalti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/30\\\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/30\\\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\\\/\"},\"author\":{\"name\":\"vinalti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\"},\"headline\":\"Aggiornamento Covid &#8211; Indici del sistema di alert dell&#8217;Unit\u00e0 di Crisi\",\"datePublished\":\"2021-03-30T10:59:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/30\\\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\\\/\"},\"wordCount\":150,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/30\\\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2021\\\/03\\\/7-3.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/30\\\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/30\\\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\\\/\",\"name\":\"Aggiornamento Covid - Indici del sistema di alert dell'Unit\u00e0 di Crisi - Santa Maria Capua Vetere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/30\\\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/30\\\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2021\\\/03\\\/7-3.png\",\"datePublished\":\"2021-03-30T10:59:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/30\\\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/30\\\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/30\\\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2021\\\/03\\\/7-3.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2021\\\/03\\\/7-3.png\",\"width\":940,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/03\\\/30\\\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aggiornamento Covid &#8211; Indici del sistema di alert dell&#8217;Unit\u00e0 di Crisi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"name\":\"Santa Maria Capua Vetere\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\",\"name\":\"vinalti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"caption\":\"vinalti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/author\\\/vinalti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aggiornamento Covid - Indici del sistema di alert dell'Unit\u00e0 di Crisi - Santa Maria Capua Vetere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/","og_locale":"it_IT","og_type":"article","og_title":"Aggiornamento Covid - Indici del sistema di alert dell'Unit\u00e0 di Crisi - Santa Maria Capua Vetere","og_description":"La situazione in Citt\u00e0 all\u2019ultimo report del sistema di alert dell\u2019Unit\u00e0 di Crisi regionale relativo alla settimana 22 \u2013 28 marzo 2021 Per la seconda settimana consecutiva la nostra Citt\u00e0 [&hellip;]","og_url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/","og_site_name":"Santa Maria Capua Vetere","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-03-30T10:59:35+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/7-3.png","type":"image\/png"}],"author":"vinalti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"vinalti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/"},"author":{"name":"vinalti","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78"},"headline":"Aggiornamento Covid &#8211; Indici del sistema di alert dell&#8217;Unit\u00e0 di Crisi","datePublished":"2021-03-30T10:59:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/"},"wordCount":150,"publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/7-3.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/","name":"Aggiornamento Covid - Indici del sistema di alert dell'Unit\u00e0 di Crisi - Santa Maria Capua Vetere","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/7-3.png","datePublished":"2021-03-30T10:59:35+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/#primaryimage","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/7-3.png","contentUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/03\/7-3.png","width":940,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/03\/30\/aggiornamento-covid-indici-del-sistema-di-alert-dellunita-di-crisi-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santamariacapuavetere\/"},{"@type":"ListItem","position":2,"name":"Aggiornamento Covid &#8211; Indici del sistema di alert dell&#8217;Unit\u00e0 di Crisi"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","name":"Santa Maria Capua Vetere","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santamariacapuavetere\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78","name":"vinalti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","caption":"vinalti"},"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/author\/vinalti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/comments?post=868"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/868\/revisions"}],"predecessor-version":[{"id":872,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/868\/revisions\/872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media\/869"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media?parent=868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/categories?post=868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/tags?post=868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}