{"id":910,"date":"2021-04-26T13:09:26","date_gmt":"2021-04-26T11:09:26","guid":{"rendered":"https:\/\/comunicacity.net\/santamariacapuavetere\/?p=910"},"modified":"2021-04-26T13:09:26","modified_gmt":"2021-04-26T11:09:26","slug":"calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\/","title":{"rendered":"Calendario disinfezione e sanificazione: da oggi gli interventi. In allegato l&#8217;elenco delle strade"},"content":{"rendered":"<p>Si informa la cittadinanza che da oggi, 26 aprile, verranno effettuati interventi di disinfezione e sanificazione delle strade cittadine.<\/p>\n<p>Il territorio \u00e8 stato ripartito in quattro zone (A &#8211; B &#8211; C &#8211; D).<\/p>\n<p>Il primo intervento parte questa sera (26 aprile) alle ore 20.30 nella <strong>Zona D<\/strong>.<\/p>\n<p>A seguire:<\/p>\n<ul>\n<li>27 aprile: <strong>Zona A<\/strong><\/li>\n<li>28 aprile: <strong>Zona C<\/strong><\/li>\n<li>29 aprile: <strong>Zona B<\/strong><\/li>\n<\/ul>\n<p><strong>In allegato il calendario dettagliato con i nomi delle strade suddivise per zone.<\/strong><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_911\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/04\/Calendario-Sanificazione.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/04\/Calendario-Sanificazione.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Calendario Disinfezione e Sanificazione<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si informa la cittadinanza che da oggi, 26 aprile, verranno effettuati interventi di disinfezione e sanificazione delle strade cittadine. Il territorio \u00e8 stato ripartito in quattro zone (A &#8211; B [&hellip;]<\/p>\n","protected":false},"author":305,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-910","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Calendario disinfezione e sanificazione: da oggi gli interventi. In allegato l&#039;elenco delle strade - Santa Maria Capua Vetere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Calendario disinfezione e sanificazione: da oggi gli interventi. In allegato l&#039;elenco delle strade - Santa Maria Capua Vetere\" \/>\n<meta property=\"og:description\" content=\"Si informa la cittadinanza che da oggi, 26 aprile, verranno effettuati interventi di disinfezione e sanificazione delle strade cittadine. Il territorio \u00e8 stato ripartito in quattro zone (A &#8211; B [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria Capua Vetere\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-26T11:09:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"vinalti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"vinalti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\\\/\"},\"author\":{\"name\":\"vinalti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\"},\"headline\":\"Calendario disinfezione e sanificazione: da oggi gli interventi. In allegato l&#8217;elenco delle strade\",\"datePublished\":\"2021-04-26T11:09:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\\\/\"},\"wordCount\":81,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\\\/\",\"name\":\"Calendario disinfezione e sanificazione: da oggi gli interventi. In allegato l'elenco delle strade - Santa Maria Capua Vetere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\"},\"datePublished\":\"2021-04-26T11:09:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Calendario disinfezione e sanificazione: da oggi gli interventi. In allegato l&#8217;elenco delle strade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"name\":\"Santa Maria Capua Vetere\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\",\"name\":\"vinalti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"caption\":\"vinalti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/author\\\/vinalti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Calendario disinfezione e sanificazione: da oggi gli interventi. In allegato l'elenco delle strade - Santa Maria Capua Vetere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\/","og_locale":"it_IT","og_type":"article","og_title":"Calendario disinfezione e sanificazione: da oggi gli interventi. In allegato l'elenco delle strade - Santa Maria Capua Vetere","og_description":"Si informa la cittadinanza che da oggi, 26 aprile, verranno effettuati interventi di disinfezione e sanificazione delle strade cittadine. Il territorio \u00e8 stato ripartito in quattro zone (A &#8211; B [&hellip;]","og_url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\/","og_site_name":"Santa Maria Capua Vetere","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-04-26T11:09:26+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"vinalti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"vinalti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\/"},"author":{"name":"vinalti","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78"},"headline":"Calendario disinfezione e sanificazione: da oggi gli interventi. In allegato l&#8217;elenco delle strade","datePublished":"2021-04-26T11:09:26+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\/"},"wordCount":81,"publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\/","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\/","name":"Calendario disinfezione e sanificazione: da oggi gli interventi. In allegato l'elenco delle strade - Santa Maria Capua Vetere","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website"},"datePublished":"2021-04-26T11:09:26+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/calendario-disinfezione-e-sanificazione-da-oggi-gli-interventi-in-allegato-lelenco-delle-strade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santamariacapuavetere\/"},{"@type":"ListItem","position":2,"name":"Calendario disinfezione e sanificazione: da oggi gli interventi. In allegato l&#8217;elenco delle strade"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","name":"Santa Maria Capua Vetere","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santamariacapuavetere\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78","name":"vinalti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","caption":"vinalti"},"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/author\/vinalti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/comments?post=910"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/910\/revisions"}],"predecessor-version":[{"id":912,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/910\/revisions\/912"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media?parent=910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/categories?post=910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/tags?post=910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}