{"id":913,"date":"2021-04-26T13:56:17","date_gmt":"2021-04-26T11:56:17","guid":{"rendered":"https:\/\/comunicacity.net\/santamariacapuavetere\/?p=913"},"modified":"2021-04-26T13:56:17","modified_gmt":"2021-04-26T11:56:17","slug":"da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/","title":{"rendered":"Da oggi in funzione la ZTL elettronica all&#8217;Anfiteatro Campano: dettagli e moduli"},"content":{"rendered":"<p>Entra in funzione oggi la ZTL con varchi elettronici nell\u2019area dell\u2019Anfiteatro Campano.<\/p>\n<p>Fino al 28 maggio 2021 gli impianti elettronici saranno attivati in modalit\u00e0 sperimentale e quindi, senza la procedura sanzionatoria che sar\u00e0 ancora a carico degli agenti della Polizia municipale fino alla stessa data, salvo diverse determinazioni opportunamente segnalate si display degli impianti; successivamente, dal 29 maggio i due sistemi per la rilevazione elettronica del transito dei veicoli procederanno anche alla elevazione di sanzioni nei confronti degli utenti non autorizzati al transito.<\/p>\n<p><strong>Come funziona la ZTL<\/strong><\/p>\n<ul>\n<li>Gli accessi alla ZTL sono disciplinati da due varchi: quello in entrata da via Tifatina e quello in uscita su Corso Aldo Moro<\/li>\n<li>La ZTL \u00e8 attiva in modo permanente, tutti i giorni, dalle 21.00 alle 5.00 del mattino.<\/li>\n<li>Il sistema provveder\u00e0 a rilevare in modo automatico i transiti irregolari per le conseguenti sanzioni<\/li>\n<li>Possono accedere nella ZTL i veicoli di:<\/li>\n<\/ul>\n<ol>\n<li>Residenti e domiciliati<\/li>\n<li>TAXI e NCC<\/li>\n<li>Gestori di attivit\u00e0 commerciali con sede nella ZTL<\/li>\n<li>Di medici e pediatri in visita domiciliare<\/li>\n<li>Di parenti di anziani ultrasettantenni residenti nella ZTL per adeguata assistenza di tipo familiare, nella misura massima di tre veicoli per ogni anziano da assistere<\/li>\n<li>I veicoli ordinariamente condotti da persone con ridotte attivit\u00e0 motorie, titolari di apposti contrassegno C.U.D.E., ovvero veicoli utilizzati ordinariamente per il trasporto di persone disabili residenti nella ZTL<\/li>\n<li>I veicoli degli Istituti di Vigilanza<\/li>\n<li>I veicoli elettrici<\/li>\n<\/ol>\n<p>Il rilascio delle autorizzazioni al transito in ZTL avviene attraverso la presentazione dell\u2019apposito modulo che pu\u00f2 essere scaricato dall\u2019App ComunicaCity (<em>moduli qui in allegato<\/em>) oppure dal Sito del Comune o anche ritirato presso gli uffici del Comando di Polizia municipale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entra in funzione oggi la ZTL con varchi elettronici nell\u2019area dell\u2019Anfiteatro Campano. Fino al 28 maggio 2021 gli impianti elettronici saranno attivati in modalit\u00e0 sperimentale e quindi, senza la procedura [&hellip;]<\/p>\n","protected":false},"author":305,"featured_media":914,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Da oggi in funzione la ZTL elettronica all&#039;Anfiteatro Campano: dettagli e moduli - Santa Maria Capua Vetere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Da oggi in funzione la ZTL elettronica all&#039;Anfiteatro Campano: dettagli e moduli - Santa Maria Capua Vetere\" \/>\n<meta property=\"og:description\" content=\"Entra in funzione oggi la ZTL con varchi elettronici nell\u2019area dell\u2019Anfiteatro Campano. Fino al 28 maggio 2021 gli impianti elettronici saranno attivati in modalit\u00e0 sperimentale e quindi, senza la procedura [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria Capua Vetere\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-26T11:56:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/04\/ZTL-varco.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vinalti\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"vinalti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\\\/\"},\"author\":{\"name\":\"vinalti\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\"},\"headline\":\"Da oggi in funzione la ZTL elettronica all&#8217;Anfiteatro Campano: dettagli e moduli\",\"datePublished\":\"2021-04-26T11:56:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\\\/\"},\"wordCount\":284,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2021\\\/04\\\/ZTL-varco.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\\\/\",\"name\":\"Da oggi in funzione la ZTL elettronica all'Anfiteatro Campano: dettagli e moduli - Santa Maria Capua Vetere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2021\\\/04\\\/ZTL-varco.jpg\",\"datePublished\":\"2021-04-26T11:56:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2021\\\/04\\\/ZTL-varco.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2021\\\/04\\\/ZTL-varco.jpg\",\"width\":1080,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/2021\\\/04\\\/26\\\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Da oggi in funzione la ZTL elettronica all&#8217;Anfiteatro Campano: dettagli e moduli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"name\":\"Santa Maria Capua Vetere\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/person\\\/8e9446fb04d67db4f4ce86e634595b78\",\"name\":\"vinalti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g\",\"caption\":\"vinalti\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/author\\\/vinalti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Da oggi in funzione la ZTL elettronica all'Anfiteatro Campano: dettagli e moduli - Santa Maria Capua Vetere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/","og_locale":"it_IT","og_type":"article","og_title":"Da oggi in funzione la ZTL elettronica all'Anfiteatro Campano: dettagli e moduli - Santa Maria Capua Vetere","og_description":"Entra in funzione oggi la ZTL con varchi elettronici nell\u2019area dell\u2019Anfiteatro Campano. Fino al 28 maggio 2021 gli impianti elettronici saranno attivati in modalit\u00e0 sperimentale e quindi, senza la procedura [&hellip;]","og_url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/","og_site_name":"Santa Maria Capua Vetere","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-04-26T11:56:17+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/04\/ZTL-varco.jpg","type":"image\/jpeg"}],"author":"vinalti","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"vinalti","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/"},"author":{"name":"vinalti","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78"},"headline":"Da oggi in funzione la ZTL elettronica all&#8217;Anfiteatro Campano: dettagli e moduli","datePublished":"2021-04-26T11:56:17+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/"},"wordCount":284,"publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/04\/ZTL-varco.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/","name":"Da oggi in funzione la ZTL elettronica all'Anfiteatro Campano: dettagli e moduli - Santa Maria Capua Vetere","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/04\/ZTL-varco.jpg","datePublished":"2021-04-26T11:56:17+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/#primaryimage","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/04\/ZTL-varco.jpg","contentUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2021\/04\/ZTL-varco.jpg","width":1080,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/2021\/04\/26\/da-oggi-in-funzione-la-ztl-elettronica-allanfiteatro-campano-dettagli-e-moduli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santamariacapuavetere\/"},{"@type":"ListItem","position":2,"name":"Da oggi in funzione la ZTL elettronica all&#8217;Anfiteatro Campano: dettagli e moduli"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","name":"Santa Maria Capua Vetere","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santamariacapuavetere\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/person\/8e9446fb04d67db4f4ce86e634595b78","name":"vinalti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dd4c2edccb588256517dbf064fe1e17fe8974ca15e17302cba4e7342d3698638?s=96&d=mm&r=g","caption":"vinalti"},"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/author\/vinalti\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/comments?post=913"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/913\/revisions"}],"predecessor-version":[{"id":918,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/posts\/913\/revisions\/918"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media\/914"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media?parent=913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/categories?post=913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/tags?post=913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}