{"id":197,"date":"2019-12-06T10:59:13","date_gmt":"2019-12-06T09:59:13","guid":{"rendered":"https:\/\/comunicacity.net\/santamariacapuavetere\/?post_type=rdif&#038;p=197"},"modified":"2019-12-06T11:02:14","modified_gmt":"2019-12-06T10:02:14","slug":"indifferenziato","status":"publish","type":"rdif","link":"https:\/\/comunicacity.net\/santamariacapuavetere\/rdif\/tipologia-rifiuto\/indifferenziato\/","title":{"rendered":"indifferenziato"},"content":{"rendered":"<p>Esporre gli appositi <strong>recipienti di colore Grigio<\/strong>\u00a0all&#8217;esterno della propria abitazione o condominio <strong>dalle ore 20.00 alle 05.00<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Giorni<\/strong>: Marted\u00ec e Sabato<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-179\" src=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2019\/12\/Contenitore-individuale-grigio.jpg\" alt=\"\" width=\"1000\" height=\"192\" srcset=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2019\/12\/Contenitore-individuale-grigio.jpg 1000w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2019\/12\/Contenitore-individuale-grigio-300x58.jpg 300w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2019\/12\/Contenitore-individuale-grigio-768x147.jpg 768w, https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2019\/12\/Contenitore-individuale-grigio-680x131.jpg 680w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<h1><span style=\"color: #008000\">S\u00cc<\/span><\/h1>\n<p>Pannolini e pannoloni, assorbenti, stracci sporchi, spugne, spazzolini, rasoi, siringhe, garze, oggetti di gomma, posate monouso, cicche di sigarette, carte e cialde plastificate, lampadine, piatti e cocci di ceramica, porcellana e terracotta.<\/p>\n<hr \/>\n<h1><span style=\"color: #800000\">NO<\/span><\/h1>\n<p>Tutti i materiali separabili e riciclabili (organico, plastica e metalli, carta, cartone e cartoncino, vetro), rifiuti urbani pericolosi, ingombranti.<\/p>\n<hr \/>\n<h3>Ricorda<\/h3>\n<ul>\n<li>\u00c8 vietato utilizzare contenitori diversi da quelli prestabiliti.<\/li>\n<li>Rispetta gli orari di esposizione dei contenitori.<\/li>\n<li>Ritira il contenitore una volta svuotato.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Esporre gli appositi recipienti di colore Grigio\u00a0all&#8217;esterno della propria abitazione o condominio dalle ore 20.00 alle 05.00 &nbsp; Giorni: Marted\u00ec e Sabato &nbsp; &nbsp; S\u00cc Pannolini e pannoloni, assorbenti, stracci [&hellip;]<\/p>\n","protected":false},"featured_media":185,"parent":172,"menu_order":3,"template":"","meta":[],"class_list":["post-197","rdif","type-rdif","status-publish","has-post-thumbnail","hentry","plugin_rdif-biglist"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>indifferenziato - Santa Maria Capua Vetere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/santamariacapuavetere\/rdif\/tipologia-rifiuto\/indifferenziato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"indifferenziato - Santa Maria Capua Vetere\" \/>\n<meta property=\"og:description\" content=\"Esporre gli appositi recipienti di colore Grigio\u00a0all&#8217;esterno della propria abitazione o condominio dalle ore 20.00 alle 05.00 &nbsp; Giorni: Marted\u00ec e Sabato &nbsp; &nbsp; S\u00cc Pannolini e pannoloni, assorbenti, stracci [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/rdif\/tipologia-rifiuto\/indifferenziato\/\" \/>\n<meta property=\"og:site_name\" content=\"Santa Maria Capua Vetere\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-06T10:02:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2019\/12\/Sacco-Indifferenziato.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"492\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/rdif\\\/tipologia-rifiuto\\\/indifferenziato\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/rdif\\\/tipologia-rifiuto\\\/indifferenziato\\\/\",\"name\":\"indifferenziato - Santa Maria Capua Vetere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/rdif\\\/tipologia-rifiuto\\\/indifferenziato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/rdif\\\/tipologia-rifiuto\\\/indifferenziato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2019\\\/12\\\/Sacco-Indifferenziato.jpg\",\"datePublished\":\"2019-12-06T09:59:13+00:00\",\"dateModified\":\"2019-12-06T10:02:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/rdif\\\/tipologia-rifiuto\\\/indifferenziato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/rdif\\\/tipologia-rifiuto\\\/indifferenziato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/rdif\\\/tipologia-rifiuto\\\/indifferenziato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2019\\\/12\\\/Sacco-Indifferenziato.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/wp-content\\\/uploads\\\/sites\\\/168\\\/2019\\\/12\\\/Sacco-Indifferenziato.jpg\",\"width\":1000,\"height\":492},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/rdif\\\/tipologia-rifiuto\\\/indifferenziato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tipologia rifiuto\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/rdif\\\/tipologia-rifiuto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"indifferenziato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"name\":\"Santa Maria Capua Vetere\",\"description\":\"ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/santamariacapuavetere\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"indifferenziato - Santa Maria Capua Vetere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/santamariacapuavetere\/rdif\/tipologia-rifiuto\/indifferenziato\/","og_locale":"it_IT","og_type":"article","og_title":"indifferenziato - Santa Maria Capua Vetere","og_description":"Esporre gli appositi recipienti di colore Grigio\u00a0all&#8217;esterno della propria abitazione o condominio dalle ore 20.00 alle 05.00 &nbsp; Giorni: Marted\u00ec e Sabato &nbsp; &nbsp; S\u00cc Pannolini e pannoloni, assorbenti, stracci [&hellip;]","og_url":"https:\/\/comunicacity.net\/santamariacapuavetere\/rdif\/tipologia-rifiuto\/indifferenziato\/","og_site_name":"Santa Maria Capua Vetere","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2019-12-06T10:02:14+00:00","og_image":[{"width":1000,"height":492,"url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2019\/12\/Sacco-Indifferenziato.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/rdif\/tipologia-rifiuto\/indifferenziato\/","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/rdif\/tipologia-rifiuto\/indifferenziato\/","name":"indifferenziato - Santa Maria Capua Vetere","isPartOf":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/rdif\/tipologia-rifiuto\/indifferenziato\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/rdif\/tipologia-rifiuto\/indifferenziato\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2019\/12\/Sacco-Indifferenziato.jpg","datePublished":"2019-12-06T09:59:13+00:00","dateModified":"2019-12-06T10:02:14+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/rdif\/tipologia-rifiuto\/indifferenziato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/santamariacapuavetere\/rdif\/tipologia-rifiuto\/indifferenziato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/rdif\/tipologia-rifiuto\/indifferenziato\/#primaryimage","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2019\/12\/Sacco-Indifferenziato.jpg","contentUrl":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-content\/uploads\/sites\/168\/2019\/12\/Sacco-Indifferenziato.jpg","width":1000,"height":492},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/rdif\/tipologia-rifiuto\/indifferenziato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/santamariacapuavetere\/"},{"@type":"ListItem","position":2,"name":"Tipologia rifiuto","item":"https:\/\/comunicacity.net\/santamariacapuavetere\/rdif\/tipologia-rifiuto\/"},{"@type":"ListItem","position":3,"name":"indifferenziato"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#website","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","name":"Santa Maria Capua Vetere","description":"ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/santamariacapuavetere\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/santamariacapuavetere\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/santamariacapuavetere\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/rdif\/197","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/rdif"}],"about":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/types\/rdif"}],"up":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/rdif\/172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media\/185"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/santamariacapuavetere\/wp-json\/wp\/v2\/media?parent=197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}