{"id":19157,"date":"2021-11-02T22:13:42","date_gmt":"2021-11-02T21:13:42","guid":{"rendered":"https:\/\/comunicacity.net\/sanvittoredellazio\/?p=19157"},"modified":"2021-11-02T22:14:59","modified_gmt":"2021-11-02T21:14:59","slug":"allerta-meteo-arancione","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/","title":{"rendered":"ALLERTA METEO ARANCIONE"},"content":{"rendered":"<p>AVVISO DI CONDIZIONI METEOROLOGICHE AVVERSE: ALLERTA ARANCIONE<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Inizio<\/h4>\n<p>02\/11\/2021 21:14<\/p>\n\t\t\t\n\t\t\t\t\t\t<h4>Fine<\/h4>\n<p>03\/11\/2021 21:14<\/p>\n\t\t\t\n\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_19159\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/11\/allertamento_02_11_2021-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/11\/allertamento_02_11_2021-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>allertamento_02_11_2021<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>AVVISO DI CONDIZIONI METEOROLOGICHE AVVERSE: ALLERTA ARANCIONE Inizio 02\/11\/2021 21:14 Fine 03\/11\/2021 21:14 \ud83d\udcce Allegatiallertamento_02_11_2021<\/p>\n","protected":false},"author":374,"featured_media":19158,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[19],"tags":[],"class_list":["post-19157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-urgenze-e-allerta"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ALLERTA METEO ARANCIONE - San Vittore del Lazio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ALLERTA METEO ARANCIONE - San Vittore del Lazio\" \/>\n<meta property=\"og:description\" content=\"AVVISO DI CONDIZIONI METEOROLOGICHE AVVERSE: ALLERTA ARANCIONE Inizio 02\/11\/2021 21:14 Fine 03\/11\/2021 21:14 \ud83d\udcce Allegatiallertamento_02_11_2021\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/\" \/>\n<meta property=\"og:site_name\" content=\"San Vittore del Lazio\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-02T21:13:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-02T21:14:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/11\/allerta-meteo-lazio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1857\" \/>\n\t<meta property=\"og:image:height\" content=\"997\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nadiabucci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"nadiabucci\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/11\\\/02\\\/allerta-meteo-arancione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/11\\\/02\\\/allerta-meteo-arancione\\\/\"},\"author\":{\"name\":\"nadiabucci\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\"},\"headline\":\"ALLERTA METEO ARANCIONE\",\"datePublished\":\"2021-11-02T21:13:42+00:00\",\"dateModified\":\"2021-11-02T21:14:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/11\\\/02\\\/allerta-meteo-arancione\\\/\"},\"wordCount\":10,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/11\\\/02\\\/allerta-meteo-arancione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2021\\\/11\\\/allerta-meteo-lazio.jpg\",\"articleSection\":[\"Urgenze e Allerta\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/11\\\/02\\\/allerta-meteo-arancione\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/11\\\/02\\\/allerta-meteo-arancione\\\/\",\"name\":\"ALLERTA METEO ARANCIONE - San Vittore del Lazio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/11\\\/02\\\/allerta-meteo-arancione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/11\\\/02\\\/allerta-meteo-arancione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2021\\\/11\\\/allerta-meteo-lazio.jpg\",\"datePublished\":\"2021-11-02T21:13:42+00:00\",\"dateModified\":\"2021-11-02T21:14:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/11\\\/02\\\/allerta-meteo-arancione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/11\\\/02\\\/allerta-meteo-arancione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/11\\\/02\\\/allerta-meteo-arancione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2021\\\/11\\\/allerta-meteo-lazio.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2021\\\/11\\\/allerta-meteo-lazio.jpg\",\"width\":1857,\"height\":997},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/11\\\/02\\\/allerta-meteo-arancione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ALLERTA METEO ARANCIONE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"name\":\"San Vittore del Lazio\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":null,\"contentUrl\":null,\"width\":724,\"height\":1024,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\",\"name\":\"nadiabucci\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"caption\":\"nadiabucci\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/author\\\/nadiabucci\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ALLERTA METEO ARANCIONE - San Vittore del Lazio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/","og_locale":"it_IT","og_type":"article","og_title":"ALLERTA METEO ARANCIONE - San Vittore del Lazio","og_description":"AVVISO DI CONDIZIONI METEOROLOGICHE AVVERSE: ALLERTA ARANCIONE Inizio 02\/11\/2021 21:14 Fine 03\/11\/2021 21:14 \ud83d\udcce Allegatiallertamento_02_11_2021","og_url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/","og_site_name":"San Vittore del Lazio","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-11-02T21:13:42+00:00","article_modified_time":"2021-11-02T21:14:59+00:00","og_image":[{"width":1857,"height":997,"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/11\/allerta-meteo-lazio.jpg","type":"image\/jpeg"}],"author":"nadiabucci","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"nadiabucci"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/"},"author":{"name":"nadiabucci","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573"},"headline":"ALLERTA METEO ARANCIONE","datePublished":"2021-11-02T21:13:42+00:00","dateModified":"2021-11-02T21:14:59+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/"},"wordCount":10,"publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/11\/allerta-meteo-lazio.jpg","articleSection":["Urgenze e Allerta"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/","name":"ALLERTA METEO ARANCIONE - San Vittore del Lazio","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/11\/allerta-meteo-lazio.jpg","datePublished":"2021-11-02T21:13:42+00:00","dateModified":"2021-11-02T21:14:59+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/#primaryimage","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/11\/allerta-meteo-lazio.jpg","contentUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/11\/allerta-meteo-lazio.jpg","width":1857,"height":997},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/11\/02\/allerta-meteo-arancione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanvittoredellazio\/"},{"@type":"ListItem","position":2,"name":"ALLERTA METEO ARANCIONE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","name":"San Vittore del Lazio","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanvittoredellazio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/","url":null,"contentUrl":null,"width":724,"height":1024,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573","name":"nadiabucci","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","caption":"nadiabucci"},"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/author\/nadiabucci\/"}]}},"meta_box":{"cc4_urg_colore":"arancio","cc4_urg_data_inizio":"02\/11\/2021 21:14","cc4_urg_data_fine":"03\/11\/2021 21:14","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/19157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/users\/374"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/comments?post=19157"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/19157\/revisions"}],"predecessor-version":[{"id":19160,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/19157\/revisions\/19160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media\/19158"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media?parent=19157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/categories?post=19157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/tags?post=19157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}