{"id":19353,"date":"2022-01-08T18:34:47","date_gmt":"2022-01-08T17:34:47","guid":{"rendered":"https:\/\/comunicacity.net\/sanvittoredellazio\/?p=19353"},"modified":"2022-01-08T18:38:34","modified_gmt":"2022-01-08T17:38:34","slug":"campagna-screening-popolazione-studentesca","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/","title":{"rendered":"Campagna screening popolazione studentesca"},"content":{"rendered":"<p>Si \u00e8 conclusa nel primo pomeriggio di oggi la campagna di screening della popolazione studentesca, del personale docente, del personale Ata e del personale mensa dei plessi scolastici siti sul territorio comunale attraverso l\u2019esecuzione di test rapidi covid 19.<\/p>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"51fk2-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"51fk2-0-0\"><span data-offset-key=\"51fk2-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"56jsl-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"56jsl-0-0\"><span data-offset-key=\"56jsl-0-0\">Un sentito ringraziamento va ai 180 circa tra bambini e ragazzi che si sono sottoposti al test con coraggio nonch\u00e9 alle loro famiglie per aver sapientemente scelto di \u201ccollaborare\u201d con l\u2019istituzione per il bene dei piccoli e di conseguenza di tutta la collettivit\u00e0, alla dirigente scolastica Prof.ssa Gelsomina Raia per aver sostenuto ed incentivato l\u2019iniziativa.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"6l41r-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"6l41r-0-0\"><span data-offset-key=\"6l41r-0-0\">I ringraziamenti sono d\u2019obbligo anche:<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"9bo4t-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"9bo4t-0-0\"><span data-offset-key=\"9bo4t-0-0\">&#8211; alla cooperativa <\/span><span class=\"diy96o5h\" data-offset-key=\"9bo4t-1-0\"><span data-offset-key=\"9bo4t-1-0\">Santa Lucia Life<\/span><\/span><span data-offset-key=\"9bo4t-2-0\"> nelle persone della dr.ssa <\/span><span class=\"diy96o5h\" data-offset-key=\"9bo4t-3-0\"><span data-offset-key=\"9bo4t-3-0\">Antonietta Sarracino<\/span><\/span><span data-offset-key=\"9bo4t-4-0\">, il dr. Benedetto Gelfusa e le infermiere Serena e Giorgia;<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"92t8c-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"92t8c-0-0\"><span data-offset-key=\"92t8c-0-0\">&#8211; alla farmacia Gulia del dr. Andrea Cocorocchio di San Vittore del Lazio;<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"2b2ji-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"2b2ji-0-0\"><span data-offset-key=\"2b2ji-0-0\">&#8211; ai ragazzi del servizio civile universale, in particolare a <\/span><span class=\"diy96o5h\" data-offset-key=\"2b2ji-1-0\"><span data-offset-key=\"2b2ji-1-0\">Mariadele Coschignano<\/span><\/span><span data-offset-key=\"2b2ji-2-0\">, Chiara Di Paolo e <\/span><span class=\"diy96o5h\" data-offset-key=\"2b2ji-3-0\"><span data-offset-key=\"2b2ji-3-0\">Luisa Musto<\/span><\/span><span data-offset-key=\"2b2ji-4-0\">;<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"f9rp4-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"f9rp4-0-0\">\n<p><span data-offset-key=\"f9rp4-0-0\"> &#8211; ai dipendenti comunali Ing. <\/span><span class=\"diy96o5h\" data-offset-key=\"f9rp4-1-0\"><span data-offset-key=\"f9rp4-1-0\">Domenico Iannetta<\/span><\/span><span data-offset-key=\"f9rp4-2-0\"><span data-offset-key=\"f9rp4-2-0\"> e dr. <\/span><\/span>Fabio Vendittelli e alla collaboratrice Moro Viviana.<\/p>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"ehgh8-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"ehgh8-0-0\"><span data-offset-key=\"ehgh8-0-0\">Grazie alla professionalit\u00e0, all\u2019impegno e all\u2019attenzione di tutti loro il servizio reso alla cittadinanza \u00e8 stato impeccabile.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"ctnbs-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"ctnbs-0-0\"><span data-offset-key=\"ctnbs-0-0\">Luned\u00ec si rientrer\u00e0 a scuola in presenza: una decisione difficile ma presa dopo attenta riflessione.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"8lp1q-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"8lp1q-0-0\"><span data-offset-key=\"8lp1q-0-0\">Mai come in questi momenti ogni scelta \u00e8 opinabile e discutibile. Sia la ripresa delle lezioni in presenza che la dad presentano pro e contro. <\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"cv26o-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"cv26o-0-0\"><span data-offset-key=\"cv26o-0-0\">Non troviamo il giusto supporto e la dovuta chiarezza neanche nelle istituzioni di livello centrale dove ormai, \u00e8 palese, regna un p\u00f2 di confusione e purtroppo i due diritti, costituzionalmente garantiti, cio\u00e8 quello allo studio e quello alla salute, sembrano non andare pi\u00f9 di pari passo.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"1to2s-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"1to2s-0-0\"><span data-offset-key=\"1to2s-0-0\">Amministrare richiede coraggio, richiede fare delle scelte che possono scontentare: non \u00e8 pi\u00f9 in gamba il sindaco che mantiene le scuole aperte, n\u00e8 il sindaco che decide di chiuderle: l\u2019importante \u00e8 che tali scelte siano precedute da una ponderata valutazione della situazione di fatto locale, dal buon senso e che vi siano misure parallele che evitino altre situazioni di possibile contagio.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"bqgv2-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"bqgv2-0-0\"><span data-offset-key=\"bqgv2-0-0\">\u00a0<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"bjhqm-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"bjhqm-0-0\"><span data-offset-key=\"bjhqm-0-0\">I nostri studenti saranno bravi nell\u2019osservare le regole vigenti negli ambienti scolastici cos\u00ec come fatto fino a dicembre , come pure gli insegnati faranno quanto necessario per rendere quanto pi\u00f9 sereno possibile questo momento.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"28nf5-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"28nf5-0-0\"><span data-offset-key=\"28nf5-0-0\">Sperando che l\u2019unica cosa che dilaghi veramente sia il senso di responsabilit\u00e0 verso se stessi e gli altri.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"cqicl-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"cqicl-0-0\"><span data-offset-key=\"cqicl-0-0\"> Indipendentemente dalla scuola.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"9s98n\" data-offset-key=\"1qgj1-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"1qgj1-0-0\"><span data-offset-key=\"1qgj1-0-0\"> L\u2019amministrazione comunale.<\/span><\/div>\n<\/div>\n<p><span data-offset-key=\"f9rp4-2-0\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-19354\" src=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-1-1024x768.jpeg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-1-1024x768.jpeg 1024w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-1-300x225.jpeg 300w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-1-768x576.jpeg 768w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-1-1536x1152.jpeg 1536w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-1.jpeg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-19355\" src=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-2-768x1024.jpeg\" alt=\"\" width=\"640\" height=\"853\" srcset=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-2-768x1024.jpeg 768w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-2-225x300.jpeg 225w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-2-1152x1536.jpeg 1152w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-2.jpeg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-19356\" src=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-3-1024x768.jpeg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-3-1024x768.jpeg 1024w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-3-300x225.jpeg 300w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-3-768x576.jpeg 768w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-3-1536x1152.jpeg 1536w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-3.jpeg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-19357\" src=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-4-1024x768.jpeg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-4-1024x768.jpeg 1024w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-4-300x225.jpeg 300w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-4-768x576.jpeg 768w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-4-1536x1152.jpeg 1536w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-4.jpeg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-19358\" src=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-5-1024x768.jpeg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-5-1024x768.jpeg 1024w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-5-300x225.jpeg 300w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-5-768x576.jpeg 768w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-5-1536x1152.jpeg 1536w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-5.jpeg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-19359\" src=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-6-1024x768.jpeg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-6-1024x768.jpeg 1024w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-6-300x225.jpeg 300w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-6-768x576.jpeg 768w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-6-1536x1152.jpeg 1536w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-6.jpeg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/span><\/p>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 conclusa nel primo pomeriggio di oggi la campagna di screening della popolazione studentesca, del personale docente, del personale Ata e del personale mensa dei plessi scolastici siti sul [&hellip;]<\/p>\n","protected":false},"author":374,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-19353","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Campagna screening popolazione studentesca - San Vittore del Lazio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campagna screening popolazione studentesca - San Vittore del Lazio\" \/>\n<meta property=\"og:description\" content=\"Si \u00e8 conclusa nel primo pomeriggio di oggi la campagna di screening della popolazione studentesca, del personale docente, del personale Ata e del personale mensa dei plessi scolastici siti sul [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/\" \/>\n<meta property=\"og:site_name\" content=\"San Vittore del Lazio\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-08T17:34:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-08T17:38:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-1-1024x768.jpeg\" \/>\n<meta name=\"author\" content=\"nadiabucci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"nadiabucci\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/01\\\/08\\\/campagna-screening-popolazione-studentesca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/01\\\/08\\\/campagna-screening-popolazione-studentesca\\\/\"},\"author\":{\"name\":\"nadiabucci\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\"},\"headline\":\"Campagna screening popolazione studentesca\",\"datePublished\":\"2022-01-08T17:34:47+00:00\",\"dateModified\":\"2022-01-08T17:38:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/01\\\/08\\\/campagna-screening-popolazione-studentesca\\\/\"},\"wordCount\":397,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/01\\\/08\\\/campagna-screening-popolazione-studentesca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2022\\\/01\\\/foto-1-1024x768.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/01\\\/08\\\/campagna-screening-popolazione-studentesca\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/01\\\/08\\\/campagna-screening-popolazione-studentesca\\\/\",\"name\":\"Campagna screening popolazione studentesca - San Vittore del Lazio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/01\\\/08\\\/campagna-screening-popolazione-studentesca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/01\\\/08\\\/campagna-screening-popolazione-studentesca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2022\\\/01\\\/foto-1-1024x768.jpeg\",\"datePublished\":\"2022-01-08T17:34:47+00:00\",\"dateModified\":\"2022-01-08T17:38:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/01\\\/08\\\/campagna-screening-popolazione-studentesca\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/01\\\/08\\\/campagna-screening-popolazione-studentesca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/01\\\/08\\\/campagna-screening-popolazione-studentesca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2022\\\/01\\\/foto-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2022\\\/01\\\/foto-1.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/01\\\/08\\\/campagna-screening-popolazione-studentesca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campagna screening popolazione studentesca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"name\":\"San Vittore del Lazio\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":null,\"contentUrl\":null,\"width\":724,\"height\":1024,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\",\"name\":\"nadiabucci\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"caption\":\"nadiabucci\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/author\\\/nadiabucci\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Campagna screening popolazione studentesca - San Vittore del Lazio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/","og_locale":"it_IT","og_type":"article","og_title":"Campagna screening popolazione studentesca - San Vittore del Lazio","og_description":"Si \u00e8 conclusa nel primo pomeriggio di oggi la campagna di screening della popolazione studentesca, del personale docente, del personale Ata e del personale mensa dei plessi scolastici siti sul [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/","og_site_name":"San Vittore del Lazio","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-01-08T17:34:47+00:00","article_modified_time":"2022-01-08T17:38:34+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-1-1024x768.jpeg","type":"","width":"","height":""}],"author":"nadiabucci","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"nadiabucci","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/"},"author":{"name":"nadiabucci","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573"},"headline":"Campagna screening popolazione studentesca","datePublished":"2022-01-08T17:34:47+00:00","dateModified":"2022-01-08T17:38:34+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/"},"wordCount":397,"publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-1-1024x768.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/","name":"Campagna screening popolazione studentesca - San Vittore del Lazio","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-1-1024x768.jpeg","datePublished":"2022-01-08T17:34:47+00:00","dateModified":"2022-01-08T17:38:34+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/#primaryimage","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-1.jpeg","contentUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/01\/foto-1.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/01\/08\/campagna-screening-popolazione-studentesca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanvittoredellazio\/"},{"@type":"ListItem","position":2,"name":"Campagna screening popolazione studentesca"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","name":"San Vittore del Lazio","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanvittoredellazio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/","url":null,"contentUrl":null,"width":724,"height":1024,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573","name":"nadiabucci","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","caption":"nadiabucci"},"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/author\/nadiabucci\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/19353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/users\/374"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/comments?post=19353"}],"version-history":[{"count":3,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/19353\/revisions"}],"predecessor-version":[{"id":19362,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/19353\/revisions\/19362"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media?parent=19353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/categories?post=19353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/tags?post=19353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}