{"id":19585,"date":"2022-03-11T14:04:11","date_gmt":"2022-03-11T13:04:11","guid":{"rendered":"https:\/\/comunicacity.net\/sanvittoredellazio\/?p=19585"},"modified":"2022-03-11T14:03:51","modified_gmt":"2022-03-11T13:03:51","slug":"soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/","title":{"rendered":"Soccorso ed Assistenza sul territorio alla popolazione ucraina"},"content":{"rendered":"<p><a href=\"https:\/\/www.comune.sanvittoredellazio.fr.it\/wp-content\/uploads\/2022\/03\/stop-war-1.webp\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-19609\" src=\"https:\/\/www.comune.sanvittoredellazio.fr.it\/wp-content\/uploads\/2022\/03\/stop-war-1-300x300.webp\" alt=\"\" width=\"300\" height=\"300\" \/><\/a><\/p>\n<p>Alla luce della crisi umanitaria in corso in Ucraina ed in previsione dei massicci fenomeni migratori verso il nostro Paese, \u00e8 necessario garantire con tempestivit\u00e0 ogni forma necessaria di soccorso ed assistenza sul territorio alla popolazione ucraina.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_19616\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/BENVENUTI-IN-ITALIA.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/BENVENUTI-IN-ITALIA.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>BENVENUTI IN ITALIA<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Alla luce della crisi umanitaria in corso in Ucraina ed in previsione dei massicci fenomeni migratori verso il nostro Paese, \u00e8 necessario garantire con tempestivit\u00e0 ogni forma necessaria di soccorso [&hellip;]<\/p>\n","protected":false},"author":374,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16],"tags":[],"class_list":["post-19585","post","type-post","status-publish","format-standard","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Soccorso ed Assistenza sul territorio alla popolazione ucraina - San Vittore del Lazio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Soccorso ed Assistenza sul territorio alla popolazione ucraina - San Vittore del Lazio\" \/>\n<meta property=\"og:description\" content=\"Alla luce della crisi umanitaria in corso in Ucraina ed in previsione dei massicci fenomeni migratori verso il nostro Paese, \u00e8 necessario garantire con tempestivit\u00e0 ogni forma necessaria di soccorso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/\" \/>\n<meta property=\"og:site_name\" content=\"San Vittore del Lazio\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-11T13:04:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.comune.sanvittoredellazio.fr.it\/wp-content\/uploads\/2022\/03\/stop-war-1-300x300.webp\" \/>\n<meta name=\"author\" content=\"nadiabucci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"nadiabucci\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\\\/\"},\"author\":{\"name\":\"nadiabucci\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\"},\"headline\":\"Soccorso ed Assistenza sul territorio alla popolazione ucraina\",\"datePublished\":\"2022-03-11T13:04:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\\\/\"},\"wordCount\":44,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.comune.sanvittoredellazio.fr.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/stop-war-1-300x300.webp\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\\\/\",\"name\":\"Soccorso ed Assistenza sul territorio alla popolazione ucraina - San Vittore del Lazio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.comune.sanvittoredellazio.fr.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/stop-war-1-300x300.webp\",\"datePublished\":\"2022-03-11T13:04:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.comune.sanvittoredellazio.fr.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/stop-war-1-300x300.webp\",\"contentUrl\":\"https:\\\/\\\/www.comune.sanvittoredellazio.fr.it\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/stop-war-1-300x300.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Soccorso ed Assistenza sul territorio alla popolazione ucraina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"name\":\"San Vittore del Lazio\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":null,\"contentUrl\":null,\"width\":724,\"height\":1024,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\",\"name\":\"nadiabucci\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"caption\":\"nadiabucci\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/author\\\/nadiabucci\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Soccorso ed Assistenza sul territorio alla popolazione ucraina - San Vittore del Lazio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/","og_locale":"it_IT","og_type":"article","og_title":"Soccorso ed Assistenza sul territorio alla popolazione ucraina - San Vittore del Lazio","og_description":"Alla luce della crisi umanitaria in corso in Ucraina ed in previsione dei massicci fenomeni migratori verso il nostro Paese, \u00e8 necessario garantire con tempestivit\u00e0 ogni forma necessaria di soccorso [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/","og_site_name":"San Vittore del Lazio","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-03-11T13:04:11+00:00","og_image":[{"url":"https:\/\/www.comune.sanvittoredellazio.fr.it\/wp-content\/uploads\/2022\/03\/stop-war-1-300x300.webp","type":"","width":"","height":""}],"author":"nadiabucci","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"nadiabucci"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/"},"author":{"name":"nadiabucci","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573"},"headline":"Soccorso ed Assistenza sul territorio alla popolazione ucraina","datePublished":"2022-03-11T13:04:11+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/"},"wordCount":44,"publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comune.sanvittoredellazio.fr.it\/wp-content\/uploads\/2022\/03\/stop-war-1-300x300.webp","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/","name":"Soccorso ed Assistenza sul territorio alla popolazione ucraina - San Vittore del Lazio","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.comune.sanvittoredellazio.fr.it\/wp-content\/uploads\/2022\/03\/stop-war-1-300x300.webp","datePublished":"2022-03-11T13:04:11+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/#primaryimage","url":"https:\/\/www.comune.sanvittoredellazio.fr.it\/wp-content\/uploads\/2022\/03\/stop-war-1-300x300.webp","contentUrl":"https:\/\/www.comune.sanvittoredellazio.fr.it\/wp-content\/uploads\/2022\/03\/stop-war-1-300x300.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/soccorso-ed-assistenza-sul-territorio-alla-popolazione-ucraina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanvittoredellazio\/"},{"@type":"ListItem","position":2,"name":"Soccorso ed Assistenza sul territorio alla popolazione ucraina"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","name":"San Vittore del Lazio","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanvittoredellazio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/","url":null,"contentUrl":null,"width":724,"height":1024,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573","name":"nadiabucci","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","caption":"nadiabucci"},"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/author\/nadiabucci\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"19608"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/19585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/users\/374"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/comments?post=19585"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/19585\/revisions"}],"predecessor-version":[{"id":19588,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/19585\/revisions\/19588"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media?parent=19585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/categories?post=19585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/tags?post=19585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}