{"id":19617,"date":"2022-03-11T18:35:35","date_gmt":"2022-03-11T17:35:35","guid":{"rendered":"https:\/\/comunicacity.net\/sanvittoredellazio\/?p=19617"},"modified":"2022-03-11T18:35:35","modified_gmt":"2022-03-11T17:35:35","slug":"convegno-monitoraggio-ambientale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/","title":{"rendered":"CONVEGNO MONITORAGGIO AMBIENTALE"},"content":{"rendered":"<div class=\"\" data-block=\"true\" data-editor=\"bch8f\" data-offset-key=\"3551n-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"3551n-0-0\"><span data-offset-key=\"3551n-0-0\">Si \u00e8 svolto l\u20198 marzo presso la sala consiliare del Comune di San Vittore del Lazio il convegno dedicato alla discussione dei primi risultati di monitoraggio ambientale svolti per conto dell\u2019amministrazione comunale di San vittore del Lazio.<\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"bch8f\" data-offset-key=\"chfre-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"chfre-0-0\"><span data-offset-key=\"chfre-0-0\">Erano presenti quali relatori la professoressa Antonella Canini ed il Dott Gabriele de Marco del Dipartimento di Biologia dell&#8217;Universit\u00e0 degli studi di Roma Tor Vergata, nonch\u00e8 il professor Nik Pacini del Dipartimento di Ingegneria Ambientale dell&#8217;Universit\u00e0 degli studi della Calabria, i quali hanno esposto ai partecipanti gli studi e le analisi eseguite su diversi campioni di prodotti raccolti sul territorio comunale. <\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"bch8f\" data-offset-key=\"89lhg-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"89lhg-0-0\"><span data-offset-key=\"89lhg-0-0\">Precisamente, \u00e8 stata analizzata la qualit\u00e0 del miele prodotto nel territorio del Comune di San Vittore del Lazio e nelle zone limitrofe utilizzando le api come bioindicatori della qualit\u00e0 ambientale e si sono svolte indagini su olive e rosmarino per determinare l&#8217;eventuale concentrazione di contaminanti persistenti e nello specifico di diossine. <\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"bch8f\" data-offset-key=\"2h0us-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"2h0us-0-0\"><span data-offset-key=\"2h0us-0-0\">L\u2019iniziativa ha permesso un solido confronto tra i due atenei sul lavoro svolto e su come proseguire gli studi per raggiungere una conoscenza completa dello stato di contaminazione del territorio comunale. <\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"bch8f\" data-offset-key=\"82hdc-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"82hdc-0-0\"><span data-offset-key=\"82hdc-0-0\">Si \u00e8 convenuto, ed in questo era concorde anche il Presidente della X Commissione Rifiuti della Regione Lazio, dr. Marco Cacciatore presente al convegno, di rendere l&#8217;Arpa Lazio parte attiva in questa attivit\u00e0 di monitoraggio importante per il nostro territorio per definire &#8220;punto zero&#8221;. <\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"bch8f\" data-offset-key=\"3te86-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"3te86-0-0\"><span data-offset-key=\"3te86-0-0\">Nelle attivit\u00e0 di monitoraggio future Arpa Lazio, che era stata invitata a prendere parte all&#8217;incontro dell&#8217;8 marzo, dovr\u00e0 essere principale attore nel ratificare e validare un protocollo di monitoraggio adeguato per questo territorio che \u00e8 chiaramente un territorio in cui insistono molteplici fattori critici. <\/span><\/div>\n<\/div>\n<div class=\"\" data-block=\"true\" data-editor=\"bch8f\" data-offset-key=\"1ifq-0-0\">\n<div class=\"_1mf _1mj\" data-offset-key=\"1ifq-0-0\"><span data-offset-key=\"1ifq-0-0\">Il Sindaco Nadia Bucci e l&#8217;Assessore D&#8217;Orsi ringraziano a nome di tutta l&#8217;amministrazione comunale, non solo i relatori ma anche tutti gli apicoltori del territorio che hanno collaborato affinch\u00e8 potesse concretizzarsi il monitoraggio nonch\u00e8 coloro che hanno partecipato al convegno, in particolare modo i volontari del Servizio Civile Universale. <\/span><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-19618\" src=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-1-1024x769.jpg\" alt=\"\" width=\"640\" height=\"481\" srcset=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-1-1024x769.jpg 1024w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-1-300x225.jpg 300w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-1-768x576.jpg 768w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-1-1536x1153.jpg 1536w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-1.jpg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-19619\" src=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-2-1024x769.jpg\" alt=\"\" width=\"640\" height=\"481\" srcset=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-2-1024x769.jpg 1024w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-2-300x225.jpg 300w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-2-768x576.jpg 768w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-2-1536x1153.jpg 1536w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-2.jpg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-19620\" src=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-4-1024x769.jpg\" alt=\"\" width=\"640\" height=\"481\" srcset=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-4-1024x769.jpg 1024w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-4-300x225.jpg 300w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-4-768x576.jpg 768w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-4-1536x1153.jpg 1536w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-4.jpg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-19621\" src=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-5-1024x769.jpg\" alt=\"\" width=\"640\" height=\"481\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-19622\" src=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-6-1024x769.jpg\" alt=\"\" width=\"640\" height=\"481\" srcset=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-6-1024x769.jpg 1024w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-6-300x225.jpg 300w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-6-768x576.jpg 768w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-6-1536x1153.jpg 1536w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/foto-6.jpg 1600w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 svolto l\u20198 marzo presso la sala consiliare del Comune di San Vittore del Lazio il convegno dedicato alla discussione dei primi risultati di monitoraggio ambientale svolti per conto [&hellip;]<\/p>\n","protected":false},"author":374,"featured_media":19623,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-19617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONVEGNO MONITORAGGIO AMBIENTALE - San Vittore del Lazio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONVEGNO MONITORAGGIO AMBIENTALE - San Vittore del Lazio\" \/>\n<meta property=\"og:description\" content=\"Si \u00e8 svolto l\u20198 marzo presso la sala consiliare del Comune di San Vittore del Lazio il convegno dedicato alla discussione dei primi risultati di monitoraggio ambientale svolti per conto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/\" \/>\n<meta property=\"og:site_name\" content=\"San Vittore del Lazio\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-11T17:35:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/FOTO-8-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nadiabucci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"nadiabucci\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/convegno-monitoraggio-ambientale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/convegno-monitoraggio-ambientale\\\/\"},\"author\":{\"name\":\"nadiabucci\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\"},\"headline\":\"CONVEGNO MONITORAGGIO AMBIENTALE\",\"datePublished\":\"2022-03-11T17:35:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/convegno-monitoraggio-ambientale\\\/\"},\"wordCount\":318,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/convegno-monitoraggio-ambientale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2022\\\/03\\\/FOTO-8-scaled.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/convegno-monitoraggio-ambientale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/convegno-monitoraggio-ambientale\\\/\",\"name\":\"CONVEGNO MONITORAGGIO AMBIENTALE - San Vittore del Lazio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/convegno-monitoraggio-ambientale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/convegno-monitoraggio-ambientale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2022\\\/03\\\/FOTO-8-scaled.jpg\",\"datePublished\":\"2022-03-11T17:35:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/convegno-monitoraggio-ambientale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/convegno-monitoraggio-ambientale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/convegno-monitoraggio-ambientale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2022\\\/03\\\/FOTO-8-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2022\\\/03\\\/FOTO-8-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2022\\\/03\\\/11\\\/convegno-monitoraggio-ambientale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONVEGNO MONITORAGGIO AMBIENTALE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"name\":\"San Vittore del Lazio\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":null,\"contentUrl\":null,\"width\":724,\"height\":1024,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\",\"name\":\"nadiabucci\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"caption\":\"nadiabucci\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/author\\\/nadiabucci\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONVEGNO MONITORAGGIO AMBIENTALE - San Vittore del Lazio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/","og_locale":"it_IT","og_type":"article","og_title":"CONVEGNO MONITORAGGIO AMBIENTALE - San Vittore del Lazio","og_description":"Si \u00e8 svolto l\u20198 marzo presso la sala consiliare del Comune di San Vittore del Lazio il convegno dedicato alla discussione dei primi risultati di monitoraggio ambientale svolti per conto [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/","og_site_name":"San Vittore del Lazio","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2022-03-11T17:35:35+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/FOTO-8-scaled.jpg","type":"image\/jpeg"}],"author":"nadiabucci","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"nadiabucci","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/"},"author":{"name":"nadiabucci","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573"},"headline":"CONVEGNO MONITORAGGIO AMBIENTALE","datePublished":"2022-03-11T17:35:35+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/"},"wordCount":318,"publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/FOTO-8-scaled.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/","name":"CONVEGNO MONITORAGGIO AMBIENTALE - San Vittore del Lazio","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/FOTO-8-scaled.jpg","datePublished":"2022-03-11T17:35:35+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/#primaryimage","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/FOTO-8-scaled.jpg","contentUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2022\/03\/FOTO-8-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2022\/03\/11\/convegno-monitoraggio-ambientale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanvittoredellazio\/"},{"@type":"ListItem","position":2,"name":"CONVEGNO MONITORAGGIO AMBIENTALE"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","name":"San Vittore del Lazio","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanvittoredellazio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/","url":null,"contentUrl":null,"width":724,"height":1024,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573","name":"nadiabucci","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","caption":"nadiabucci"},"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/author\/nadiabucci\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/19617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/users\/374"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/comments?post=19617"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/19617\/revisions"}],"predecessor-version":[{"id":19624,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/19617\/revisions\/19624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media\/19623"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media?parent=19617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/categories?post=19617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/tags?post=19617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}