{"id":20501,"date":"2023-01-04T11:14:49","date_gmt":"2023-01-04T10:14:49","guid":{"rendered":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/"},"modified":"2023-01-04T11:14:49","modified_gmt":"2023-01-04T10:14:49","slug":"sospensione-servizio-di-raccolta-6-gennaio-2023","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/","title":{"rendered":"SOSPENSIONE SERVIZIO DI RACCOLTA 6 GENNAIO 2023"},"content":{"rendered":"<p>SOSPENSIONE RACCOLTA INDIFFERENZIATA PER IL 06.01.2023. LA RACCCOLTA VERRA&#8217; POSTICIPATA AL GIORNO 07.01.2023<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SOSPENSIONE RACCOLTA INDIFFERENZIATA PER IL 06.01.2023. LA RACCCOLTA VERRA&#8217; POSTICIPATA AL GIORNO 07.01.2023<\/p>\n","protected":false},"author":374,"featured_media":20502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-20501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interruzione-di-servizio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SOSPENSIONE SERVIZIO DI RACCOLTA 6 GENNAIO 2023 - San Vittore del Lazio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SOSPENSIONE SERVIZIO DI RACCOLTA 6 GENNAIO 2023 - San Vittore del Lazio\" \/>\n<meta property=\"og:description\" content=\"SOSPENSIONE RACCOLTA INDIFFERENZIATA PER IL 06.01.2023. LA RACCCOLTA VERRA&#8217; POSTICIPATA AL GIORNO 07.01.2023\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"San Vittore del Lazio\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-04T10:14:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2023\/01\/Cestini-raccolta-differenziata-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1281\" \/>\n\t<meta property=\"og:image:height\" content=\"981\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nadiabucci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"nadiabucci\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2023\\\/01\\\/04\\\/sospensione-servizio-di-raccolta-6-gennaio-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2023\\\/01\\\/04\\\/sospensione-servizio-di-raccolta-6-gennaio-2023\\\/\"},\"author\":{\"name\":\"nadiabucci\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\"},\"headline\":\"SOSPENSIONE SERVIZIO DI RACCOLTA 6 GENNAIO 2023\",\"datePublished\":\"2023-01-04T10:14:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2023\\\/01\\\/04\\\/sospensione-servizio-di-raccolta-6-gennaio-2023\\\/\"},\"wordCount\":16,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2023\\\/01\\\/04\\\/sospensione-servizio-di-raccolta-6-gennaio-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2023\\\/01\\\/Cestini-raccolta-differenziata-min.jpg\",\"articleSection\":[\"Interruzione di Servizio\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2023\\\/01\\\/04\\\/sospensione-servizio-di-raccolta-6-gennaio-2023\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2023\\\/01\\\/04\\\/sospensione-servizio-di-raccolta-6-gennaio-2023\\\/\",\"name\":\"SOSPENSIONE SERVIZIO DI RACCOLTA 6 GENNAIO 2023 - San Vittore del Lazio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2023\\\/01\\\/04\\\/sospensione-servizio-di-raccolta-6-gennaio-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2023\\\/01\\\/04\\\/sospensione-servizio-di-raccolta-6-gennaio-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2023\\\/01\\\/Cestini-raccolta-differenziata-min.jpg\",\"datePublished\":\"2023-01-04T10:14:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2023\\\/01\\\/04\\\/sospensione-servizio-di-raccolta-6-gennaio-2023\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2023\\\/01\\\/04\\\/sospensione-servizio-di-raccolta-6-gennaio-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2023\\\/01\\\/04\\\/sospensione-servizio-di-raccolta-6-gennaio-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2023\\\/01\\\/Cestini-raccolta-differenziata-min.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2023\\\/01\\\/Cestini-raccolta-differenziata-min.jpg\",\"width\":1281,\"height\":981},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2023\\\/01\\\/04\\\/sospensione-servizio-di-raccolta-6-gennaio-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SOSPENSIONE SERVIZIO DI RACCOLTA 6 GENNAIO 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"name\":\"San Vittore del Lazio\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":null,\"contentUrl\":null,\"width\":724,\"height\":1024,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\",\"name\":\"nadiabucci\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"caption\":\"nadiabucci\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/author\\\/nadiabucci\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SOSPENSIONE SERVIZIO DI RACCOLTA 6 GENNAIO 2023 - San Vittore del Lazio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/","og_locale":"it_IT","og_type":"article","og_title":"SOSPENSIONE SERVIZIO DI RACCOLTA 6 GENNAIO 2023 - San Vittore del Lazio","og_description":"SOSPENSIONE RACCOLTA INDIFFERENZIATA PER IL 06.01.2023. LA RACCCOLTA VERRA&#8217; POSTICIPATA AL GIORNO 07.01.2023","og_url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/","og_site_name":"San Vittore del Lazio","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2023-01-04T10:14:49+00:00","og_image":[{"width":1281,"height":981,"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2023\/01\/Cestini-raccolta-differenziata-min.jpg","type":"image\/jpeg"}],"author":"nadiabucci","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"nadiabucci","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/"},"author":{"name":"nadiabucci","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573"},"headline":"SOSPENSIONE SERVIZIO DI RACCOLTA 6 GENNAIO 2023","datePublished":"2023-01-04T10:14:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/"},"wordCount":16,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2023\/01\/Cestini-raccolta-differenziata-min.jpg","articleSection":["Interruzione di Servizio"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/","name":"SOSPENSIONE SERVIZIO DI RACCOLTA 6 GENNAIO 2023 - San Vittore del Lazio","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2023\/01\/Cestini-raccolta-differenziata-min.jpg","datePublished":"2023-01-04T10:14:49+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/#primaryimage","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2023\/01\/Cestini-raccolta-differenziata-min.jpg","contentUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2023\/01\/Cestini-raccolta-differenziata-min.jpg","width":1281,"height":981},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2023\/01\/04\/sospensione-servizio-di-raccolta-6-gennaio-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanvittoredellazio\/"},{"@type":"ListItem","position":2,"name":"SOSPENSIONE SERVIZIO DI RACCOLTA 6 GENNAIO 2023"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","name":"San Vittore del Lazio","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanvittoredellazio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/","url":null,"contentUrl":null,"width":724,"height":1024,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573","name":"nadiabucci","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","caption":"nadiabucci"},"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/author\/nadiabucci\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"20113"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/20501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/users\/374"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/comments?post=20501"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/20501\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media\/20502"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media?parent=20501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/categories?post=20501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/tags?post=20501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}