{"id":21894,"date":"2026-03-12T16:37:40","date_gmt":"2026-03-12T15:37:40","guid":{"rendered":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/"},"modified":"2026-03-12T16:37:40","modified_gmt":"2026-03-12T15:37:40","slug":"tessere-elettorali","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/","title":{"rendered":"Tessere elettorali"},"content":{"rendered":"<p><em>Orari di apertura al pubblico per rilascio tessere elettorali.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>In vista delle imminenti\u00a0<b>ELEZIONI REFERENDARIE del 22 e 23 MARZO p.v<\/b>. si invitano gli elettori a verificare per tempo che siano in possesso della tessera elettorale personale e che sulla stessa non siano esauriti gli spazi destinati all\u2019apposizione del bollo della sezione per la certificazione del voto.<br \/>\nSi comunica pertanto che per il rilascio delle tessere l\u2019Ufficio Elettorale seguir\u00e0 gli orari coma riportati sul prospetto allegato.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_21896\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/03\/ORARIO-APERTURA-STAMPA-TESSERE.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/03\/ORARIO-APERTURA-STAMPA-TESSERE.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ORARIO APERTURA STAMPA TESSERE<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Orari di apertura al pubblico per rilascio tessere elettorali.&nbsp; Descrizione&nbsp; In vista delle imminenti\u00a0ELEZIONI REFERENDARIE del 22 e 23 MARZO p.v. si invitano gli elettori a verificare per tempo che [&hellip;]<\/p>\n","protected":false},"author":374,"featured_media":21895,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-21894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tessere elettorali - San Vittore del Lazio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tessere elettorali - San Vittore del Lazio\" \/>\n<meta property=\"og:description\" content=\"Orari di apertura al pubblico per rilascio tessere elettorali.&nbsp; Descrizione&nbsp; In vista delle imminenti\u00a0ELEZIONI REFERENDARIE del 22 e 23 MARZO p.v. si invitano gli elettori a verificare per tempo che [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/\" \/>\n<meta property=\"og:site_name\" content=\"San Vittore del Lazio\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-12T15:37:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/03\/tessera-elettorale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nadiabucci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"nadiabucci\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/03\\\/12\\\/tessere-elettorali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/03\\\/12\\\/tessere-elettorali\\\/\"},\"author\":{\"name\":\"nadiabucci\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\"},\"headline\":\"Tessere elettorali\",\"datePublished\":\"2026-03-12T15:37:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/03\\\/12\\\/tessere-elettorali\\\/\"},\"wordCount\":82,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/03\\\/12\\\/tessere-elettorali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2026\\\/03\\\/tessera-elettorale.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/03\\\/12\\\/tessere-elettorali\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/03\\\/12\\\/tessere-elettorali\\\/\",\"name\":\"Tessere elettorali - San Vittore del Lazio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/03\\\/12\\\/tessere-elettorali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/03\\\/12\\\/tessere-elettorali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2026\\\/03\\\/tessera-elettorale.png\",\"datePublished\":\"2026-03-12T15:37:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/03\\\/12\\\/tessere-elettorali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/03\\\/12\\\/tessere-elettorali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/03\\\/12\\\/tessere-elettorali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2026\\\/03\\\/tessera-elettorale.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2026\\\/03\\\/tessera-elettorale.png\",\"width\":640,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/03\\\/12\\\/tessere-elettorali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tessere elettorali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"name\":\"San Vittore del Lazio\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":null,\"contentUrl\":null,\"width\":724,\"height\":1024,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\",\"name\":\"nadiabucci\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"caption\":\"nadiabucci\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/author\\\/nadiabucci\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tessere elettorali - San Vittore del Lazio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/","og_locale":"it_IT","og_type":"article","og_title":"Tessere elettorali - San Vittore del Lazio","og_description":"Orari di apertura al pubblico per rilascio tessere elettorali.&nbsp; Descrizione&nbsp; In vista delle imminenti\u00a0ELEZIONI REFERENDARIE del 22 e 23 MARZO p.v. si invitano gli elettori a verificare per tempo che [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/","og_site_name":"San Vittore del Lazio","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-03-12T15:37:40+00:00","og_image":[{"width":640,"height":400,"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/03\/tessera-elettorale.png","type":"image\/png"}],"author":"nadiabucci","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"nadiabucci"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/"},"author":{"name":"nadiabucci","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573"},"headline":"Tessere elettorali","datePublished":"2026-03-12T15:37:40+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/"},"wordCount":82,"publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/03\/tessera-elettorale.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/","name":"Tessere elettorali - San Vittore del Lazio","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/03\/tessera-elettorale.png","datePublished":"2026-03-12T15:37:40+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/#primaryimage","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/03\/tessera-elettorale.png","contentUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/03\/tessera-elettorale.png","width":640,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/03\/12\/tessere-elettorali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanvittoredellazio\/"},{"@type":"ListItem","position":2,"name":"Tessere elettorali"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","name":"San Vittore del Lazio","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanvittoredellazio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/","url":null,"contentUrl":null,"width":724,"height":1024,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573","name":"nadiabucci","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","caption":"nadiabucci"},"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/author\/nadiabucci\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00003736"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/21894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/users\/374"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/comments?post=21894"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/21894\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media\/21895"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media?parent=21894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/categories?post=21894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/tags?post=21894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}