{"id":21928,"date":"2026-04-08T09:38:51","date_gmt":"2026-04-08T07:38:51","guid":{"rendered":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/"},"modified":"2026-04-08T09:38:51","modified_gmt":"2026-04-08T07:38:51","slug":"ordinanza-n-06-del-07-04-2026","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/","title":{"rendered":"Ordinanza n. 06 del 07.04.2026"},"content":{"rendered":"<p><em>Chiusura Plesso scolastico via G. Marconi<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><strong>Chiusura per la giornata del 09 aprile 2026 della scuola dell\u2019infanzia, primaria e secondaria di primo grado del plesso Capoluogo di Via G. Marconi in San Vittore del Lazio.<\/strong><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_21930\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/04\/ORDINANZA-N.-06-26.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/04\/ORDINANZA-N.-06-26.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ORDINANZA N. 06-26<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Chiusura Plesso scolastico via G. Marconi&nbsp; Descrizione&nbsp; Chiusura per la giornata del 09 aprile 2026 della scuola dell\u2019infanzia, primaria e secondaria di primo grado del plesso Capoluogo di Via G. [&hellip;]<\/p>\n","protected":false},"author":374,"featured_media":21929,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-21928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ordinanza n. 06 del 07.04.2026 - San Vittore del Lazio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ordinanza n. 06 del 07.04.2026 - San Vittore del Lazio\" \/>\n<meta property=\"og:description\" content=\"Chiusura Plesso scolastico via G. Marconi&nbsp; Descrizione&nbsp; Chiusura per la giornata del 09 aprile 2026 della scuola dell\u2019infanzia, primaria e secondaria di primo grado del plesso Capoluogo di Via G. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"San Vittore del Lazio\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-08T07:38:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/04\/ordinanza_sindacale-32.png\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nadiabucci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"nadiabucci\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/04\\\/08\\\/ordinanza-n-06-del-07-04-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/04\\\/08\\\/ordinanza-n-06-del-07-04-2026\\\/\"},\"author\":{\"name\":\"nadiabucci\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\"},\"headline\":\"Ordinanza n. 06 del 07.04.2026\",\"datePublished\":\"2026-04-08T07:38:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/04\\\/08\\\/ordinanza-n-06-del-07-04-2026\\\/\"},\"wordCount\":40,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/04\\\/08\\\/ordinanza-n-06-del-07-04-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2026\\\/04\\\/ordinanza_sindacale-32.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/04\\\/08\\\/ordinanza-n-06-del-07-04-2026\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/04\\\/08\\\/ordinanza-n-06-del-07-04-2026\\\/\",\"name\":\"Ordinanza n. 06 del 07.04.2026 - San Vittore del Lazio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/04\\\/08\\\/ordinanza-n-06-del-07-04-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/04\\\/08\\\/ordinanza-n-06-del-07-04-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2026\\\/04\\\/ordinanza_sindacale-32.png\",\"datePublished\":\"2026-04-08T07:38:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/04\\\/08\\\/ordinanza-n-06-del-07-04-2026\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/04\\\/08\\\/ordinanza-n-06-del-07-04-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/04\\\/08\\\/ordinanza-n-06-del-07-04-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2026\\\/04\\\/ordinanza_sindacale-32.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2026\\\/04\\\/ordinanza_sindacale-32.png\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2026\\\/04\\\/08\\\/ordinanza-n-06-del-07-04-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ordinanza n. 06 del 07.04.2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"name\":\"San Vittore del Lazio\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":null,\"contentUrl\":null,\"width\":724,\"height\":1024,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\",\"name\":\"nadiabucci\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"caption\":\"nadiabucci\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/author\\\/nadiabucci\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ordinanza n. 06 del 07.04.2026 - San Vittore del Lazio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/","og_locale":"it_IT","og_type":"article","og_title":"Ordinanza n. 06 del 07.04.2026 - San Vittore del Lazio","og_description":"Chiusura Plesso scolastico via G. Marconi&nbsp; Descrizione&nbsp; Chiusura per la giornata del 09 aprile 2026 della scuola dell\u2019infanzia, primaria e secondaria di primo grado del plesso Capoluogo di Via G. [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/","og_site_name":"San Vittore del Lazio","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-04-08T07:38:51+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/04\/ordinanza_sindacale-32.png","type":"image\/png"}],"author":"nadiabucci","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"nadiabucci"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/"},"author":{"name":"nadiabucci","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573"},"headline":"Ordinanza n. 06 del 07.04.2026","datePublished":"2026-04-08T07:38:51+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/"},"wordCount":40,"publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/04\/ordinanza_sindacale-32.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/","name":"Ordinanza n. 06 del 07.04.2026 - San Vittore del Lazio","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/04\/ordinanza_sindacale-32.png","datePublished":"2026-04-08T07:38:51+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/#primaryimage","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/04\/ordinanza_sindacale-32.png","contentUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2026\/04\/ordinanza_sindacale-32.png","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2026\/04\/08\/ordinanza-n-06-del-07-04-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanvittoredellazio\/"},{"@type":"ListItem","position":2,"name":"Ordinanza n. 06 del 07.04.2026"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","name":"San Vittore del Lazio","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanvittoredellazio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/","url":null,"contentUrl":null,"width":724,"height":1024,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573","name":"nadiabucci","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","caption":"nadiabucci"},"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/author\/nadiabucci\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00003765"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/21928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/users\/374"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/comments?post=21928"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/21928\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media\/21929"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media?parent=21928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/categories?post=21928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/tags?post=21928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}