{"id":295,"date":"2021-04-21T08:42:32","date_gmt":"2021-04-21T06:42:32","guid":{"rendered":"https:\/\/comunicacity.net\/sanvittoredellazio\/?p=295"},"modified":"2021-04-21T08:42:32","modified_gmt":"2021-04-21T06:42:32","slug":"contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/","title":{"rendered":"Contributo agli alunni con disabilit\u00e0 residenti nel Comune di San Vittore del Lazio"},"content":{"rendered":"<h2><strong>Contributo agli alunni con disabilit\u00e0 residenti nel comune di San Vittore del Lazio per l\u2019acquisto di materiali e servizi idonei ad agevolare la fruizione della didattica a distanza e della didattica digitale integrata (Anno Scolastico 2020\/2021)<\/strong><\/h2>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_296\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/04\/AVVISO-CONTRIBUTI-ALUNNI-CON-DISABILITA-PER-ACQUISTO-MATERIALI-DAD-E-DDI.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/04\/AVVISO-CONTRIBUTI-ALUNNI-CON-DISABILITA-PER-ACQUISTO-MATERIALI-DAD-E-DDI.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>AVVISO-CONTRIBUTI-ALUNNI-CON-DISABILITA-PER-ACQUISTO-MATERIALI-DAD-E-DDI<\/a><\/li>\n<li><a id=\"wpba_attachment_list_297\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/04\/MODULO-DI-RICHIESTA.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/04\/MODULO-DI-RICHIESTA.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>MODULO-DI-RICHIESTA<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Contributo agli alunni con disabilit\u00e0 residenti nel comune di San Vittore del Lazio per l\u2019acquisto di materiali e servizi idonei ad agevolare la fruizione della didattica a distanza e della [&hellip;]<\/p>\n","protected":false},"author":374,"featured_media":298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-295","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contributo agli alunni con disabilit\u00e0 residenti nel Comune di San Vittore del Lazio - San Vittore del Lazio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contributo agli alunni con disabilit\u00e0 residenti nel Comune di San Vittore del Lazio - San Vittore del Lazio\" \/>\n<meta property=\"og:description\" content=\"Contributo agli alunni con disabilit\u00e0 residenti nel comune di San Vittore del Lazio per l\u2019acquisto di materiali e servizi idonei ad agevolare la fruizione della didattica a distanza e della [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/\" \/>\n<meta property=\"og:site_name\" content=\"San Vittore del Lazio\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-21T06:42:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/04\/didattica-a-distanza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nadiabucci\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"nadiabucci\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/04\\\/21\\\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/04\\\/21\\\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\\\/\"},\"author\":{\"name\":\"nadiabucci\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\"},\"headline\":\"Contributo agli alunni con disabilit\u00e0 residenti nel Comune di San Vittore del Lazio\",\"datePublished\":\"2021-04-21T06:42:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/04\\\/21\\\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\\\/\"},\"wordCount\":49,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/04\\\/21\\\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2021\\\/04\\\/didattica-a-distanza.jpg\",\"articleSection\":[\"Cultura\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/04\\\/21\\\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/04\\\/21\\\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\\\/\",\"name\":\"Contributo agli alunni con disabilit\u00e0 residenti nel Comune di San Vittore del Lazio - San Vittore del Lazio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/04\\\/21\\\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/04\\\/21\\\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2021\\\/04\\\/didattica-a-distanza.jpg\",\"datePublished\":\"2021-04-21T06:42:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/04\\\/21\\\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/04\\\/21\\\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/04\\\/21\\\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2021\\\/04\\\/didattica-a-distanza.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2021\\\/04\\\/didattica-a-distanza.jpg\",\"width\":800,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/2021\\\/04\\\/21\\\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contributo agli alunni con disabilit\u00e0 residenti nel Comune di San Vittore del Lazio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"name\":\"San Vittore del Lazio\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":null,\"contentUrl\":null,\"width\":724,\"height\":1024,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/person\\\/3f272235608749ad388742bfaae7b573\",\"name\":\"nadiabucci\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g\",\"caption\":\"nadiabucci\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/author\\\/nadiabucci\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contributo agli alunni con disabilit\u00e0 residenti nel Comune di San Vittore del Lazio - San Vittore del Lazio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/","og_locale":"it_IT","og_type":"article","og_title":"Contributo agli alunni con disabilit\u00e0 residenti nel Comune di San Vittore del Lazio - San Vittore del Lazio","og_description":"Contributo agli alunni con disabilit\u00e0 residenti nel comune di San Vittore del Lazio per l\u2019acquisto di materiali e servizi idonei ad agevolare la fruizione della didattica a distanza e della [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/","og_site_name":"San Vittore del Lazio","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2021-04-21T06:42:32+00:00","og_image":[{"width":800,"height":530,"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/04\/didattica-a-distanza.jpg","type":"image\/jpeg"}],"author":"nadiabucci","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"nadiabucci"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/"},"author":{"name":"nadiabucci","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573"},"headline":"Contributo agli alunni con disabilit\u00e0 residenti nel Comune di San Vittore del Lazio","datePublished":"2021-04-21T06:42:32+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/"},"wordCount":49,"publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/04\/didattica-a-distanza.jpg","articleSection":["Cultura"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/","name":"Contributo agli alunni con disabilit\u00e0 residenti nel Comune di San Vittore del Lazio - San Vittore del Lazio","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/04\/didattica-a-distanza.jpg","datePublished":"2021-04-21T06:42:32+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/#primaryimage","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/04\/didattica-a-distanza.jpg","contentUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2021\/04\/didattica-a-distanza.jpg","width":800,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/2021\/04\/21\/contributo-agli-alunni-con-disabilita-residenti-nel-comune-di-san-vittore-del-lazio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanvittoredellazio\/"},{"@type":"ListItem","position":2,"name":"Contributo agli alunni con disabilit\u00e0 residenti nel Comune di San Vittore del Lazio"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","name":"San Vittore del Lazio","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanvittoredellazio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/","url":null,"contentUrl":null,"width":724,"height":1024,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/person\/3f272235608749ad388742bfaae7b573","name":"nadiabucci","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a78059d9734f48ca7deea57a928561d6e509ba9983ecd35b38ec37896365a9ed?s=96&d=mm&r=g","caption":"nadiabucci"},"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/author\/nadiabucci\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/users\/374"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/comments?post=295"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/295\/revisions"}],"predecessor-version":[{"id":299,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/posts\/295\/revisions\/299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media\/298"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media?parent=295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/categories?post=295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/tags?post=295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}