{"id":40,"date":"2020-07-09T16:30:45","date_gmt":"2020-07-09T14:30:45","guid":{"rendered":"https:\/\/comunicacity.net\/sanvittoredellazio\/?post_type=turismo&#038;p=40"},"modified":"2020-09-22T11:56:40","modified_gmt":"2020-09-22T09:56:40","slug":"una-breve-sintesi-del-paese","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/sanvittoredellazio\/turismo\/una-breve-sintesi-del-paese\/","title":{"rendered":"Una breve sintesi del paese"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-130\" src=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2020\/07\/Panorama-del-centro-storico-con-la-torre-campanaria-della-Chiesa-di-Santa-maria-della-rosa-la-Torre-Civica-al-centro-dellimmagine-e-il-campanile.jpg\" alt=\"\" width=\"740\" height=\"557\" srcset=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2020\/07\/Panorama-del-centro-storico-con-la-torre-campanaria-della-Chiesa-di-Santa-maria-della-rosa-la-Torre-Civica-al-centro-dellimmagine-e-il-campanile.jpg 740w, https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2020\/07\/Panorama-del-centro-storico-con-la-torre-campanaria-della-Chiesa-di-Santa-maria-della-rosa-la-Torre-Civica-al-centro-dellimmagine-e-il-campanile-300x226.jpg 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/p>\n<p class=\"text_verdana_10px_regolare_giustificato_marginato_black\">Il Comune di S. Vittore del Lazio, situato all\u2019estremo sud della Provincia di Frosinone, \u00e8 uno dei Comuni che fa parte\u00a0della XV^ Comunit\u00e0 Montana Valle del Liri e della zona del Cassinate.<\/p>\n<p>Occupa una posizione geografica strategica, poich\u00e9 costituisce il punto di passaggio obbligato per le province di Latina, Caserta ed Isernia, essendo punto di snodo della grande viabilit\u00e0 come la SR Casilina e l\u2019Autostrada del Sole.<br \/>\nIn particolare, il Casello Autostradale \u201cS.VITTORE\u201d \u00e8 di primaria importanza per i collegamenti Roma-Napoli con Alto Casertano, il Molise ed il Medio Adriatico (Isernia, Roccaraso, Campobasso, Vasto, Termoli).<br \/>\nInoltre, \u00e8 punto di interscambio della tratta ferroviaria Roma-Napoli con la linea Venafro-Isernia ed \u00e8 sede dell\u2019interconnessione della linea Treno Alta Velocit\u00e0.<\/p>\n<p>Il territorio comunale \u00e8 costituito da un\u2019ampia area montana e forestale (la popolosa Contrada di montagna Radicosa, Monte Sammucro, Loc. Muraglie), dalla zona collinare del Centro Storico e di Collemeroni, dalla fascia pedemontana a monte della S.R.Casilina e dalla parte a valle di pianura attraversata dalla S.S. 430 Valle del Garigliano fino all\u2019Autostrada del Sole in Localit\u00e0 S. Cesario.<\/p>\n<p>Il Comune di S. Vittore del Lazio vanta tradizioni storiche e culturali di tutto rispetto. La\u00a0 nascita dell\u2019attuale paese risale al processo d\u2019incastellamento e al ripopolamento effettuato dai monaci di Montecassino nel X secolo dopo le distruzioni saracene.<\/p>\n<p>La sua origine medioevale \u00e8 testimoniata dai resti della cinta muraria del castello con 23 torri rotonde e quadrate (alcune sono ancora ben visibili) ed un arco a sesto acuto, antica porta d\u2019ingresso al castello sita in Piazza Municipio.<br \/>\nL\u2019impianto del castello \u00e8 ben riconoscibile e la fortificazione del versante ovest si pu\u00f2 apprezzare percorrendo la Strada Provinciale di collegamento con Cervaro.<\/p>\n<p class=\"text_verdana_10px_regolare_giustificato_marginato_black\">Il centro storico conserva vicoli caratteristici, tipici dell\u2019impianto medioevale, con archi e fregi di portoni di antichi casati; pu\u00f2 essere visitata percorrendo l\u2019anello di Via Castello con i relativi vicoli, che talvolta permettono il collegamento tra i due rami della strada.<\/p>\n<p class=\"text_verdana_10px_regolare_giustificato_marginato_black\">La Piazza Municipio, cos\u00ec denominata per la presenza della Casa Comunale con la facciata in stile \u2018700, con l\u2019arco a sesto acuto e la caratteristica fontana in pietra del tardo 1800, rappresenta il punto nodale che unisce l\u2019impianto dell\u2019incastellamento al Borgo dei Greci ed \u00e8 tradizionale luogo di incontro del Centro Storico.<\/p>\n<p class=\"text_verdana_10px_regolare_giustificato_marginato_black\">Al di fuori delle mura del Castello, nell\u2019alto medioevo si insedi\u00f2 una ricca colonia di Greci con due proprie chiese: S. Basilio (ormai scomparsa completamente), che si affacciava sull\u2019antica\u00a0 Via dei Greci,\u00a0 e\u00a0\u00a0 S. Nicola, esistente e completamente restaurata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di S. Vittore del Lazio, situato all\u2019estremo sud della Provincia di Frosinone, \u00e8 uno dei Comuni che fa parte\u00a0della XV^ Comunit\u00e0 Montana Valle del Liri e della zona [&hellip;]<\/p>\n","protected":false},"featured_media":0,"parent":0,"menu_order":2,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-40","turismo","type-turismo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una breve sintesi del paese - San Vittore del Lazio<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanvittoredellazio\/turismo\/una-breve-sintesi-del-paese\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una breve sintesi del paese - San Vittore del Lazio\" \/>\n<meta property=\"og:description\" content=\"Il Comune di S. Vittore del Lazio, situato all\u2019estremo sud della Provincia di Frosinone, \u00e8 uno dei Comuni che fa parte\u00a0della XV^ Comunit\u00e0 Montana Valle del Liri e della zona [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/turismo\/una-breve-sintesi-del-paese\/\" \/>\n<meta property=\"og:site_name\" content=\"San Vittore del Lazio\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-22T09:56:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2020\/07\/Panorama-del-centro-storico-con-la-torre-campanaria-della-Chiesa-di-Santa-maria-della-rosa-la-Torre-Civica-al-centro-dellimmagine-e-il-campanile.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/turismo\\\/una-breve-sintesi-del-paese\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/turismo\\\/una-breve-sintesi-del-paese\\\/\",\"name\":\"Una breve sintesi del paese - San Vittore del Lazio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/turismo\\\/una-breve-sintesi-del-paese\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/turismo\\\/una-breve-sintesi-del-paese\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2020\\\/07\\\/Panorama-del-centro-storico-con-la-torre-campanaria-della-Chiesa-di-Santa-maria-della-rosa-la-Torre-Civica-al-centro-dellimmagine-e-il-campanile.jpg\",\"datePublished\":\"2020-07-09T14:30:45+00:00\",\"dateModified\":\"2020-09-22T09:56:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/turismo\\\/una-breve-sintesi-del-paese\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/turismo\\\/una-breve-sintesi-del-paese\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/turismo\\\/una-breve-sintesi-del-paese\\\/#primaryimage\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2020\\\/07\\\/Panorama-del-centro-storico-con-la-torre-campanaria-della-Chiesa-di-Santa-maria-della-rosa-la-Torre-Civica-al-centro-dellimmagine-e-il-campanile.jpg\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/wp-content\\\/uploads\\\/sites\\\/193\\\/2020\\\/07\\\/Panorama-del-centro-storico-con-la-torre-campanaria-della-Chiesa-di-Santa-maria-della-rosa-la-Torre-Civica-al-centro-dellimmagine-e-il-campanile.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/turismo\\\/una-breve-sintesi-del-paese\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una breve sintesi del paese\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"name\":\"San Vittore del Lazio\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":null,\"contentUrl\":null,\"width\":724,\"height\":1024,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanvittoredellazio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una breve sintesi del paese - San Vittore del Lazio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanvittoredellazio\/turismo\/una-breve-sintesi-del-paese\/","og_locale":"it_IT","og_type":"article","og_title":"Una breve sintesi del paese - San Vittore del Lazio","og_description":"Il Comune di S. Vittore del Lazio, situato all\u2019estremo sud della Provincia di Frosinone, \u00e8 uno dei Comuni che fa parte\u00a0della XV^ Comunit\u00e0 Montana Valle del Liri e della zona [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanvittoredellazio\/turismo\/una-breve-sintesi-del-paese\/","og_site_name":"San Vittore del Lazio","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2020-09-22T09:56:40+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2020\/07\/Panorama-del-centro-storico-con-la-torre-campanaria-della-Chiesa-di-Santa-maria-della-rosa-la-Torre-Civica-al-centro-dellimmagine-e-il-campanile.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/turismo\/una-breve-sintesi-del-paese\/","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/turismo\/una-breve-sintesi-del-paese\/","name":"Una breve sintesi del paese - San Vittore del Lazio","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/turismo\/una-breve-sintesi-del-paese\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/turismo\/una-breve-sintesi-del-paese\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2020\/07\/Panorama-del-centro-storico-con-la-torre-campanaria-della-Chiesa-di-Santa-maria-della-rosa-la-Torre-Civica-al-centro-dellimmagine-e-il-campanile.jpg","datePublished":"2020-07-09T14:30:45+00:00","dateModified":"2020-09-22T09:56:40+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/turismo\/una-breve-sintesi-del-paese\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanvittoredellazio\/turismo\/una-breve-sintesi-del-paese\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/turismo\/una-breve-sintesi-del-paese\/#primaryimage","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2020\/07\/Panorama-del-centro-storico-con-la-torre-campanaria-della-Chiesa-di-Santa-maria-della-rosa-la-Torre-Civica-al-centro-dellimmagine-e-il-campanile.jpg","contentUrl":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-content\/uploads\/sites\/193\/2020\/07\/Panorama-del-centro-storico-con-la-torre-campanaria-della-Chiesa-di-Santa-maria-della-rosa-la-Torre-Civica-al-centro-dellimmagine-e-il-campanile.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/turismo\/una-breve-sintesi-del-paese\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanvittoredellazio\/"},{"@type":"ListItem","position":2,"name":"Una breve sintesi del paese"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#website","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","name":"San Vittore del Lazio","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanvittoredellazio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanvittoredellazio\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/","url":null,"contentUrl":null,"width":724,"height":1024,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanvittoredellazio\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/turismo\/40","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/types\/turismo"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/media?parent=40"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/sanvittoredellazio\/wp-json\/wp\/v2\/plugin_turismo?post=40"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}