{"id":17895,"date":"2024-12-18T10:00:21","date_gmt":"2024-12-18T09:00:21","guid":{"rendered":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/"},"modified":"2024-12-18T11:02:10","modified_gmt":"2024-12-18T10:02:10","slug":"convocazione-consiglio-comunale-in-sessione-ordinaria-4","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/","title":{"rendered":"Convocazione Consiglio Comunale in sessione Ordinaria"},"content":{"rendered":"<p><em>Convocazione Consiglio Comunale in sessione ordinaria ed in seduta Pubblica di Prima Convocazione il 23\/12\/2024 alle ore 19:30<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p style=\"text-align: right\"><strong>Ai Consiglieri Comunali<\/strong><br \/>\n<strong>Ai Responsabili di Servizio<\/strong><br \/>\n<strong>Al Segretario Comunale<\/strong><br \/>\n<strong>Sede <\/strong><\/p>\n<p><em><strong>Oggetto: Convocazione Consiglio Comunale in sessione Ordinaria.<\/strong><\/em><\/p>\n<p style=\"text-align: center\"><strong>Il Sindaco<\/strong><\/p>\n<p style=\"text-align: left\">Visto il T.U. Ordinamento Enti locali approvato con D.lgs. 18 agosto 2000, n. 267, e successive modifiche ed integrazione;<br \/>\nRichiamato il vigente Statuto Comunale;<\/p>\n<p style=\"text-align: center\"><strong>convoca<\/strong><\/p>\n<p style=\"text-align: left\">il Consiglio Comunale in sessione ordinaria ed in seduta Pubblica di Prima Convocazione nella sala delle adunanze del Comune in Piazza XXIV Maggio per il giorno 23 dicembre 2024, alle ore 19:30 per la trattazione del seguente ordine del giorno:<br \/>\n1. Approvazione verbali sedute precedenti;<br \/>\n2. Imposta Municipale Propria (IMU)_ Approvazione aliquote anno d&#8217;imposta 2025<br \/>\n3. Approvazione delle tariffe della tassa sui rifiuti (TARI) anno 2025_ Adempimenti<br \/>\n4. Servizio Idrico Integrato (SII)_ Approvazione PEF e Piano Tariffario anno 2025<br \/>\n5. Ricognizione periodica delle partecipazioni pubbliche detenute al 31 dicembre 2023 ex art. 20 D.Lgs 19 agosto 2016, n. 175, cos\u00ec come modificato ed integrato dal D.Lgs. 16 giugno 2017, n.1000. Determinazioni<br \/>\n6. Esercizio Finanziario 2025\/2027 Determinazione prezzi di cessione Aree per l&#8217;edilizia economica e Popolare, per gli insediamenti Produttivi e Terziari delle Aree e dei fabbricati da cedere in propriet\u00e0 o in Diritto di Superficie. Provvedimenti Variazione di Bilancio &#8211; Ratifica di consiglio;<br \/>\n7. Approvazione &#8220;Piano delle Alienazione e valorizzazione dei Beni Immobili di propriet\u00e0 Comunale per l&#8217;anno 2025&#8221;;<br \/>\n8. Variazione N. 5 al Bilancio di Previsione 2024-2026 ed agli atti programmatori connessi e collegati allo stesso. Pro Consiglio. Ratifica delibera di Giunta comunale n. 72 del 25.11.2024<br \/>\n9. Adozione del Documento Unico di Programmazione Semplificato (DUPS) 2025 &#8211; 2026 -2027<br \/>\n10. Approvazione del Bilancio di Previsione Finanziaria 2025 &#8211; 2027 (Art. 11 D. Lgs. 118\/2011)<br \/>\n11. Adozione programma triennale dei lavori pubblici e degli acquisti di beni e servizi anni 2025\/2027<br \/>\n12. SAD Ecodiano &#8211; Adozione modifiche della convenzione vigente stipulata in data 19.05.2022<\/p>\n<p>Sanza, li 18 dicembre 2024<\/p>\n<p>Il Sindaco<br \/>\nDott. Vittorio ESPOSITO<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_17900\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2024\/12\/KM_C36824121809580-1.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2024\/12\/KM_C36824121809580-1.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>KM_C36824121809580<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Convocazione Consiglio Comunale in sessione ordinaria ed in seduta Pubblica di Prima Convocazione il 23\/12\/2024 alle ore 19:30&nbsp; Descrizione&nbsp; Ai Consiglieri Comunali Ai Responsabili di Servizio Al Segretario Comunale Sede [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17899,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-17895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Convocazione Consiglio Comunale in sessione Ordinaria - Sanza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Convocazione Consiglio Comunale in sessione Ordinaria - Sanza\" \/>\n<meta property=\"og:description\" content=\"Convocazione Consiglio Comunale in sessione ordinaria ed in seduta Pubblica di Prima Convocazione il 23\/12\/2024 alle ore 19:30&nbsp; Descrizione&nbsp; Ai Consiglieri Comunali Ai Responsabili di Servizio Al Segretario Comunale Sede [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Sanza\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-18T09:00:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-18T10:02:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2024\/12\/convocazione-consigli-comunali-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2024\\\/12\\\/18\\\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2024\\\/12\\\/18\\\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Convocazione Consiglio Comunale in sessione Ordinaria\",\"datePublished\":\"2024-12-18T09:00:21+00:00\",\"dateModified\":\"2024-12-18T10:02:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2024\\\/12\\\/18\\\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\\\/\"},\"wordCount\":295,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2024\\\/12\\\/18\\\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2024\\\/12\\\/convocazione-consigli-comunali-1.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2024\\\/12\\\/18\\\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2024\\\/12\\\/18\\\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\\\/\",\"name\":\"Convocazione Consiglio Comunale in sessione Ordinaria - Sanza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2024\\\/12\\\/18\\\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2024\\\/12\\\/18\\\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2024\\\/12\\\/convocazione-consigli-comunali-1.jpg\",\"datePublished\":\"2024-12-18T09:00:21+00:00\",\"dateModified\":\"2024-12-18T10:02:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2024\\\/12\\\/18\\\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2024\\\/12\\\/18\\\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2024\\\/12\\\/18\\\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2024\\\/12\\\/convocazione-consigli-comunali-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2024\\\/12\\\/convocazione-consigli-comunali-1.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2024\\\/12\\\/18\\\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Convocazione Consiglio Comunale in sessione Ordinaria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Convocazione Consiglio Comunale in sessione Ordinaria - Sanza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/","og_locale":"it_IT","og_type":"article","og_title":"Convocazione Consiglio Comunale in sessione Ordinaria - Sanza","og_description":"Convocazione Consiglio Comunale in sessione ordinaria ed in seduta Pubblica di Prima Convocazione il 23\/12\/2024 alle ore 19:30&nbsp; Descrizione&nbsp; Ai Consiglieri Comunali Ai Responsabili di Servizio Al Segretario Comunale Sede [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/","og_site_name":"Sanza","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-12-18T09:00:21+00:00","article_modified_time":"2024-12-18T10:02:10+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2024\/12\/convocazione-consigli-comunali-1.jpg","type":"image\/jpeg"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Convocazione Consiglio Comunale in sessione Ordinaria","datePublished":"2024-12-18T09:00:21+00:00","dateModified":"2024-12-18T10:02:10+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/"},"wordCount":295,"publisher":{"@id":"https:\/\/comunicacity.net\/sanza\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2024\/12\/convocazione-consigli-comunali-1.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/","url":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/","name":"Convocazione Consiglio Comunale in sessione Ordinaria - Sanza","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanza\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2024\/12\/convocazione-consigli-comunali-1.jpg","datePublished":"2024-12-18T09:00:21+00:00","dateModified":"2024-12-18T10:02:10+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/#primaryimage","url":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2024\/12\/convocazione-consigli-comunali-1.jpg","contentUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2024\/12\/convocazione-consigli-comunali-1.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanza\/2024\/12\/18\/convocazione-consiglio-comunale-in-sessione-ordinaria-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanza\/"},{"@type":"ListItem","position":2,"name":"Convocazione Consiglio Comunale in sessione Ordinaria"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanza\/#website","url":"https:\/\/comunicacity.net\/sanza\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanza\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanza\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanza\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001674"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts\/17895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/comments?post=17895"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts\/17895\/revisions"}],"predecessor-version":[{"id":17898,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts\/17895\/revisions\/17898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/media\/17899"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/media?parent=17895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/categories?post=17895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/tags?post=17895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}