{"id":18068,"date":"2025-07-10T13:04:55","date_gmt":"2025-07-10T11:04:55","guid":{"rendered":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/"},"modified":"2025-07-10T13:04:55","modified_gmt":"2025-07-10T11:04:55","slug":"rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/","title":{"rendered":"Rettifica per mero errore materiale &#8211;  Procedura di selezione finalizzata utilizzo graduatorie di concorsi pubblici di altri enti per l&#8217;assunzione di 1 unit\u00e0 a tempo parziale e indeterminato con profilo professionale agente di polizia locale area istruttori (ex cat. C1)"},"content":{"rendered":"<p><em>Ordine graduatoria COGNOME E NOME Punteggio complessivamente ottenuto<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><strong>RETTIFICA PER MERO ERRORE MATERIALE<\/strong><br \/>\n<strong>PROCEDURA DI SELEZIONE FINALIZZATA UTILIZZO GRADUATORIE DI CONCORSI PUBBLICI DI ALTRI ENTI PER L&#8217;ASSUNZIONE DI 1 UNITA&#8217; A TEMPO PARZIALE (12\/36 ORE SETTIMANALI) E INDETERMINATO CON PROFILO PROFESSIONALE AGENTE DI POLIZIA LOCALE AREA ISTRUTTORI (EX CAT. C1).<\/strong><\/p>\n<p style=\"text-align: center\"><strong>GRADUATORIA FINALE<\/strong><\/p>\n<p>Ordine graduatoria &#8211; COGNOME E NOME &#8211; Punteggio complessivamente ottenuto<br \/>\n1 &#8211; Santoro Michela &#8211; 7\/10 (prova superata)<br \/>\n2 &#8211; Cretella Luca &#8211; 4\/10 (prova non superata)<br \/>\n3 &#8211; Parente Cosimo &#8211; 2\/10 (prova non superata)<\/p>\n<p>Sanza, l\u00ec 10 luglio 2025<\/p>\n<p>La Commissione<br \/>\nf.to Dott.ssa Barbara Mangiapane \u2013 Presidente<br \/>\nf.to Dott. Francesco Paolo &#8211; Componente esperto segretario verbalizzante<br \/>\nf.to Ing. Giuseppe D\u2019Angiolillo &#8211; Componente esperto<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_18070\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/GRADUATORIA-FINALE-RETTIFICATA.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/GRADUATORIA-FINALE-RETTIFICATA.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>GRADUATORIA FINALE RETTIFICATA<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ordine graduatoria COGNOME E NOME Punteggio complessivamente ottenuto&nbsp; Descrizione&nbsp; RETTIFICA PER MERO ERRORE MATERIALE PROCEDURA DI SELEZIONE FINALIZZATA UTILIZZO GRADUATORIE DI CONCORSI PUBBLICI DI ALTRI ENTI PER L&#8217;ASSUNZIONE DI 1 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-18068","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rettifica per mero errore materiale - Procedura di selezione finalizzata utilizzo graduatorie di concorsi pubblici di altri enti per l&#039;assunzione di 1 unit\u00e0 a tempo parziale e indeterminato con profilo professionale agente di polizia locale area istruttori (ex cat. C1) - Sanza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rettifica per mero errore materiale - Procedura di selezione finalizzata utilizzo graduatorie di concorsi pubblici di altri enti per l&#039;assunzione di 1 unit\u00e0 a tempo parziale e indeterminato con profilo professionale agente di polizia locale area istruttori (ex cat. C1) - Sanza\" \/>\n<meta property=\"og:description\" content=\"Ordine graduatoria COGNOME E NOME Punteggio complessivamente ottenuto&nbsp; Descrizione&nbsp; RETTIFICA PER MERO ERRORE MATERIALE PROCEDURA DI SELEZIONE FINALIZZATA UTILIZZO GRADUATORIE DI CONCORSI PUBBLICI DI ALTRI ENTI PER L&#8217;ASSUNZIONE DI 1 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/\" \/>\n<meta property=\"og:site_name\" content=\"Sanza\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-10T11:04:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/10\\\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/10\\\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Rettifica per mero errore materiale &#8211; Procedura di selezione finalizzata utilizzo graduatorie di concorsi pubblici di altri enti per l&#8217;assunzione di 1 unit\u00e0 a tempo parziale e indeterminato con profilo professionale agente di polizia locale area istruttori (ex cat. C1)\",\"datePublished\":\"2025-07-10T11:04:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/10\\\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\\\/\"},\"wordCount\":153,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/10\\\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/07\\\/cropped-Sanza.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/10\\\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/10\\\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\\\/\",\"name\":\"Rettifica per mero errore materiale - Procedura di selezione finalizzata utilizzo graduatorie di concorsi pubblici di altri enti per l'assunzione di 1 unit\u00e0 a tempo parziale e indeterminato con profilo professionale agente di polizia locale area istruttori (ex cat. C1) - Sanza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/10\\\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/10\\\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/07\\\/cropped-Sanza.png\",\"datePublished\":\"2025-07-10T11:04:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/10\\\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/10\\\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/10\\\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/07\\\/cropped-Sanza.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/07\\\/cropped-Sanza.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/10\\\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rettifica per mero errore materiale &#8211; Procedura di selezione finalizzata utilizzo graduatorie di concorsi pubblici di altri enti per l&#8217;assunzione di 1 unit\u00e0 a tempo parziale e indeterminato con profilo professionale agente di polizia locale area istruttori (ex cat. C1)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rettifica per mero errore materiale - Procedura di selezione finalizzata utilizzo graduatorie di concorsi pubblici di altri enti per l'assunzione di 1 unit\u00e0 a tempo parziale e indeterminato con profilo professionale agente di polizia locale area istruttori (ex cat. C1) - Sanza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/","og_locale":"it_IT","og_type":"article","og_title":"Rettifica per mero errore materiale - Procedura di selezione finalizzata utilizzo graduatorie di concorsi pubblici di altri enti per l'assunzione di 1 unit\u00e0 a tempo parziale e indeterminato con profilo professionale agente di polizia locale area istruttori (ex cat. C1) - Sanza","og_description":"Ordine graduatoria COGNOME E NOME Punteggio complessivamente ottenuto&nbsp; Descrizione&nbsp; RETTIFICA PER MERO ERRORE MATERIALE PROCEDURA DI SELEZIONE FINALIZZATA UTILIZZO GRADUATORIE DI CONCORSI PUBBLICI DI ALTRI ENTI PER L&#8217;ASSUNZIONE DI 1 [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/","og_site_name":"Sanza","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-07-10T11:04:55+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza.png","type":"image\/png"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Rettifica per mero errore materiale &#8211; Procedura di selezione finalizzata utilizzo graduatorie di concorsi pubblici di altri enti per l&#8217;assunzione di 1 unit\u00e0 a tempo parziale e indeterminato con profilo professionale agente di polizia locale area istruttori (ex cat. C1)","datePublished":"2025-07-10T11:04:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/"},"wordCount":153,"publisher":{"@id":"https:\/\/comunicacity.net\/sanza\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/","url":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/","name":"Rettifica per mero errore materiale - Procedura di selezione finalizzata utilizzo graduatorie di concorsi pubblici di altri enti per l'assunzione di 1 unit\u00e0 a tempo parziale e indeterminato con profilo professionale agente di polizia locale area istruttori (ex cat. C1) - Sanza","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanza\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza.png","datePublished":"2025-07-10T11:04:55+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/#primaryimage","url":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza.png","contentUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/10\/rettifica-per-mero-errore-materiale-procedura-di-selezione-finalizzata-utilizzo-graduatorie-di-concorsi-pubblici-di-altri-enti-per-lassunzione-di-1-unita-a-tempo-parziale-e-indeterminato-con-prof\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanza\/"},{"@type":"ListItem","position":2,"name":"Rettifica per mero errore materiale &#8211; Procedura di selezione finalizzata utilizzo graduatorie di concorsi pubblici di altri enti per l&#8217;assunzione di 1 unit\u00e0 a tempo parziale e indeterminato con profilo professionale agente di polizia locale area istruttori (ex cat. C1)"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanza\/#website","url":"https:\/\/comunicacity.net\/sanza\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanza\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanza\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanza\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001792"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts\/18068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/comments?post=18068"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts\/18068\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/media\/18069"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/media?parent=18068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/categories?post=18068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/tags?post=18068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}