{"id":18071,"date":"2025-07-14T11:38:36","date_gmt":"2025-07-14T09:38:36","guid":{"rendered":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/"},"modified":"2025-07-14T11:38:36","modified_gmt":"2025-07-14T09:38:36","slug":"destinazione-5-x-1000","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/","title":{"rendered":"Destinazione 5 x 1000"},"content":{"rendered":"<p><em>Relazione illustrativa del rendiconto della destinazione della quota del cinque per mille dell&#8217;IRPEF a sostegno delle attivit\u00e0 sociali svolte dal Comune di residenza del contribuente a gisutificazione dell&#8217;anno d&#8217;imposta 2022 anno finanziario 2023.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<h2>Relazione illustrativa del rendiconto della destinazione della quota del cinque per mille dell&#8217;IRPEF a sostegno delle attivit\u00e0 sociali svolte dal Comune di residenza del contribuente a gisutificazione dell&#8217;anno d&#8217;imposta 2022 anno finanziario 2023<\/h2>\n<p>(art. 12, decreto del Presidente del Consiglio dei ministri 23 aprile 2010 aggiornato con le istruzioni del Decreto del Presidente del Consiglio 7 luglio 2016)<\/p>\n<p>&#8230;segue negli allegati.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_18073\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/nota-illustrativa.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/nota-illustrativa.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>nota illustrativa<\/a><\/li>\n<li><a id=\"wpba_attachment_list_18074\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/rendiconto-cinque-per-mille.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/rendiconto-cinque-per-mille.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>rendiconto cinque per mille<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Relazione illustrativa del rendiconto della destinazione della quota del cinque per mille dell&#8217;IRPEF a sostegno delle attivit\u00e0 sociali svolte dal Comune di residenza del contribuente a gisutificazione dell&#8217;anno d&#8217;imposta 2022 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-18071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Destinazione 5 x 1000 - Sanza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Destinazione 5 x 1000 - Sanza\" \/>\n<meta property=\"og:description\" content=\"Relazione illustrativa del rendiconto della destinazione della quota del cinque per mille dell&#8217;IRPEF a sostegno delle attivit\u00e0 sociali svolte dal Comune di residenza del contribuente a gisutificazione dell&#8217;anno d&#8217;imposta 2022 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/\" \/>\n<meta property=\"og:site_name\" content=\"Sanza\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-14T09:38:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/14\\\/destinazione-5-x-1000\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/14\\\/destinazione-5-x-1000\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Destinazione 5 x 1000\",\"datePublished\":\"2025-07-14T09:38:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/14\\\/destinazione-5-x-1000\\\/\"},\"wordCount\":90,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/14\\\/destinazione-5-x-1000\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/07\\\/cropped-Sanza-2.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/14\\\/destinazione-5-x-1000\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/14\\\/destinazione-5-x-1000\\\/\",\"name\":\"Destinazione 5 x 1000 - Sanza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/14\\\/destinazione-5-x-1000\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/14\\\/destinazione-5-x-1000\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/07\\\/cropped-Sanza-2.png\",\"datePublished\":\"2025-07-14T09:38:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/14\\\/destinazione-5-x-1000\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/14\\\/destinazione-5-x-1000\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/14\\\/destinazione-5-x-1000\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/07\\\/cropped-Sanza-2.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/07\\\/cropped-Sanza-2.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/14\\\/destinazione-5-x-1000\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destinazione 5 x 1000\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Destinazione 5 x 1000 - Sanza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/","og_locale":"it_IT","og_type":"article","og_title":"Destinazione 5 x 1000 - Sanza","og_description":"Relazione illustrativa del rendiconto della destinazione della quota del cinque per mille dell&#8217;IRPEF a sostegno delle attivit\u00e0 sociali svolte dal Comune di residenza del contribuente a gisutificazione dell&#8217;anno d&#8217;imposta 2022 [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/","og_site_name":"Sanza","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-07-14T09:38:36+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza-2.png","type":"image\/png"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Destinazione 5 x 1000","datePublished":"2025-07-14T09:38:36+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/"},"wordCount":90,"publisher":{"@id":"https:\/\/comunicacity.net\/sanza\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza-2.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/","url":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/","name":"Destinazione 5 x 1000 - Sanza","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanza\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza-2.png","datePublished":"2025-07-14T09:38:36+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/#primaryimage","url":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza-2.png","contentUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza-2.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/14\/destinazione-5-x-1000\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanza\/"},{"@type":"ListItem","position":2,"name":"Destinazione 5 x 1000"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanza\/#website","url":"https:\/\/comunicacity.net\/sanza\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanza\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanza\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanza\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001794"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts\/18071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/comments?post=18071"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts\/18071\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/media\/18072"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/media?parent=18071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/categories?post=18071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/tags?post=18071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}