{"id":18101,"date":"2025-07-31T13:01:39","date_gmt":"2025-07-31T11:01:39","guid":{"rendered":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/"},"modified":"2025-07-31T13:01:39","modified_gmt":"2025-07-31T11:01:39","slug":"avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/","title":{"rendered":"Avviso ai creditori &#8211; Lavori di &#8220;fossa di Cianna-Donna Annina e del rifugio il loc. &#8220;Fossa di Cianna&#8221; &#8211; CUP G44J17000030002"},"content":{"rendered":"<p><em>Avviso ai creditori (Art. 102 D.Lgs 50\/2016)<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<h2><strong>Avviso ai creditori &#8211; Lavori di &#8220;fossa di Cianna-Donna Annina e del rifugio il loc. &#8220;Fossa di Cianna&#8221; &#8211; CUP G44J17000030002<\/strong><\/h2>\n<p>Avviso in allegato<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_18103\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/KM_C36825073112550.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/KM_C36825073112550.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>KM_C36825073112550<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Avviso ai creditori (Art. 102 D.Lgs 50\/2016)&nbsp; Descrizione&nbsp; Avviso ai creditori &#8211; Lavori di &#8220;fossa di Cianna-Donna Annina e del rifugio il loc. &#8220;Fossa di Cianna&#8221; &#8211; CUP G44J17000030002 Avviso [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18102,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-18101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso ai creditori - Lavori di &quot;fossa di Cianna-Donna Annina e del rifugio il loc. &quot;Fossa di Cianna&quot; - CUP G44J17000030002 - Sanza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso ai creditori - Lavori di &quot;fossa di Cianna-Donna Annina e del rifugio il loc. &quot;Fossa di Cianna&quot; - CUP G44J17000030002 - Sanza\" \/>\n<meta property=\"og:description\" content=\"Avviso ai creditori (Art. 102 D.Lgs 50\/2016)&nbsp; Descrizione&nbsp; Avviso ai creditori &#8211; Lavori di &#8220;fossa di Cianna-Donna Annina e del rifugio il loc. &#8220;Fossa di Cianna&#8221; &#8211; CUP G44J17000030002 Avviso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/\" \/>\n<meta property=\"og:site_name\" content=\"Sanza\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-31T11:01:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza-6.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/31\\\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/31\\\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Avviso ai creditori &#8211; Lavori di &#8220;fossa di Cianna-Donna Annina e del rifugio il loc. &#8220;Fossa di Cianna&#8221; &#8211; CUP G44J17000030002\",\"datePublished\":\"2025-07-31T11:01:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/31\\\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\\\/\"},\"wordCount\":56,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/31\\\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/07\\\/cropped-Sanza-6.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/31\\\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/31\\\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\\\/\",\"name\":\"Avviso ai creditori - Lavori di \\\"fossa di Cianna-Donna Annina e del rifugio il loc. \\\"Fossa di Cianna\\\" - CUP G44J17000030002 - Sanza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/31\\\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/31\\\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/07\\\/cropped-Sanza-6.png\",\"datePublished\":\"2025-07-31T11:01:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/31\\\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/31\\\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/31\\\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/07\\\/cropped-Sanza-6.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/07\\\/cropped-Sanza-6.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/07\\\/31\\\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso ai creditori &#8211; Lavori di &#8220;fossa di Cianna-Donna Annina e del rifugio il loc. &#8220;Fossa di Cianna&#8221; &#8211; CUP G44J17000030002\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso ai creditori - Lavori di \"fossa di Cianna-Donna Annina e del rifugio il loc. \"Fossa di Cianna\" - CUP G44J17000030002 - Sanza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso ai creditori - Lavori di \"fossa di Cianna-Donna Annina e del rifugio il loc. \"Fossa di Cianna\" - CUP G44J17000030002 - Sanza","og_description":"Avviso ai creditori (Art. 102 D.Lgs 50\/2016)&nbsp; Descrizione&nbsp; Avviso ai creditori &#8211; Lavori di &#8220;fossa di Cianna-Donna Annina e del rifugio il loc. &#8220;Fossa di Cianna&#8221; &#8211; CUP G44J17000030002 Avviso [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/","og_site_name":"Sanza","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-07-31T11:01:39+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza-6.png","type":"image\/png"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Avviso ai creditori &#8211; Lavori di &#8220;fossa di Cianna-Donna Annina e del rifugio il loc. &#8220;Fossa di Cianna&#8221; &#8211; CUP G44J17000030002","datePublished":"2025-07-31T11:01:39+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/"},"wordCount":56,"publisher":{"@id":"https:\/\/comunicacity.net\/sanza\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza-6.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/","url":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/","name":"Avviso ai creditori - Lavori di \"fossa di Cianna-Donna Annina e del rifugio il loc. \"Fossa di Cianna\" - CUP G44J17000030002 - Sanza","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanza\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza-6.png","datePublished":"2025-07-31T11:01:39+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/#primaryimage","url":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza-6.png","contentUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/07\/cropped-Sanza-6.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanza\/2025\/07\/31\/avviso-ai-creditori-lavori-di-fossa-di-cianna-donna-annina-e-del-rifugio-il-loc-fossa-di-cianna-cup-g44j17000030002\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanza\/"},{"@type":"ListItem","position":2,"name":"Avviso ai creditori &#8211; Lavori di &#8220;fossa di Cianna-Donna Annina e del rifugio il loc. &#8220;Fossa di Cianna&#8221; &#8211; CUP G44J17000030002"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanza\/#website","url":"https:\/\/comunicacity.net\/sanza\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanza\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanza\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanza\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001810"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts\/18101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/comments?post=18101"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts\/18101\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/media\/18102"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/media?parent=18101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/categories?post=18101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/tags?post=18101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}