{"id":18181,"date":"2025-10-10T15:20:14","date_gmt":"2025-10-10T13:20:14","guid":{"rendered":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/"},"modified":"2025-10-10T15:20:14","modified_gmt":"2025-10-10T13:20:14","slug":"avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/","title":{"rendered":"Avviso pubblico di selezione per attribuzione differenziali per i dipendenti del Comune di Sanza appartenenti alle categorie operatori esperti e funzionari anno 2023 &#8211; decorrenza 01.01.2023"},"content":{"rendered":"<p><em>Selezione per l&#8217;attribuzione di progressione economica orizzontale, con decorrenza 01 Gennaio 2023.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<h2 style=\"text-align: center\"><strong>UFFICIO DEL SEGRETARIO<\/strong><br \/>\n<strong>AVVISO PUBBLICO DI SELEZIONE PER ATTRIBUZIONE DIFFERENZIALI PER I DIPENDENTI DEL COMUNE DI SANZA APPARTENENTI ALLE CATEGORIE OPERATORI ESPERTI E FUNZIONARI ANNO 2023 &#8211; DECORRENZA 01.01.2023<\/strong><\/h2>\n<p><strong>IL SEGRETARIO COMUNALE<\/strong><\/p>\n<p>Visto l&#8217;art. 14 del contratto collettivo nazionale di lavoro del comparto delle Regioni e delle Autonomie Locali del 16.11.2022, che disciplina l&#8217;istituto della progressione economica all\u2019interno della categoria di appartenenza;<br \/>\nDato atto che tra l&#8217;Amministrazione comunale e le Organizzazioni sindacali territoriali \u00e8 stato sottoscritto in data 12\/12\/2023 il \u201cContratto decentrato del personale per l\u2019anno 2023\u201d nel quale, tra l\u2019altro, si \u00e8 stabilito di procedere all\u2019attribuzione di nuovi differenziali stipendiali, con decorrenza 01 Gennaio 2023, per i dipendenti di Categoria Funzionario (ex D) e i dipendenti di Categoria Operatori Esperti (ex B);<\/p>\n<p style=\"text-align: center\"><strong>AVVISA<\/strong><\/p>\n<p>Che al fine di effettuare le procedure per l\u2019attribuzione dei differenziali stipendiali dei dipendenti del Comune di Sanza appartenenti alle categorie giuridiche &#8220;Funzionario &#8221; e \u201cOperatori Esperti\u201d<\/p>\n<p style=\"text-align: center\"><strong>VIENE INDETTA LA SELEZIONE<\/strong><\/p>\n<p>per l&#8217;attribuzione di progressione economica orizzontale, con decorrenza 01 Gennaio 2023;<\/p>\n<p><em>&#8230; continua in allegato.<\/em><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_18183\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/10\/Atto-copia-uso-amministrativo.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/10\/Atto-copia-uso-amministrativo.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Atto copia uso amministrativo<\/a><\/li>\n<li><a id=\"wpba_attachment_list_18184\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/10\/BANDO-Differenziali-2023-Sanza.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/10\/BANDO-Differenziali-2023-Sanza.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>BANDO Differenziali 2023 Sanza<\/a><\/li>\n<li><a id=\"wpba_attachment_list_18185\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/10\/DOMANDA-RICHIESTA-ATTRIBUZIONE-DIFFERENZIALI1.docx\" onclick=\"window.open('https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/10\/DOMANDA-RICHIESTA-ATTRIBUZIONE-DIFFERENZIALI1.docx', '_system'); return false;\"><i class='icon attachment'><\/i>DOMANDA RICHIESTA ATTRIBUZIONE DIFFERENZIALI(1)<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Selezione per l&#8217;attribuzione di progressione economica orizzontale, con decorrenza 01 Gennaio 2023.&nbsp; Descrizione&nbsp; UFFICIO DEL SEGRETARIO AVVISO PUBBLICO DI SELEZIONE PER ATTRIBUZIONE DIFFERENZIALI PER I DIPENDENTI DEL COMUNE DI SANZA [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18182,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-18181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso pubblico di selezione per attribuzione differenziali per i dipendenti del Comune di Sanza appartenenti alle categorie operatori esperti e funzionari anno 2023 - decorrenza 01.01.2023 - Sanza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso pubblico di selezione per attribuzione differenziali per i dipendenti del Comune di Sanza appartenenti alle categorie operatori esperti e funzionari anno 2023 - decorrenza 01.01.2023 - Sanza\" \/>\n<meta property=\"og:description\" content=\"Selezione per l&#8217;attribuzione di progressione economica orizzontale, con decorrenza 01 Gennaio 2023.&nbsp; Descrizione&nbsp; UFFICIO DEL SEGRETARIO AVVISO PUBBLICO DI SELEZIONE PER ATTRIBUZIONE DIFFERENZIALI PER I DIPENDENTI DEL COMUNE DI SANZA [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Sanza\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-10T13:20:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/10\/cropped-Sanza.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/10\\\/10\\\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/10\\\/10\\\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Avviso pubblico di selezione per attribuzione differenziali per i dipendenti del Comune di Sanza appartenenti alle categorie operatori esperti e funzionari anno 2023 &#8211; decorrenza 01.01.2023\",\"datePublished\":\"2025-10-10T13:20:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/10\\\/10\\\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\\\/\"},\"wordCount\":198,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/10\\\/10\\\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/10\\\/cropped-Sanza.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/10\\\/10\\\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/10\\\/10\\\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\\\/\",\"name\":\"Avviso pubblico di selezione per attribuzione differenziali per i dipendenti del Comune di Sanza appartenenti alle categorie operatori esperti e funzionari anno 2023 - decorrenza 01.01.2023 - Sanza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/10\\\/10\\\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/10\\\/10\\\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/10\\\/cropped-Sanza.png\",\"datePublished\":\"2025-10-10T13:20:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/10\\\/10\\\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/10\\\/10\\\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/10\\\/10\\\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/10\\\/cropped-Sanza.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2025\\\/10\\\/cropped-Sanza.png\",\"width\":512,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2025\\\/10\\\/10\\\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso pubblico di selezione per attribuzione differenziali per i dipendenti del Comune di Sanza appartenenti alle categorie operatori esperti e funzionari anno 2023 &#8211; decorrenza 01.01.2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso pubblico di selezione per attribuzione differenziali per i dipendenti del Comune di Sanza appartenenti alle categorie operatori esperti e funzionari anno 2023 - decorrenza 01.01.2023 - Sanza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso pubblico di selezione per attribuzione differenziali per i dipendenti del Comune di Sanza appartenenti alle categorie operatori esperti e funzionari anno 2023 - decorrenza 01.01.2023 - Sanza","og_description":"Selezione per l&#8217;attribuzione di progressione economica orizzontale, con decorrenza 01 Gennaio 2023.&nbsp; Descrizione&nbsp; UFFICIO DEL SEGRETARIO AVVISO PUBBLICO DI SELEZIONE PER ATTRIBUZIONE DIFFERENZIALI PER I DIPENDENTI DEL COMUNE DI SANZA [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/","og_site_name":"Sanza","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-10-10T13:20:14+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/10\/cropped-Sanza.png","type":"image\/png"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Avviso pubblico di selezione per attribuzione differenziali per i dipendenti del Comune di Sanza appartenenti alle categorie operatori esperti e funzionari anno 2023 &#8211; decorrenza 01.01.2023","datePublished":"2025-10-10T13:20:14+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/"},"wordCount":198,"publisher":{"@id":"https:\/\/comunicacity.net\/sanza\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/10\/cropped-Sanza.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/","url":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/","name":"Avviso pubblico di selezione per attribuzione differenziali per i dipendenti del Comune di Sanza appartenenti alle categorie operatori esperti e funzionari anno 2023 - decorrenza 01.01.2023 - Sanza","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanza\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/10\/cropped-Sanza.png","datePublished":"2025-10-10T13:20:14+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/#primaryimage","url":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/10\/cropped-Sanza.png","contentUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2025\/10\/cropped-Sanza.png","width":512,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanza\/2025\/10\/10\/avviso-pubblico-di-selezione-per-attribuzione-differenziali-per-i-dipendenti-del-comune-di-sanza-appartenenti-alle-categorie-operatori-esperti-e-funzionari-anno-2023-decorrenza-01-01-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanza\/"},{"@type":"ListItem","position":2,"name":"Avviso pubblico di selezione per attribuzione differenziali per i dipendenti del Comune di Sanza appartenenti alle categorie operatori esperti e funzionari anno 2023 &#8211; decorrenza 01.01.2023"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanza\/#website","url":"https:\/\/comunicacity.net\/sanza\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanza\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanza\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanza\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001848"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts\/18181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/comments?post=18181"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts\/18181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/media\/18182"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/media?parent=18181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/categories?post=18181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/tags?post=18181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}