{"id":18310,"date":"2026-01-29T10:04:57","date_gmt":"2026-01-29T09:04:57","guid":{"rendered":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/"},"modified":"2026-01-29T10:07:23","modified_gmt":"2026-01-29T09:07:23","slug":"referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/","title":{"rendered":"Referendum costituzionale del 22 e 23 marzo 2026 opzione degli elettori temporaneamente all&#8217;estero esercizio del voto per corrispondenza nella circoscrizione estero"},"content":{"rendered":"<p><em>Opzione di voto per corrispondenza degli elettori temporaneamente all&#8217;estero pervenga direttamente al comune d&#8217;iscrizione nelle liste elettorali entro il trentaduesimo giorno antecedente la data di votazione e quindi entro il 18 febbraio p.v.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p><strong>REFERENDUM COSTITUZIONALE DEL 22 E 23 MARZO 2026 OPZIONE DEGLI ELETTORI TEMPORANEAMENTE ALL&#8217;ESTERO ESERCIZIO DEL VOTO PER CORRISPONDENZA NELLA CIRCOSCRIZIONE ESTERO<\/strong><\/p>\n<p>Per gli elettori temporaneamente residenti all&#8217;estero <em>L&#8217;art. 4-bis, comma 2, della legge n. 459\/01, modificato da ultimo dall&#8217;articolo 6, comma 2, lett. a), della legge 3 novembre 2017, n. 165, prevede che 1 opzione di voto per corrispondenza degli elettori temporaneamente all&#8217;estero pervenga direttamente al comune d&#8217;iscrizione nelle liste elettorali entro il <\/em><strong>trentaduesimo <\/strong><em>giorno antecedente la data di votazione e quindi <\/em><strong>entro <\/strong><em>il <\/em><strong>18 febbraio p.v. <\/strong><em>in tempo utile per l&#8217;immediata comunicazione al Ministero dell&#8217;Interno.<\/em><\/p>\n<p><strong><em>L&#8217;opzione potr\u00e0 pervenire al comune per posta ordinaria all\u2019indirizzo mail: <a href=\"mailto:amministrativo@comune.sanza.sa.it\">amministrativo@comune.sanza.sa.it<\/a>; \u00a0o per posta elettronica certificata: <a href=\"mailto:protocollo@pec.comune.sanza.sa.it\">protocollo@pec.comune.sanza.sa.it<\/a>; \u00a0e potr\u00e0 essere recapitata a mano anche da persona diversa dall&#8217;interessato.<\/em><\/strong><\/p>\n<p><em>Al fine di permetterne la necessaria <strong>diffusione a vista <\/strong>con ogni mezzo ritenuto idoneo <strong>viene allegato alla presente l&#8217;apposito<\/strong> <strong>modello di opzione (All. 2), <\/strong>che potrebbe essere utilizzato dai suddetti elettori temporaneamente residenti all&#8217;estero che intendono ivi esprimere il voto per corrispondenza. <\/em><em>Tale modello in formato PDF editabile con alcuni campi resi obbligatori \u2013 \u00e8<\/em> <em>formulato in modo da poter essere utilizzato da tutti i temporanei all&#8217;estero aventi diritto al<\/em> <em>voto per corrispondenza, ivi compresi gli elettori di cui ai commi 5 e 6 del citato art. 4-bis.<\/em> <em>Eventuali opzioni pervenute con un diverso modello sono comunque da considerarsi<\/em> <em>valide. purch\u00e9 siano conformi a quanto prescritto dal comma 2 del medesimo articolo 4-bis e nel termine massimo del <\/em><strong>trentaduesimo <\/strong><em>giorno antecedente la data di votazione e. quindi. <\/em><strong>entro <\/strong><em>il <\/em><strong>18 febbraio p.v.<\/strong><\/p>\n<p><strong>Il Sindaco<br \/>\n<\/strong><strong>Dott. Vittorio Esposito<\/strong><\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_18317\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2026\/01\/circ-dait-003-servelet-22-gennaio-2026-all-2.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2026\/01\/circ-dait-003-servelet-22-gennaio-2026-all-2.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>circ-dait-003-servelet-22-gennaio-2026-all-2<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Opzione di voto per corrispondenza degli elettori temporaneamente all&#8217;estero pervenga direttamente al comune d&#8217;iscrizione nelle liste elettorali entro il trentaduesimo giorno antecedente la data di votazione e quindi entro il [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18316,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-18310","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Referendum costituzionale del 22 e 23 marzo 2026 opzione degli elettori temporaneamente all&#039;estero esercizio del voto per corrispondenza nella circoscrizione estero - Sanza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Referendum costituzionale del 22 e 23 marzo 2026 opzione degli elettori temporaneamente all&#039;estero esercizio del voto per corrispondenza nella circoscrizione estero - Sanza\" \/>\n<meta property=\"og:description\" content=\"Opzione di voto per corrispondenza degli elettori temporaneamente all&#8217;estero pervenga direttamente al comune d&#8217;iscrizione nelle liste elettorali entro il trentaduesimo giorno antecedente la data di votazione e quindi entro il [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/\" \/>\n<meta property=\"og:site_name\" content=\"Sanza\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-29T09:04:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T09:07:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2026\/01\/speciale-referendum-2026-img-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"comunicadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"comunicadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2026\\\/01\\\/29\\\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2026\\\/01\\\/29\\\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\\\/\"},\"author\":{\"name\":\"comunicadmin\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\"},\"headline\":\"Referendum costituzionale del 22 e 23 marzo 2026 opzione degli elettori temporaneamente all&#8217;estero esercizio del voto per corrispondenza nella circoscrizione estero\",\"datePublished\":\"2026-01-29T09:04:57+00:00\",\"dateModified\":\"2026-01-29T09:07:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2026\\\/01\\\/29\\\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\\\/\"},\"wordCount\":308,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2026\\\/01\\\/29\\\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2026\\\/01\\\/speciale-referendum-2026-img-1.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2026\\\/01\\\/29\\\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2026\\\/01\\\/29\\\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\\\/\",\"name\":\"Referendum costituzionale del 22 e 23 marzo 2026 opzione degli elettori temporaneamente all'estero esercizio del voto per corrispondenza nella circoscrizione estero - Sanza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2026\\\/01\\\/29\\\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2026\\\/01\\\/29\\\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2026\\\/01\\\/speciale-referendum-2026-img-1.png\",\"datePublished\":\"2026-01-29T09:04:57+00:00\",\"dateModified\":\"2026-01-29T09:07:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2026\\\/01\\\/29\\\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2026\\\/01\\\/29\\\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2026\\\/01\\\/29\\\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2026\\\/01\\\/speciale-referendum-2026-img-1.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/wp-content\\\/uploads\\\/sites\\\/207\\\/2026\\\/01\\\/speciale-referendum-2026-img-1.png\",\"width\":800,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/2026\\\/01\\\/29\\\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Referendum costituzionale del 22 e 23 marzo 2026 opzione degli elettori temporaneamente all&#8217;estero esercizio del voto per corrispondenza nella circoscrizione estero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\",\"name\":\"ComunicaCity\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"contentUrl\":\"http:\\\/\\\/comunicacity.net\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/logo_comunicacity.png\",\"width\":501,\"height\":79,\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/sanza\\\/#\\\/schema\\\/person\\\/afdbb374f214a0c80148caaf3018dd53\",\"name\":\"comunicadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g\",\"caption\":\"comunicadmin\"},\"sameAs\":[\"http:\\\/\\\/www.comunicacity.it\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Referendum costituzionale del 22 e 23 marzo 2026 opzione degli elettori temporaneamente all'estero esercizio del voto per corrispondenza nella circoscrizione estero - Sanza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/","og_locale":"it_IT","og_type":"article","og_title":"Referendum costituzionale del 22 e 23 marzo 2026 opzione degli elettori temporaneamente all'estero esercizio del voto per corrispondenza nella circoscrizione estero - Sanza","og_description":"Opzione di voto per corrispondenza degli elettori temporaneamente all&#8217;estero pervenga direttamente al comune d&#8217;iscrizione nelle liste elettorali entro il trentaduesimo giorno antecedente la data di votazione e quindi entro il [&hellip;]","og_url":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/","og_site_name":"Sanza","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-01-29T09:04:57+00:00","article_modified_time":"2026-01-29T09:07:23+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2026\/01\/speciale-referendum-2026-img-1.png","type":"image\/png"}],"author":"comunicadmin","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"comunicadmin","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/"},"author":{"name":"comunicadmin","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53"},"headline":"Referendum costituzionale del 22 e 23 marzo 2026 opzione degli elettori temporaneamente all&#8217;estero esercizio del voto per corrispondenza nella circoscrizione estero","datePublished":"2026-01-29T09:04:57+00:00","dateModified":"2026-01-29T09:07:23+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/"},"wordCount":308,"publisher":{"@id":"https:\/\/comunicacity.net\/sanza\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2026\/01\/speciale-referendum-2026-img-1.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/","url":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/","name":"Referendum costituzionale del 22 e 23 marzo 2026 opzione degli elettori temporaneamente all'estero esercizio del voto per corrispondenza nella circoscrizione estero - Sanza","isPartOf":{"@id":"https:\/\/comunicacity.net\/sanza\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2026\/01\/speciale-referendum-2026-img-1.png","datePublished":"2026-01-29T09:04:57+00:00","dateModified":"2026-01-29T09:07:23+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/#primaryimage","url":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2026\/01\/speciale-referendum-2026-img-1.png","contentUrl":"https:\/\/comunicacity.net\/sanza\/wp-content\/uploads\/sites\/207\/2026\/01\/speciale-referendum-2026-img-1.png","width":800,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/sanza\/2026\/01\/29\/referendum-costituzionale-del-22-e-23-marzo-2026-opzione-degli-elettori-temporaneamente-allestero-esercizio-del-voto-per-corrispondenza-nella-circoscrizione-estero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/sanza\/"},{"@type":"ListItem","position":2,"name":"Referendum costituzionale del 22 e 23 marzo 2026 opzione degli elettori temporaneamente all&#8217;estero esercizio del voto per corrispondenza nella circoscrizione estero"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/sanza\/#website","url":"https:\/\/comunicacity.net\/sanza\/","name":"ComunicaCity","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/sanza\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/sanza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/sanza\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/sanza\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/logo\/image\/","url":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","contentUrl":"http:\/\/comunicacity.net\/wp-content\/uploads\/2014\/11\/logo_comunicacity.png","width":501,"height":79,"caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/sanza\/#\/schema\/person\/afdbb374f214a0c80148caaf3018dd53","name":"comunicadmin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/238a7f01be6e5f09c36aedef94fb10ae47d52a6a71608e5985bef2a1560a0d9b?s=96&d=mm&r=g","caption":"comunicadmin"},"sameAs":["http:\/\/www.comunicacity.it"]}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001958"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts\/18310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/comments?post=18310"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts\/18310\/revisions"}],"predecessor-version":[{"id":18313,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/posts\/18310\/revisions\/18313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/media\/18316"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/media?parent=18310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/categories?post=18310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/sanza\/wp-json\/wp\/v2\/tags?post=18310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}