{"id":15916,"date":"2025-03-05T10:54:42","date_gmt":"2025-03-05T09:54:42","guid":{"rendered":"https:\/\/comunicacity.net\/scalettazanclea\/?p=15916"},"modified":"2025-03-05T10:54:42","modified_gmt":"2025-03-05T09:54:42","slug":"trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/","title":{"rendered":"TRASFERIMENTO TEMPORANEO A NIZZA DI SICILIA SERVIZIO DI ESENZIONE TICKET E RILASCIO AUSILI E PRESIDI"},"content":{"rendered":"<p>Con nota dell&#8217;Asp di Messina del 04.03.2025, si comunica il trasferimento temporaneo degli uffici di esenzione ticket per patologia e rilascio autorizzazioni presidi ed ausili, da Furci Siculo a Nizza Di Sicilia Via C. Todaro n. 20.<\/p>\n<p>L&#8217;ufficio sar\u00e0 aperto al pubblico da lunedi a venerdi dalle ore 8.30-11.30<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_15918\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/03\/NOTA-ASP.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/03\/NOTA-ASP.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>NOTA ASP<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con nota dell&#8217;Asp di Messina del 04.03.2025, si comunica il trasferimento temporaneo degli uffici di esenzione ticket per patologia e rilascio autorizzazioni presidi ed ausili, da Furci Siculo a Nizza [&hellip;]<\/p>\n","protected":false},"author":268,"featured_media":15917,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-15916","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TRASFERIMENTO TEMPORANEO A NIZZA DI SICILIA SERVIZIO DI ESENZIONE TICKET E RILASCIO AUSILI E PRESIDI - Scaletta Zanclea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TRASFERIMENTO TEMPORANEO A NIZZA DI SICILIA SERVIZIO DI ESENZIONE TICKET E RILASCIO AUSILI E PRESIDI - Scaletta Zanclea\" \/>\n<meta property=\"og:description\" content=\"Con nota dell&#8217;Asp di Messina del 04.03.2025, si comunica il trasferimento temporaneo degli uffici di esenzione ticket per patologia e rilascio autorizzazioni presidi ed ausili, da Furci Siculo a Nizza [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/\" \/>\n<meta property=\"og:site_name\" content=\"Scaletta Zanclea\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-05T09:54:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/03\/images-asp.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"318\" \/>\n\t<meta property=\"og:image:height\" content=\"159\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"servizisociali\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"servizisociali\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/03\\\/05\\\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/03\\\/05\\\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\\\/\"},\"author\":{\"name\":\"servizisociali\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#\\\/schema\\\/person\\\/90a333a3afa0c220640069ac529812bc\"},\"headline\":\"TRASFERIMENTO TEMPORANEO A NIZZA DI SICILIA SERVIZIO DI ESENZIONE TICKET E RILASCIO AUSILI E PRESIDI\",\"datePublished\":\"2025-03-05T09:54:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/03\\\/05\\\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\\\/\"},\"wordCount\":62,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/03\\\/05\\\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2025\\\/03\\\/images-asp.jpeg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/03\\\/05\\\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/03\\\/05\\\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\\\/\",\"name\":\"TRASFERIMENTO TEMPORANEO A NIZZA DI SICILIA SERVIZIO DI ESENZIONE TICKET E RILASCIO AUSILI E PRESIDI - Scaletta Zanclea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/03\\\/05\\\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/03\\\/05\\\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2025\\\/03\\\/images-asp.jpeg\",\"datePublished\":\"2025-03-05T09:54:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#\\\/schema\\\/person\\\/90a333a3afa0c220640069ac529812bc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/03\\\/05\\\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/03\\\/05\\\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/03\\\/05\\\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2025\\\/03\\\/images-asp.jpeg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2025\\\/03\\\/images-asp.jpeg\",\"width\":318,\"height\":159},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/03\\\/05\\\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TRASFERIMENTO TEMPORANEO A NIZZA DI SICILIA SERVIZIO DI ESENZIONE TICKET E RILASCIO AUSILI E PRESIDI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/\",\"name\":\"Scaletta Zanclea\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#\\\/schema\\\/person\\\/90a333a3afa0c220640069ac529812bc\",\"name\":\"servizisociali\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g\",\"caption\":\"servizisociali\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/author\\\/servizisociali\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TRASFERIMENTO TEMPORANEO A NIZZA DI SICILIA SERVIZIO DI ESENZIONE TICKET E RILASCIO AUSILI E PRESIDI - Scaletta Zanclea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/","og_locale":"it_IT","og_type":"article","og_title":"TRASFERIMENTO TEMPORANEO A NIZZA DI SICILIA SERVIZIO DI ESENZIONE TICKET E RILASCIO AUSILI E PRESIDI - Scaletta Zanclea","og_description":"Con nota dell&#8217;Asp di Messina del 04.03.2025, si comunica il trasferimento temporaneo degli uffici di esenzione ticket per patologia e rilascio autorizzazioni presidi ed ausili, da Furci Siculo a Nizza [&hellip;]","og_url":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/","og_site_name":"Scaletta Zanclea","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-03-05T09:54:42+00:00","og_image":[{"width":318,"height":159,"url":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/03\/images-asp.jpeg","type":"image\/jpeg"}],"author":"servizisociali","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"servizisociali"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/"},"author":{"name":"servizisociali","@id":"https:\/\/comunicacity.net\/scalettazanclea\/#\/schema\/person\/90a333a3afa0c220640069ac529812bc"},"headline":"TRASFERIMENTO TEMPORANEO A NIZZA DI SICILIA SERVIZIO DI ESENZIONE TICKET E RILASCIO AUSILI E PRESIDI","datePublished":"2025-03-05T09:54:42+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/"},"wordCount":62,"image":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/03\/images-asp.jpeg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/","url":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/","name":"TRASFERIMENTO TEMPORANEO A NIZZA DI SICILIA SERVIZIO DI ESENZIONE TICKET E RILASCIO AUSILI E PRESIDI - Scaletta Zanclea","isPartOf":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/03\/images-asp.jpeg","datePublished":"2025-03-05T09:54:42+00:00","author":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/#\/schema\/person\/90a333a3afa0c220640069ac529812bc"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/#primaryimage","url":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/03\/images-asp.jpeg","contentUrl":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/03\/images-asp.jpeg","width":318,"height":159},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/03\/05\/trasferimento-temporaneo-a-nizza-di-sicilia-servizio-di-esenzione-ticket-e-rilascio-ausili-e-presidi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/scalettazanclea\/"},{"@type":"ListItem","position":2,"name":"TRASFERIMENTO TEMPORANEO A NIZZA DI SICILIA SERVIZIO DI ESENZIONE TICKET E RILASCIO AUSILI E PRESIDI"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/scalettazanclea\/#website","url":"https:\/\/comunicacity.net\/scalettazanclea\/","name":"Scaletta Zanclea","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/scalettazanclea\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/scalettazanclea\/#\/schema\/person\/90a333a3afa0c220640069ac529812bc","name":"servizisociali","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g","caption":"servizisociali"},"url":"https:\/\/comunicacity.net\/scalettazanclea\/author\/servizisociali\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts\/15916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/users\/268"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/comments?post=15916"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts\/15916\/revisions"}],"predecessor-version":[{"id":15919,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts\/15916\/revisions\/15919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/media\/15917"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/media?parent=15916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/categories?post=15916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/tags?post=15916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}