{"id":16144,"date":"2025-09-17T17:42:27","date_gmt":"2025-09-17T15:42:27","guid":{"rendered":"https:\/\/comunicacity.net\/scalettazanclea\/?p=16144"},"modified":"2025-09-17T17:42:27","modified_gmt":"2025-09-17T15:42:27","slug":"gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/","title":{"rendered":"GITA PER RAGAZZI DAI 16-25 ANNI &#8220;ETNALAND-THEME PARK&#8221; -ADESIONE ENTRO IL 22.09.2025 ORE 13:00"},"content":{"rendered":"<p>L\u2019Amministrazione comunale, nell\u2019ambito delle Politiche giovanili, intende organizzare una gita di fine estate presso il parco tematico \u201c<strong>Etnaland\u2014Theme Park<\/strong>\u201d di Belpasso, rivolta ai giovani di et\u00e0 compresa tra i 16-25 anni, <strong>\u00a0<\/strong>per un numero massimo di 50 persone.<\/p>\n<p><strong>Data della gita<\/strong>: domenica 28 settembre 2025<\/p>\n<p><strong>Quota di partecipazione<\/strong>:<\/p>\n<ul>\n<li>gratuita per i residenti<\/li>\n<li>\u20ac 15,00 per i residenti di et\u00e0 superiore ai 25 anni<\/li>\n<li>\u20ac 25,00 per i non residenti<\/li>\n<\/ul>\n<p>La quota dovr\u00e0 essere pagata tramite il sistema PagoPa<\/p>\n<p>Le adesioni dovranno pervenire entro e non oltre le ore 13:00 di <strong>luned\u00ec 22 settembre 2025<\/strong> presso il protocollo del Comune, compilando l\u2019apposito modulo di iscrizione disponibile presso l\u2019ufficio protocollo del comune o scaricabile dal sito.<\/p>\n<p>Le adesioni potranno essere inviate tramite email a:<\/p>\n<p><a href=\"mailto:servizisociali@comunescalettazanclea.it\">servizisociali@comunescalettazanclea.it<\/a> oppure <a href=\"mailto:ufficioprotocollo@pec.comunescalettazanclea.it\">ufficioprotocollo@pec.comunescalettazanclea.it<\/a><\/p>\n<p>La gita verr\u00e0 realizzata solo se si raggiunge il numero minimo di 30 partecipanti.<\/p>\n<p>In caso di superamento del limite massimo (50 iscritti) verr\u00e0 stilata una graduatoria, secondo l\u2019ordine di arrivo delle domande.<\/p>\n<p>&nbsp;<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_16145\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/09\/avviso-gita-ETNALAND.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/09\/avviso-gita-ETNALAND.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>avviso gita ETNALAND<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Amministrazione comunale, nell\u2019ambito delle Politiche giovanili, intende organizzare una gita di fine estate presso il parco tematico \u201cEtnaland\u2014Theme Park\u201d di Belpasso, rivolta ai giovani di et\u00e0 compresa tra i 16-25 [&hellip;]<\/p>\n","protected":false},"author":268,"featured_media":16147,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-16144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GITA PER RAGAZZI DAI 16-25 ANNI &quot;ETNALAND-THEME PARK&quot; -ADESIONE ENTRO IL 22.09.2025 ORE 13:00 - Scaletta Zanclea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GITA PER RAGAZZI DAI 16-25 ANNI &quot;ETNALAND-THEME PARK&quot; -ADESIONE ENTRO IL 22.09.2025 ORE 13:00 - Scaletta Zanclea\" \/>\n<meta property=\"og:description\" content=\"L\u2019Amministrazione comunale, nell\u2019ambito delle Politiche giovanili, intende organizzare una gita di fine estate presso il parco tematico \u201cEtnaland\u2014Theme Park\u201d di Belpasso, rivolta ai giovani di et\u00e0 compresa tra i 16-25 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/\" \/>\n<meta property=\"og:site_name\" content=\"Scaletta Zanclea\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-17T15:42:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/09\/LOCANDINA-ETNALAND.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1131\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"servizisociali\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"servizisociali\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/09\\\/17\\\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/09\\\/17\\\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\\\/\"},\"author\":{\"name\":\"servizisociali\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#\\\/schema\\\/person\\\/90a333a3afa0c220640069ac529812bc\"},\"headline\":\"GITA PER RAGAZZI DAI 16-25 ANNI &#8220;ETNALAND-THEME PARK&#8221; -ADESIONE ENTRO IL 22.09.2025 ORE 13:00\",\"datePublished\":\"2025-09-17T15:42:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/09\\\/17\\\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\\\/\"},\"wordCount\":169,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/09\\\/17\\\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2025\\\/09\\\/LOCANDINA-ETNALAND.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/09\\\/17\\\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/09\\\/17\\\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\\\/\",\"name\":\"GITA PER RAGAZZI DAI 16-25 ANNI \\\"ETNALAND-THEME PARK\\\" -ADESIONE ENTRO IL 22.09.2025 ORE 13:00 - Scaletta Zanclea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/09\\\/17\\\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/09\\\/17\\\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2025\\\/09\\\/LOCANDINA-ETNALAND.jpg\",\"datePublished\":\"2025-09-17T15:42:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#\\\/schema\\\/person\\\/90a333a3afa0c220640069ac529812bc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/09\\\/17\\\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/09\\\/17\\\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/09\\\/17\\\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2025\\\/09\\\/LOCANDINA-ETNALAND.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2025\\\/09\\\/LOCANDINA-ETNALAND.jpg\",\"width\":1131,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2025\\\/09\\\/17\\\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GITA PER RAGAZZI DAI 16-25 ANNI &#8220;ETNALAND-THEME PARK&#8221; -ADESIONE ENTRO IL 22.09.2025 ORE 13:00\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/\",\"name\":\"Scaletta Zanclea\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#\\\/schema\\\/person\\\/90a333a3afa0c220640069ac529812bc\",\"name\":\"servizisociali\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g\",\"caption\":\"servizisociali\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/author\\\/servizisociali\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GITA PER RAGAZZI DAI 16-25 ANNI \"ETNALAND-THEME PARK\" -ADESIONE ENTRO IL 22.09.2025 ORE 13:00 - Scaletta Zanclea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/","og_locale":"it_IT","og_type":"article","og_title":"GITA PER RAGAZZI DAI 16-25 ANNI \"ETNALAND-THEME PARK\" -ADESIONE ENTRO IL 22.09.2025 ORE 13:00 - Scaletta Zanclea","og_description":"L\u2019Amministrazione comunale, nell\u2019ambito delle Politiche giovanili, intende organizzare una gita di fine estate presso il parco tematico \u201cEtnaland\u2014Theme Park\u201d di Belpasso, rivolta ai giovani di et\u00e0 compresa tra i 16-25 [&hellip;]","og_url":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/","og_site_name":"Scaletta Zanclea","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-09-17T15:42:27+00:00","og_image":[{"width":1131,"height":1600,"url":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/09\/LOCANDINA-ETNALAND.jpg","type":"image\/jpeg"}],"author":"servizisociali","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"servizisociali","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/"},"author":{"name":"servizisociali","@id":"https:\/\/comunicacity.net\/scalettazanclea\/#\/schema\/person\/90a333a3afa0c220640069ac529812bc"},"headline":"GITA PER RAGAZZI DAI 16-25 ANNI &#8220;ETNALAND-THEME PARK&#8221; -ADESIONE ENTRO IL 22.09.2025 ORE 13:00","datePublished":"2025-09-17T15:42:27+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/"},"wordCount":169,"image":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/09\/LOCANDINA-ETNALAND.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/","url":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/","name":"GITA PER RAGAZZI DAI 16-25 ANNI \"ETNALAND-THEME PARK\" -ADESIONE ENTRO IL 22.09.2025 ORE 13:00 - Scaletta Zanclea","isPartOf":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/09\/LOCANDINA-ETNALAND.jpg","datePublished":"2025-09-17T15:42:27+00:00","author":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/#\/schema\/person\/90a333a3afa0c220640069ac529812bc"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/#primaryimage","url":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/09\/LOCANDINA-ETNALAND.jpg","contentUrl":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2025\/09\/LOCANDINA-ETNALAND.jpg","width":1131,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2025\/09\/17\/gita-per-ragazzi-dai-16-25-anni-etnaland-theme-park-adesione-entro-il-22-09-2025-ore-1300\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/scalettazanclea\/"},{"@type":"ListItem","position":2,"name":"GITA PER RAGAZZI DAI 16-25 ANNI &#8220;ETNALAND-THEME PARK&#8221; -ADESIONE ENTRO IL 22.09.2025 ORE 13:00"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/scalettazanclea\/#website","url":"https:\/\/comunicacity.net\/scalettazanclea\/","name":"Scaletta Zanclea","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/scalettazanclea\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/scalettazanclea\/#\/schema\/person\/90a333a3afa0c220640069ac529812bc","name":"servizisociali","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g","caption":"servizisociali"},"url":"https:\/\/comunicacity.net\/scalettazanclea\/author\/servizisociali\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts\/16144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/users\/268"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/comments?post=16144"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts\/16144\/revisions"}],"predecessor-version":[{"id":16148,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts\/16144\/revisions\/16148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/media\/16147"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/media?parent=16144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/categories?post=16144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/tags?post=16144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}