{"id":16318,"date":"2026-02-25T10:42:09","date_gmt":"2026-02-25T09:42:09","guid":{"rendered":"https:\/\/comunicacity.net\/scalettazanclea\/?p=16318"},"modified":"2026-02-25T10:42:09","modified_gmt":"2026-02-25T09:42:09","slug":"prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/","title":{"rendered":"PREVENZIONE TRUFFE AGLI ANZIANI-INCONTRO ORATORIO S. MARIA DEL CARMELO IL 27.02.2026 ORE 16,30"},"content":{"rendered":"<p>LA CITTADINANZA E&#8217; INVITATA A PARTECIPARE ALL&#8217;INCONTRO CHE SI TERRA&#8217; VENERDI 27 FEBBRAIO 2026 ORE 16,30 PRESSO L&#8217;ORATORIO S. MARIA DEL CARMELO PER TRATTARE IL TEMA SULLA PREVENZIONE DELLE TRUFFE AGLI ANZIANI.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LA CITTADINANZA E&#8217; INVITATA A PARTECIPARE ALL&#8217;INCONTRO CHE SI TERRA&#8217; VENERDI 27 FEBBRAIO 2026 ORE 16,30 PRESSO L&#8217;ORATORIO S. MARIA DEL CARMELO PER TRATTARE IL TEMA SULLA PREVENZIONE DELLE TRUFFE [&hellip;]<\/p>\n","protected":false},"author":268,"featured_media":16319,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-16318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PREVENZIONE TRUFFE AGLI ANZIANI-INCONTRO ORATORIO S. MARIA DEL CARMELO IL 27.02.2026 ORE 16,30 - Scaletta Zanclea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PREVENZIONE TRUFFE AGLI ANZIANI-INCONTRO ORATORIO S. MARIA DEL CARMELO IL 27.02.2026 ORE 16,30 - Scaletta Zanclea\" \/>\n<meta property=\"og:description\" content=\"LA CITTADINANZA E&#8217; INVITATA A PARTECIPARE ALL&#8217;INCONTRO CHE SI TERRA&#8217; VENERDI 27 FEBBRAIO 2026 ORE 16,30 PRESSO L&#8217;ORATORIO S. MARIA DEL CARMELO PER TRATTARE IL TEMA SULLA PREVENZIONE DELLE TRUFFE [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/\" \/>\n<meta property=\"og:site_name\" content=\"Scaletta Zanclea\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-25T09:42:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2026\/02\/INCONTRO-27-FEBBRAIO.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1415\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"servizisociali\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"servizisociali\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2026\\\/02\\\/25\\\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2026\\\/02\\\/25\\\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\\\/\"},\"author\":{\"name\":\"servizisociali\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#\\\/schema\\\/person\\\/90a333a3afa0c220640069ac529812bc\"},\"headline\":\"PREVENZIONE TRUFFE AGLI ANZIANI-INCONTRO ORATORIO S. MARIA DEL CARMELO IL 27.02.2026 ORE 16,30\",\"datePublished\":\"2026-02-25T09:42:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2026\\\/02\\\/25\\\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\\\/\"},\"wordCount\":40,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2026\\\/02\\\/25\\\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2026\\\/02\\\/INCONTRO-27-FEBBRAIO.jpg\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2026\\\/02\\\/25\\\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2026\\\/02\\\/25\\\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\\\/\",\"name\":\"PREVENZIONE TRUFFE AGLI ANZIANI-INCONTRO ORATORIO S. MARIA DEL CARMELO IL 27.02.2026 ORE 16,30 - Scaletta Zanclea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2026\\\/02\\\/25\\\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2026\\\/02\\\/25\\\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2026\\\/02\\\/INCONTRO-27-FEBBRAIO.jpg\",\"datePublished\":\"2026-02-25T09:42:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#\\\/schema\\\/person\\\/90a333a3afa0c220640069ac529812bc\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2026\\\/02\\\/25\\\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2026\\\/02\\\/25\\\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2026\\\/02\\\/25\\\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2026\\\/02\\\/INCONTRO-27-FEBBRAIO.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2026\\\/02\\\/INCONTRO-27-FEBBRAIO.jpg\",\"width\":1415,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2026\\\/02\\\/25\\\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PREVENZIONE TRUFFE AGLI ANZIANI-INCONTRO ORATORIO S. MARIA DEL CARMELO IL 27.02.2026 ORE 16,30\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/\",\"name\":\"Scaletta Zanclea\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#\\\/schema\\\/person\\\/90a333a3afa0c220640069ac529812bc\",\"name\":\"servizisociali\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g\",\"caption\":\"servizisociali\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/author\\\/servizisociali\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PREVENZIONE TRUFFE AGLI ANZIANI-INCONTRO ORATORIO S. MARIA DEL CARMELO IL 27.02.2026 ORE 16,30 - Scaletta Zanclea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/","og_locale":"it_IT","og_type":"article","og_title":"PREVENZIONE TRUFFE AGLI ANZIANI-INCONTRO ORATORIO S. MARIA DEL CARMELO IL 27.02.2026 ORE 16,30 - Scaletta Zanclea","og_description":"LA CITTADINANZA E&#8217; INVITATA A PARTECIPARE ALL&#8217;INCONTRO CHE SI TERRA&#8217; VENERDI 27 FEBBRAIO 2026 ORE 16,30 PRESSO L&#8217;ORATORIO S. MARIA DEL CARMELO PER TRATTARE IL TEMA SULLA PREVENZIONE DELLE TRUFFE [&hellip;]","og_url":"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/","og_site_name":"Scaletta Zanclea","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2026-02-25T09:42:09+00:00","og_image":[{"width":1415,"height":2000,"url":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2026\/02\/INCONTRO-27-FEBBRAIO.jpg","type":"image\/jpeg"}],"author":"servizisociali","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"servizisociali"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/"},"author":{"name":"servizisociali","@id":"https:\/\/comunicacity.net\/scalettazanclea\/#\/schema\/person\/90a333a3afa0c220640069ac529812bc"},"headline":"PREVENZIONE TRUFFE AGLI ANZIANI-INCONTRO ORATORIO S. MARIA DEL CARMELO IL 27.02.2026 ORE 16,30","datePublished":"2026-02-25T09:42:09+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/"},"wordCount":40,"image":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2026\/02\/INCONTRO-27-FEBBRAIO.jpg","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/","url":"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/","name":"PREVENZIONE TRUFFE AGLI ANZIANI-INCONTRO ORATORIO S. MARIA DEL CARMELO IL 27.02.2026 ORE 16,30 - Scaletta Zanclea","isPartOf":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2026\/02\/INCONTRO-27-FEBBRAIO.jpg","datePublished":"2026-02-25T09:42:09+00:00","author":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/#\/schema\/person\/90a333a3afa0c220640069ac529812bc"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/#primaryimage","url":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2026\/02\/INCONTRO-27-FEBBRAIO.jpg","contentUrl":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2026\/02\/INCONTRO-27-FEBBRAIO.jpg","width":1415,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2026\/02\/25\/prevenzione-truffe-agli-anziani-incontro-oratorio-s-maria-del-carmelo-il-27-02-2026-ore-1630\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/scalettazanclea\/"},{"@type":"ListItem","position":2,"name":"PREVENZIONE TRUFFE AGLI ANZIANI-INCONTRO ORATORIO S. MARIA DEL CARMELO IL 27.02.2026 ORE 16,30"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/scalettazanclea\/#website","url":"https:\/\/comunicacity.net\/scalettazanclea\/","name":"Scaletta Zanclea","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/scalettazanclea\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/scalettazanclea\/#\/schema\/person\/90a333a3afa0c220640069ac529812bc","name":"servizisociali","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6fce52d5124421fc5ed640f4fce5efe0d6270262ade5e6b30e5a470b5158a9f4?s=96&d=mm&r=g","caption":"servizisociali"},"url":"https:\/\/comunicacity.net\/scalettazanclea\/author\/servizisociali\/"}]}},"meta_box":{"cc4_urg_colore":"rosso","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"0","longitude":"0","zoom":"0"},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts\/16318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/users\/268"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/comments?post=16318"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts\/16318\/revisions"}],"predecessor-version":[{"id":16320,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts\/16318\/revisions\/16320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/media\/16319"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/media?parent=16318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/categories?post=16318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/tags?post=16318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}