{"id":188,"date":"2018-11-27T12:05:23","date_gmt":"2018-11-27T11:05:23","guid":{"rendered":"https:\/\/comunicacity.net\/scalettazanclea\/?p=188"},"modified":"2018-11-27T12:05:23","modified_gmt":"2018-11-27T11:05:23","slug":"una-panchina-per-la-vita-4-dicembre-2018","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/","title":{"rendered":"&#8220;Una Panchina per la Vita&#8221; &#8211; 4 dicembre 2018"},"content":{"rendered":"<p>&#8220;Una Panchina per la Vita&#8221;<\/p>\n<p>Campagna di sensibilizzazione contro la violenza sulle donne<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-189\" src=\"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2018\/11\/IMG-20181121-WA0000-215x300.jpg\" alt=\"\" width=\"215\" height=\"300\" srcset=\"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2018\/11\/IMG-20181121-WA0000-215x300.jpg 215w, https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2018\/11\/IMG-20181121-WA0000-768x1073.jpg 768w, https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2018\/11\/IMG-20181121-WA0000-733x1024.jpg 733w, https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2018\/11\/IMG-20181121-WA0000-680x950.jpg 680w, https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2018\/11\/IMG-20181121-WA0000-600x838.jpg 600w, https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2018\/11\/IMG-20181121-WA0000-800x1118.jpg 800w, https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2018\/11\/IMG-20181121-WA0000.jpg 1145w\" sizes=\"auto, (max-width: 215px) 100vw, 215px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Una Panchina per la Vita&#8221; Campagna di sensibilizzazione contro la violenza sulle donne<\/p>\n","protected":false},"author":267,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-188","post","type-post","status-publish","format-standard","hentry","category-servizi-sociali-e-casa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Una Panchina per la Vita&quot; - 4 dicembre 2018 - Scaletta Zanclea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Una Panchina per la Vita&quot; - 4 dicembre 2018 - Scaletta Zanclea\" \/>\n<meta property=\"og:description\" content=\"&#8220;Una Panchina per la Vita&#8221; Campagna di sensibilizzazione contro la violenza sulle donne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Scaletta Zanclea\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-27T11:05:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2018\/11\/IMG-20181121-WA0000-215x300.jpg\" \/>\n<meta name=\"author\" content=\"segreteria\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"segreteria\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2018\\\/11\\\/27\\\/una-panchina-per-la-vita-4-dicembre-2018\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2018\\\/11\\\/27\\\/una-panchina-per-la-vita-4-dicembre-2018\\\/\"},\"author\":{\"name\":\"segreteria\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#\\\/schema\\\/person\\\/49c6e4b7d0872ed12334a8736e00f6a8\"},\"headline\":\"&#8220;Una Panchina per la Vita&#8221; &#8211; 4 dicembre 2018\",\"datePublished\":\"2018-11-27T11:05:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2018\\\/11\\\/27\\\/una-panchina-per-la-vita-4-dicembre-2018\\\/\"},\"wordCount\":20,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2018\\\/11\\\/27\\\/una-panchina-per-la-vita-4-dicembre-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2018\\\/11\\\/IMG-20181121-WA0000-215x300.jpg\",\"articleSection\":[\"Servizi Sociali e Casa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2018\\\/11\\\/27\\\/una-panchina-per-la-vita-4-dicembre-2018\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2018\\\/11\\\/27\\\/una-panchina-per-la-vita-4-dicembre-2018\\\/\",\"name\":\"\\\"Una Panchina per la Vita\\\" - 4 dicembre 2018 - Scaletta Zanclea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2018\\\/11\\\/27\\\/una-panchina-per-la-vita-4-dicembre-2018\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2018\\\/11\\\/27\\\/una-panchina-per-la-vita-4-dicembre-2018\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2018\\\/11\\\/IMG-20181121-WA0000-215x300.jpg\",\"datePublished\":\"2018-11-27T11:05:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#\\\/schema\\\/person\\\/49c6e4b7d0872ed12334a8736e00f6a8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2018\\\/11\\\/27\\\/una-panchina-per-la-vita-4-dicembre-2018\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2018\\\/11\\\/27\\\/una-panchina-per-la-vita-4-dicembre-2018\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2018\\\/11\\\/27\\\/una-panchina-per-la-vita-4-dicembre-2018\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2018\\\/11\\\/IMG-20181121-WA0000.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/wp-content\\\/uploads\\\/sites\\\/156\\\/2018\\\/11\\\/IMG-20181121-WA0000.jpg\",\"width\":1145,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/2018\\\/11\\\/27\\\/una-panchina-per-la-vita-4-dicembre-2018\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Una Panchina per la Vita&#8221; &#8211; 4 dicembre 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/\",\"name\":\"Scaletta Zanclea\",\"description\":\"Ecco un altro sito ComunicaCity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/#\\\/schema\\\/person\\\/49c6e4b7d0872ed12334a8736e00f6a8\",\"name\":\"segreteria\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d8b3cb84e2f913694aa0d75a04ecb3e2cf47121b0774d118c6872a1865e6894?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d8b3cb84e2f913694aa0d75a04ecb3e2cf47121b0774d118c6872a1865e6894?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d8b3cb84e2f913694aa0d75a04ecb3e2cf47121b0774d118c6872a1865e6894?s=96&d=mm&r=g\",\"caption\":\"segreteria\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/scalettazanclea\\\/author\\\/segreteria\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Una Panchina per la Vita\" - 4 dicembre 2018 - Scaletta Zanclea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/","og_locale":"it_IT","og_type":"article","og_title":"\"Una Panchina per la Vita\" - 4 dicembre 2018 - Scaletta Zanclea","og_description":"&#8220;Una Panchina per la Vita&#8221; Campagna di sensibilizzazione contro la violenza sulle donne","og_url":"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/","og_site_name":"Scaletta Zanclea","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2018-11-27T11:05:23+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2018\/11\/IMG-20181121-WA0000-215x300.jpg","type":"","width":"","height":""}],"author":"segreteria","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"segreteria"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/"},"author":{"name":"segreteria","@id":"https:\/\/comunicacity.net\/scalettazanclea\/#\/schema\/person\/49c6e4b7d0872ed12334a8736e00f6a8"},"headline":"&#8220;Una Panchina per la Vita&#8221; &#8211; 4 dicembre 2018","datePublished":"2018-11-27T11:05:23+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/"},"wordCount":20,"image":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2018\/11\/IMG-20181121-WA0000-215x300.jpg","articleSection":["Servizi Sociali e Casa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/","url":"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/","name":"\"Una Panchina per la Vita\" - 4 dicembre 2018 - Scaletta Zanclea","isPartOf":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2018\/11\/IMG-20181121-WA0000-215x300.jpg","datePublished":"2018-11-27T11:05:23+00:00","author":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/#\/schema\/person\/49c6e4b7d0872ed12334a8736e00f6a8"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/#primaryimage","url":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2018\/11\/IMG-20181121-WA0000.jpg","contentUrl":"https:\/\/comunicacity.net\/scalettazanclea\/wp-content\/uploads\/sites\/156\/2018\/11\/IMG-20181121-WA0000.jpg","width":1145,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/scalettazanclea\/2018\/11\/27\/una-panchina-per-la-vita-4-dicembre-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/scalettazanclea\/"},{"@type":"ListItem","position":2,"name":"&#8220;Una Panchina per la Vita&#8221; &#8211; 4 dicembre 2018"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/scalettazanclea\/#website","url":"https:\/\/comunicacity.net\/scalettazanclea\/","name":"Scaletta Zanclea","description":"Ecco un altro sito ComunicaCity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/scalettazanclea\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/scalettazanclea\/#\/schema\/person\/49c6e4b7d0872ed12334a8736e00f6a8","name":"segreteria","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/6d8b3cb84e2f913694aa0d75a04ecb3e2cf47121b0774d118c6872a1865e6894?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6d8b3cb84e2f913694aa0d75a04ecb3e2cf47121b0774d118c6872a1865e6894?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6d8b3cb84e2f913694aa0d75a04ecb3e2cf47121b0774d118c6872a1865e6894?s=96&d=mm&r=g","caption":"segreteria"},"url":"https:\/\/comunicacity.net\/scalettazanclea\/author\/segreteria\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts\/188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/users\/267"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/comments?post=188"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts\/188\/revisions"}],"predecessor-version":[{"id":190,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/posts\/188\/revisions\/190"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/media?parent=188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/categories?post=188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/scalettazanclea\/wp-json\/wp\/v2\/tags?post=188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}