{"id":19465,"date":"2024-04-26T14:39:55","date_gmt":"2024-04-26T12:39:55","guid":{"rendered":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/"},"modified":"2024-04-26T14:39:55","modified_gmt":"2024-04-26T12:39:55","slug":"divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/","title":{"rendered":"Divieto di sosta e transito dalle ore 08.00 alle ore 20.00 del giorno Mercoled\u00ec 1 Maggio 2024"},"content":{"rendered":"<p><em>In via Santa Maria del Colle, Piazza Madonna delle Grazie, via della Chiesa e tutto il centro storico<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>In occasione della &#8220;Sagra delle fave e del pecorino&#8221;, che si svolger\u00e0 il giorno 1 Maggio 2024 in localit\u00e0 Ponticelli, si comunica il divieto di sosta e transito sulle vie e aree indicate.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_19467\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/04\/Sagra-delle-Fave-e-Pecorino-ord.-15.2024.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/04\/Sagra-delle-Fave-e-Pecorino-ord.-15.2024.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Sagra delle Fave e Pecorino &#8211; ord. 15.2024<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In via Santa Maria del Colle, Piazza Madonna delle Grazie, via della Chiesa e tutto il centro storico&nbsp; Descrizione&nbsp; In occasione della &#8220;Sagra delle fave e del pecorino&#8221;, che si [&hellip;]<\/p>\n","protected":false},"author":365,"featured_media":19466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-19465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Divieto di sosta e transito dalle ore 08.00 alle ore 20.00 del giorno Mercoled\u00ec 1 Maggio 2024 - Scandriglia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Divieto di sosta e transito dalle ore 08.00 alle ore 20.00 del giorno Mercoled\u00ec 1 Maggio 2024 - Scandriglia\" \/>\n<meta property=\"og:description\" content=\"In via Santa Maria del Colle, Piazza Madonna delle Grazie, via della Chiesa e tutto il centro storico&nbsp; Descrizione&nbsp; In occasione della &#8220;Sagra delle fave e del pecorino&#8221;, che si [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Scandriglia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-26T12:39:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/04\/safra-delle-fave-e-del-pecorino.png\" \/>\n\t<meta property=\"og:image:width\" content=\"630\" \/>\n\t<meta property=\"og:image:height\" content=\"476\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"imargottini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"imargottini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/04\\\/26\\\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/04\\\/26\\\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\\\/\"},\"author\":{\"name\":\"imargottini\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/person\\\/a9149b71e8760b847dd3a06ff9e02b54\"},\"headline\":\"Divieto di sosta e transito dalle ore 08.00 alle ore 20.00 del giorno Mercoled\u00ec 1 Maggio 2024\",\"datePublished\":\"2024-04-26T12:39:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/04\\\/26\\\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\\\/\"},\"wordCount\":65,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/04\\\/26\\\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/wp-content\\\/uploads\\\/sites\\\/192\\\/2024\\\/04\\\/safra-delle-fave-e-del-pecorino.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/04\\\/26\\\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/04\\\/26\\\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\\\/\",\"name\":\"Divieto di sosta e transito dalle ore 08.00 alle ore 20.00 del giorno Mercoled\u00ec 1 Maggio 2024 - Scandriglia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/04\\\/26\\\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/04\\\/26\\\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/wp-content\\\/uploads\\\/sites\\\/192\\\/2024\\\/04\\\/safra-delle-fave-e-del-pecorino.png\",\"datePublished\":\"2024-04-26T12:39:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/04\\\/26\\\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/04\\\/26\\\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/04\\\/26\\\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/wp-content\\\/uploads\\\/sites\\\/192\\\/2024\\\/04\\\/safra-delle-fave-e-del-pecorino.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/wp-content\\\/uploads\\\/sites\\\/192\\\/2024\\\/04\\\/safra-delle-fave-e-del-pecorino.png\",\"width\":630,\"height\":476},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/04\\\/26\\\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Divieto di sosta e transito dalle ore 08.00 alle ore 20.00 del giorno Mercoled\u00ec 1 Maggio 2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\",\"name\":\"Scandriglia\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/person\\\/a9149b71e8760b847dd3a06ff9e02b54\",\"name\":\"imargottini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g\",\"caption\":\"imargottini\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/author\\\/imargottini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Divieto di sosta e transito dalle ore 08.00 alle ore 20.00 del giorno Mercoled\u00ec 1 Maggio 2024 - Scandriglia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/","og_locale":"it_IT","og_type":"article","og_title":"Divieto di sosta e transito dalle ore 08.00 alle ore 20.00 del giorno Mercoled\u00ec 1 Maggio 2024 - Scandriglia","og_description":"In via Santa Maria del Colle, Piazza Madonna delle Grazie, via della Chiesa e tutto il centro storico&nbsp; Descrizione&nbsp; In occasione della &#8220;Sagra delle fave e del pecorino&#8221;, che si [&hellip;]","og_url":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/","og_site_name":"Scandriglia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-04-26T12:39:55+00:00","og_image":[{"width":630,"height":476,"url":"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/04\/safra-delle-fave-e-del-pecorino.png","type":"image\/png"}],"author":"imargottini","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"imargottini"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/"},"author":{"name":"imargottini","@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/person\/a9149b71e8760b847dd3a06ff9e02b54"},"headline":"Divieto di sosta e transito dalle ore 08.00 alle ore 20.00 del giorno Mercoled\u00ec 1 Maggio 2024","datePublished":"2024-04-26T12:39:55+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/"},"wordCount":65,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/04\/safra-delle-fave-e-del-pecorino.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/","url":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/","name":"Divieto di sosta e transito dalle ore 08.00 alle ore 20.00 del giorno Mercoled\u00ec 1 Maggio 2024 - Scandriglia","isPartOf":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/04\/safra-delle-fave-e-del-pecorino.png","datePublished":"2024-04-26T12:39:55+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/#primaryimage","url":"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/04\/safra-delle-fave-e-del-pecorino.png","contentUrl":"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/04\/safra-delle-fave-e-del-pecorino.png","width":630,"height":476},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/04\/26\/divieto-di-sosta-e-transito-dalle-ore-08-00-alle-ore-20-00-del-giorno-mercoledi-1-maggio-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/scandriglia\/"},{"@type":"ListItem","position":2,"name":"Divieto di sosta e transito dalle ore 08.00 alle ore 20.00 del giorno Mercoled\u00ec 1 Maggio 2024"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/scandriglia\/#website","url":"https:\/\/comunicacity.net\/scandriglia\/","name":"Scandriglia","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/scandriglia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/scandriglia\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/scandriglia\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/person\/a9149b71e8760b847dd3a06ff9e02b54","name":"imargottini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g","caption":"imargottini"},"url":"https:\/\/comunicacity.net\/scandriglia\/author\/imargottini\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001806"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/posts\/19465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/users\/365"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/comments?post=19465"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/posts\/19465\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/media\/19466"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/media?parent=19465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/categories?post=19465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/tags?post=19465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}