{"id":19660,"date":"2024-09-17T13:33:49","date_gmt":"2024-09-17T11:33:49","guid":{"rendered":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/"},"modified":"2024-09-17T13:33:49","modified_gmt":"2024-09-17T11:33:49","slug":"decreto-medio-fondo-la-medievale","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/","title":{"rendered":"Decreto Medio Fondo La Medievale"},"content":{"rendered":"<p><em>Sospensione temporanea della circolazione, per consentire il passaggio dei concorrenti, il giorno 22\/9\/2024, lungo il percorso di gara secondo le modalit\u00e0 di cui all\u2019allegata istanza che costituisce parte integrante del presente provvedimento.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>In ciascun punto del percorso la sospensione della circolazione avr\u00e0 la durata strettamente necessaria al transito dei concorrenti ritenuti, secondo i regolamenti sportivi, ancora in corsa a partire dal momento del passaggio del veicolo recante il cartello mobile \u201cinizio gara ciclistica\u201d fino al passaggio di quello con il cartello mobile \u201cfine gara ciclistica\u201d. In ogni caso la durata della chiusura in ciascun punto del percorso non potr\u00e0 essere superiore a 60 minuti calcolati dal momento del transito del primo concorrente ;<\/p>\n<ul>\n<li>DURANTE IL PERIODO DI SOSPENSIONE TEMPORANEA DELLA CIRCOLAZIONE:<\/li>\n<\/ul>\n<ol>\n<li>\u00a0\u00e8 vietato il transito di qualsiasi veicolo non al seguito della gara, in entrambi i sensi di marcia del tratto interessato dal transito dei concorrenti;<\/li>\n<li>\u00a0\u00e8 fatto divieto a tutti i veicoli di immettersi nel percorso interessato dal transito dei concorrenti;<\/li>\n<li>\u00a0\u00e8 fatto obbligo a tutti i veicoli provenienti da strade o da aree che intersecano ovvero che si immettono su quella interessata dal transito dei concorrenti, di arrestarsi prima di impegnarla rispettando le segnalazioni manuali o luminose degli organi preposti alla vigilanza o del personale dell\u2019organizzazione;<\/li>\n<li>\u00e8 fatto obbligo ai conducenti di veicoli ed ai pedoni di non attraversare la strada.<\/li>\n<\/ol>\n<ul>\n<li>Ferma restando la necessit\u00e0 di adottare tutte le cautele necessarie ad evitare pericoli per i concorrenti, I DIVIETI E GLI OBBLIGHI SOPRAINDICATI NON SI APPLICANO AI VEICOLI ADIBITI A SERVIZI DI POLIZIA, ANTINCENDIO E PRONTO SOCCORSO, NONCH\u00c8 A QUELLI SPECIFICAMENTE AUTORIZZATI DALL\u2019ORGANIZZAZIONE O DAGLI ORGANI DI POLIZIA PREPOSTI ALLA VIGILANZA.<br \/>\nD I S P O N E altres\u00ec che:<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>la QUESTURA di Rieti, quale organo di Polizia coordinatore dell\u2019 operazione, \u00e8 incaricata dell\u2019 esecuzione della presente ordinanza nonch\u00e8 della verifica del rispetto delle prescrizioni imposte con il presente provvedimento e di quelle contenute nell\u2019 autorizzazione della competizione ai sensi dell\u2019art.9, 1\u00b0 comma C.D.S;<\/li>\n<li>\u00a0l\u2019ORGANIZZAZIONE provveder\u00e0 affinch\u00e8 le intersezioni stradali siano presidiate da proprio personale idoneo e facilmente riconoscibile e predisporr\u00e0 un adeguato servizio e, ove necessario, una specifica segnaletica, in corrispondenza degli incroci che interessano il transito della corsa, in modo che tutti gli utenti della strada siano resi edotti della sospensione della circolazione.<\/li>\n<\/ul>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_19662\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/09\/DECRETOLAMEDIEVALE-signed.pdf.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/09\/DECRETOLAMEDIEVALE-signed.pdf.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>DECRETOLAMEDIEVALE-signed.pdf<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sospensione temporanea della circolazione, per consentire il passaggio dei concorrenti, il giorno 22\/9\/2024, lungo il percorso di gara secondo le modalit\u00e0 di cui all\u2019allegata istanza che costituisce parte integrante del [&hellip;]<\/p>\n","protected":false},"author":365,"featured_media":19661,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-19660","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Decreto Medio Fondo La Medievale - Scandriglia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Decreto Medio Fondo La Medievale - Scandriglia\" \/>\n<meta property=\"og:description\" content=\"Sospensione temporanea della circolazione, per consentire il passaggio dei concorrenti, il giorno 22\/9\/2024, lungo il percorso di gara secondo le modalit\u00e0 di cui all\u2019allegata istanza che costituisce parte integrante del [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/\" \/>\n<meta property=\"og:site_name\" content=\"Scandriglia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T11:33:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/09\/immagine_evidenza_comune_scandriglia-2-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"imargottini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"imargottini\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/09\\\/17\\\/decreto-medio-fondo-la-medievale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/09\\\/17\\\/decreto-medio-fondo-la-medievale\\\/\"},\"author\":{\"name\":\"imargottini\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/person\\\/a9149b71e8760b847dd3a06ff9e02b54\"},\"headline\":\"Decreto Medio Fondo La Medievale\",\"datePublished\":\"2024-09-17T11:33:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/09\\\/17\\\/decreto-medio-fondo-la-medievale\\\/\"},\"wordCount\":384,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/09\\\/17\\\/decreto-medio-fondo-la-medievale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/wp-content\\\/uploads\\\/sites\\\/192\\\/2024\\\/09\\\/immagine_evidenza_comune_scandriglia-2-2.png\",\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/09\\\/17\\\/decreto-medio-fondo-la-medievale\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/09\\\/17\\\/decreto-medio-fondo-la-medievale\\\/\",\"name\":\"Decreto Medio Fondo La Medievale - Scandriglia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/09\\\/17\\\/decreto-medio-fondo-la-medievale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/09\\\/17\\\/decreto-medio-fondo-la-medievale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/wp-content\\\/uploads\\\/sites\\\/192\\\/2024\\\/09\\\/immagine_evidenza_comune_scandriglia-2-2.png\",\"datePublished\":\"2024-09-17T11:33:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/09\\\/17\\\/decreto-medio-fondo-la-medievale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/09\\\/17\\\/decreto-medio-fondo-la-medievale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/09\\\/17\\\/decreto-medio-fondo-la-medievale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/wp-content\\\/uploads\\\/sites\\\/192\\\/2024\\\/09\\\/immagine_evidenza_comune_scandriglia-2-2.png\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/wp-content\\\/uploads\\\/sites\\\/192\\\/2024\\\/09\\\/immagine_evidenza_comune_scandriglia-2-2.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2024\\\/09\\\/17\\\/decreto-medio-fondo-la-medievale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decreto Medio Fondo La Medievale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\",\"name\":\"Scandriglia\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/person\\\/a9149b71e8760b847dd3a06ff9e02b54\",\"name\":\"imargottini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g\",\"caption\":\"imargottini\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/author\\\/imargottini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Decreto Medio Fondo La Medievale - Scandriglia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/","og_locale":"it_IT","og_type":"article","og_title":"Decreto Medio Fondo La Medievale - Scandriglia","og_description":"Sospensione temporanea della circolazione, per consentire il passaggio dei concorrenti, il giorno 22\/9\/2024, lungo il percorso di gara secondo le modalit\u00e0 di cui all\u2019allegata istanza che costituisce parte integrante del [&hellip;]","og_url":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/","og_site_name":"Scandriglia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2024-09-17T11:33:49+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/09\/immagine_evidenza_comune_scandriglia-2-2.png","type":"image\/png"}],"author":"imargottini","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"imargottini","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/"},"author":{"name":"imargottini","@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/person\/a9149b71e8760b847dd3a06ff9e02b54"},"headline":"Decreto Medio Fondo La Medievale","datePublished":"2024-09-17T11:33:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/"},"wordCount":384,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#organization"},"image":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/09\/immagine_evidenza_comune_scandriglia-2-2.png","articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/","url":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/","name":"Decreto Medio Fondo La Medievale - Scandriglia","isPartOf":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/09\/immagine_evidenza_comune_scandriglia-2-2.png","datePublished":"2024-09-17T11:33:49+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/#primaryimage","url":"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/09\/immagine_evidenza_comune_scandriglia-2-2.png","contentUrl":"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2024\/09\/immagine_evidenza_comune_scandriglia-2-2.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/scandriglia\/2024\/09\/17\/decreto-medio-fondo-la-medievale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/scandriglia\/"},{"@type":"ListItem","position":2,"name":"Decreto Medio Fondo La Medievale"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/scandriglia\/#website","url":"https:\/\/comunicacity.net\/scandriglia\/","name":"Scandriglia","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/scandriglia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/scandriglia\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/scandriglia\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/person\/a9149b71e8760b847dd3a06ff9e02b54","name":"imargottini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g","caption":"imargottini"},"url":"https:\/\/comunicacity.net\/scandriglia\/author\/imargottini\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00001990"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/posts\/19660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/users\/365"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/comments?post=19660"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/posts\/19660\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/media\/19661"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/media?parent=19660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/categories?post=19660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/tags?post=19660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}