{"id":19835,"date":"2025-05-23T09:46:16","date_gmt":"2025-05-23T07:46:16","guid":{"rendered":"https:\/\/comunicacity.net\/scandriglia\/2025\/05\/23\/avviso-controllo-mastelli-saprodir\/"},"modified":"2025-05-23T09:46:16","modified_gmt":"2025-05-23T07:46:16","slug":"avviso-controllo-mastelli-saprodir","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/scandriglia\/2025\/05\/23\/avviso-controllo-mastelli-saprodir\/","title":{"rendered":"Avviso controllo mastelli Saprodir"},"content":{"rendered":"<p><em>Controllo sui conferimenti dei rifiuti indifferenziati.<\/em>&nbsp;<\/p>\n<p><b>Descrizione&nbsp;<\/b><\/p>\n<p>Si informa la popolazione che a partire dalla prossima settimana inizieranno controlli sui conferimenti dei rifiuti indifferenziati.<br \/>\nLe verifiche saranno finalizzate ad accertare la corretta differenziazione e il rispetto delle modalit\u00e0 di conferimento, secondo le normative comunali vigenti.<br \/>\nI rifiuti dovranno essere conferiti solo ed esclusivamente all\u2019interno del mastello di colore grigio, che saranno oggetto di controllo.<br \/>\nSi invitano pertanto tutti i cittadini a prestare la massima attenzione alle regole di raccolta differenziata per evitare sanzioni.<\/p>\n<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_19836\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2025\/05\/Avviso-controlli-Scandriglia.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2025\/05\/Avviso-controlli-Scandriglia.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>Avviso controlli Scandriglia<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Controllo sui conferimenti dei rifiuti indifferenziati.&nbsp; Descrizione&nbsp; Si informa la popolazione che a partire dalla prossima settimana inizieranno controlli sui conferimenti dei rifiuti indifferenziati. Le verifiche saranno finalizzate ad accertare [&hellip;]<\/p>\n","protected":false},"author":365,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-19835","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Avviso controllo mastelli Saprodir - Scandriglia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/scandriglia\/2025\/05\/23\/avviso-controllo-mastelli-saprodir\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avviso controllo mastelli Saprodir - Scandriglia\" \/>\n<meta property=\"og:description\" content=\"Controllo sui conferimenti dei rifiuti indifferenziati.&nbsp; Descrizione&nbsp; Si informa la popolazione che a partire dalla prossima settimana inizieranno controlli sui conferimenti dei rifiuti indifferenziati. Le verifiche saranno finalizzate ad accertare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/scandriglia\/2025\/05\/23\/avviso-controllo-mastelli-saprodir\/\" \/>\n<meta property=\"og:site_name\" content=\"Scandriglia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-23T07:46:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/scandriglia\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"imargottini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"imargottini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2025\\\/05\\\/23\\\/avviso-controllo-mastelli-saprodir\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2025\\\/05\\\/23\\\/avviso-controllo-mastelli-saprodir\\\/\"},\"author\":{\"name\":\"imargottini\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/person\\\/a9149b71e8760b847dd3a06ff9e02b54\"},\"headline\":\"Avviso controllo mastelli Saprodir\",\"datePublished\":\"2025-05-23T07:46:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2025\\\/05\\\/23\\\/avviso-controllo-mastelli-saprodir\\\/\"},\"wordCount\":90,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2025\\\/05\\\/23\\\/avviso-controllo-mastelli-saprodir\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2025\\\/05\\\/23\\\/avviso-controllo-mastelli-saprodir\\\/\",\"name\":\"Avviso controllo mastelli Saprodir - Scandriglia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#website\"},\"datePublished\":\"2025-05-23T07:46:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2025\\\/05\\\/23\\\/avviso-controllo-mastelli-saprodir\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2025\\\/05\\\/23\\\/avviso-controllo-mastelli-saprodir\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2025\\\/05\\\/23\\\/avviso-controllo-mastelli-saprodir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avviso controllo mastelli Saprodir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\",\"name\":\"Scandriglia\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/person\\\/a9149b71e8760b847dd3a06ff9e02b54\",\"name\":\"imargottini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g\",\"caption\":\"imargottini\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/author\\\/imargottini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avviso controllo mastelli Saprodir - Scandriglia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/scandriglia\/2025\/05\/23\/avviso-controllo-mastelli-saprodir\/","og_locale":"it_IT","og_type":"article","og_title":"Avviso controllo mastelli Saprodir - Scandriglia","og_description":"Controllo sui conferimenti dei rifiuti indifferenziati.&nbsp; Descrizione&nbsp; Si informa la popolazione che a partire dalla prossima settimana inizieranno controlli sui conferimenti dei rifiuti indifferenziati. Le verifiche saranno finalizzate ad accertare [&hellip;]","og_url":"https:\/\/comunicacity.net\/scandriglia\/2025\/05\/23\/avviso-controllo-mastelli-saprodir\/","og_site_name":"Scandriglia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2025-05-23T07:46:16+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/scandriglia\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"imargottini","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"imargottini"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/scandriglia\/2025\/05\/23\/avviso-controllo-mastelli-saprodir\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2025\/05\/23\/avviso-controllo-mastelli-saprodir\/"},"author":{"name":"imargottini","@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/person\/a9149b71e8760b847dd3a06ff9e02b54"},"headline":"Avviso controllo mastelli Saprodir","datePublished":"2025-05-23T07:46:16+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2025\/05\/23\/avviso-controllo-mastelli-saprodir\/"},"wordCount":90,"commentCount":0,"publisher":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/scandriglia\/2025\/05\/23\/avviso-controllo-mastelli-saprodir\/","url":"https:\/\/comunicacity.net\/scandriglia\/2025\/05\/23\/avviso-controllo-mastelli-saprodir\/","name":"Avviso controllo mastelli Saprodir - Scandriglia","isPartOf":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#website"},"datePublished":"2025-05-23T07:46:16+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2025\/05\/23\/avviso-controllo-mastelli-saprodir\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/scandriglia\/2025\/05\/23\/avviso-controllo-mastelli-saprodir\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/scandriglia\/2025\/05\/23\/avviso-controllo-mastelli-saprodir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/scandriglia\/"},{"@type":"ListItem","position":2,"name":"Avviso controllo mastelli Saprodir"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/scandriglia\/#website","url":"https:\/\/comunicacity.net\/scandriglia\/","name":"Scandriglia","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/scandriglia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/scandriglia\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/scandriglia\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/person\/a9149b71e8760b847dd3a06ff9e02b54","name":"imargottini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g","caption":"imargottini"},"url":"https:\/\/comunicacity.net\/scandriglia\/author\/imargottini\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":"00002177"},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/posts\/19835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/users\/365"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/comments?post=19835"}],"version-history":[{"count":0,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/posts\/19835\/revisions"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/media?parent=19835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/categories?post=19835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/tags?post=19835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}