{"id":317,"date":"2020-10-27T11:33:49","date_gmt":"2020-10-27T10:33:49","guid":{"rendered":"https:\/\/comunicacity.net\/scandriglia\/?p=317"},"modified":"2020-10-27T11:33:49","modified_gmt":"2020-10-27T10:33:49","slug":"ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/scandriglia\/2020\/10\/27\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\/","title":{"rendered":"Ordinanza del Presidente della Regione Lazio d&#8217;intesa con il Ministro della Salute"},"content":{"rendered":"<div id='wpba_attachment_list' class=''>\n<div class='ui list'><h3 style=\"display:none;\">\ud83d\udcce Allegati<\/h3><ul><li><a id=\"wpba_attachment_list_318\" class=\"y-skip-href item\" href=\"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2020\/10\/ordinanza_regione_lazio_intesa_Ministro_salute__mod_accettate_rev1__ore_24_1_signed.pdf\" onclick=\"window.open('https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2020\/10\/ordinanza_regione_lazio_intesa_Ministro_salute__mod_accettate_rev1__ore_24_1_signed.pdf', '_system'); return false;\"><i class='icon attachment'><\/i>ordinanza_regione_lazio_intesa_Ministro_salute__mod_accettate_rev1__ore_24_1_signed<\/a><\/li>\n<\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\ud83d\udcce Allegatiordinanza_regione_lazio_intesa_Ministro_salute__mod_accettate_rev1__ore_24_1_signed<\/p>\n","protected":false},"author":365,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-317","post","type-post","status-publish","format-standard","hentry","category-notizie-e-informazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ordinanza del Presidente della Regione Lazio d&#039;intesa con il Ministro della Salute - Scandriglia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/scandriglia\/2020\/10\/27\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ordinanza del Presidente della Regione Lazio d&#039;intesa con il Ministro della Salute - Scandriglia\" \/>\n<meta property=\"og:description\" content=\"\ud83d\udcce Allegatiordinanza_regione_lazio_intesa_Ministro_salute__mod_accettate_rev1__ore_24_1_signed\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/scandriglia\/2020\/10\/27\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\/\" \/>\n<meta property=\"og:site_name\" content=\"Scandriglia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-27T10:33:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/scandriglia\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n<meta name=\"author\" content=\"imargottini\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"imargottini\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2020\\\/10\\\/27\\\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2020\\\/10\\\/27\\\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\\\/\"},\"author\":{\"name\":\"imargottini\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/person\\\/a9149b71e8760b847dd3a06ff9e02b54\"},\"headline\":\"Ordinanza del Presidente della Regione Lazio d&#8217;intesa con il Ministro della Salute\",\"datePublished\":\"2020-10-27T10:33:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2020\\\/10\\\/27\\\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\\\/\"},\"wordCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#organization\"},\"articleSection\":[\"Notizie e Informazioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2020\\\/10\\\/27\\\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2020\\\/10\\\/27\\\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\\\/\",\"name\":\"Ordinanza del Presidente della Regione Lazio d'intesa con il Ministro della Salute - Scandriglia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#website\"},\"datePublished\":\"2020-10-27T10:33:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2020\\\/10\\\/27\\\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2020\\\/10\\\/27\\\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/2020\\\/10\\\/27\\\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ordinanza del Presidente della Regione Lazio d&#8217;intesa con il Ministro della Salute\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\",\"name\":\"Scandriglia\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/person\\\/a9149b71e8760b847dd3a06ff9e02b54\",\"name\":\"imargottini\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g\",\"caption\":\"imargottini\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/author\\\/imargottini\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ordinanza del Presidente della Regione Lazio d'intesa con il Ministro della Salute - Scandriglia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/scandriglia\/2020\/10\/27\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\/","og_locale":"it_IT","og_type":"article","og_title":"Ordinanza del Presidente della Regione Lazio d'intesa con il Ministro della Salute - Scandriglia","og_description":"\ud83d\udcce Allegatiordinanza_regione_lazio_intesa_Ministro_salute__mod_accettate_rev1__ore_24_1_signed","og_url":"https:\/\/comunicacity.net\/scandriglia\/2020\/10\/27\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\/","og_site_name":"Scandriglia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_published_time":"2020-10-27T10:33:49+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/scandriglia\/wp-content\/themes\/comunicacity\/build\/assets\/categorie\/notizie-e-informazioni.png","height":600,"width":1200,"type":""}],"author":"imargottini","twitter_card":"summary_large_image","twitter_creator":"@comunicacity","twitter_site":"@comunicacity","twitter_misc":{"Scritto da":"imargottini"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/scandriglia\/2020\/10\/27\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2020\/10\/27\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\/"},"author":{"name":"imargottini","@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/person\/a9149b71e8760b847dd3a06ff9e02b54"},"headline":"Ordinanza del Presidente della Regione Lazio d&#8217;intesa con il Ministro della Salute","datePublished":"2020-10-27T10:33:49+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2020\/10\/27\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\/"},"wordCount":12,"publisher":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#organization"},"articleSection":["Notizie e Informazioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/scandriglia\/2020\/10\/27\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\/","url":"https:\/\/comunicacity.net\/scandriglia\/2020\/10\/27\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\/","name":"Ordinanza del Presidente della Regione Lazio d'intesa con il Ministro della Salute - Scandriglia","isPartOf":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#website"},"datePublished":"2020-10-27T10:33:49+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/scandriglia\/2020\/10\/27\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/scandriglia\/2020\/10\/27\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/scandriglia\/2020\/10\/27\/ordinanza-del-presidente-della-regione-lazio-dintesa-con-il-ministro-della-salute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/scandriglia\/"},{"@type":"ListItem","position":2,"name":"Ordinanza del Presidente della Regione Lazio d&#8217;intesa con il Ministro della Salute"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/scandriglia\/#website","url":"https:\/\/comunicacity.net\/scandriglia\/","name":"Scandriglia","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/scandriglia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/scandriglia\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/scandriglia\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]},{"@type":"Person","@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/person\/a9149b71e8760b847dd3a06ff9e02b54","name":"imargottini","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14e5d3bc0768b6089ac36faf94e26d5976459bb220e2e72bf511a753b5f8fbf9?s=96&d=mm&r=g","caption":"imargottini"},"url":"https:\/\/comunicacity.net\/scandriglia\/author\/imargottini\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/posts\/317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/users\/365"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/comments?post=317"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/posts\/317\/revisions"}],"predecessor-version":[{"id":319,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/posts\/317\/revisions\/319"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/media?parent=317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/categories?post=317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/tags?post=317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}