{"id":50,"date":"2020-05-25T16:44:22","date_gmt":"2020-05-25T14:44:22","guid":{"rendered":"https:\/\/comunicacity.net\/scandriglia\/?post_type=turismo&#038;p=50"},"modified":"2020-05-25T16:50:28","modified_gmt":"2020-05-25T14:50:28","slug":"dal-regno-ditalia-ad-oggi","status":"publish","type":"turismo","link":"https:\/\/comunicacity.net\/scandriglia\/turismo\/dal-regno-ditalia-ad-oggi\/","title":{"rendered":"Dal Regno d\u2019Italia ad oggi"},"content":{"rendered":"<p>Da sempre presente nello Stato Pontificio, nel 1860 Scandriglia entra a far parte del Regno d\u2019Italia come comune della provincia di Perugia e poi di Roma. Nel 1927 in seguito all\u2019istituzione della provincia di Rieti entr\u00f2 a far parte di quest\u2019ultima.<\/p>\n<p>Attualmente Scandriglia occupa un territorio ampio circa 6600 ettari, costituito in gran parte da colline e dalla terza parte da montagne boscose. Compresa la frazione di Ponticelli, i suoi abitanti sono circa 3.100. L\u2019economia verte principalmente sulla produzione di olio di oliva; si coltivano anche cereali, piante da frutto, viti e ortaggi. E\u2019 sviluppato l\u2019allevamento dei bovini, equini ed ovini, che in parte si svolge allo stato brado nelle verdi e ubertose vallate della catena appenninica che lambisce il territorio scandrigliese. Nella stagione estiva questo ameno paese si trasforma in un centro affollatissimo che offre a tutti i nuovi arrivati dei panorami inebrianti ed un clima salubre in un ambiente ecologicamente incontaminato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da sempre presente nello Stato Pontificio, nel 1860 Scandriglia entra a far parte del Regno d\u2019Italia come comune della provincia di Perugia e poi di Roma. Nel 1927 in seguito [&hellip;]<\/p>\n","protected":false},"featured_media":0,"menu_order":3,"template":"","meta":[],"plugin_turismo":[],"class_list":["post-50","turismo","type-turismo","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dal Regno d\u2019Italia ad oggi - Scandriglia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/scandriglia\/turismo\/dal-regno-ditalia-ad-oggi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dal Regno d\u2019Italia ad oggi - Scandriglia\" \/>\n<meta property=\"og:description\" content=\"Da sempre presente nello Stato Pontificio, nel 1860 Scandriglia entra a far parte del Regno d\u2019Italia come comune della provincia di Perugia e poi di Roma. Nel 1927 in seguito [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/scandriglia\/turismo\/dal-regno-ditalia-ad-oggi\/\" \/>\n<meta property=\"og:site_name\" content=\"Scandriglia\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/ComunicaCity\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-25T14:50:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2020\/05\/scandriglia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"50\" \/>\n\t<meta property=\"og:image:height\" content=\"50\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comunicacity\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/turismo\\\/dal-regno-ditalia-ad-oggi\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/turismo\\\/dal-regno-ditalia-ad-oggi\\\/\",\"name\":\"Dal Regno d\u2019Italia ad oggi - Scandriglia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#website\"},\"datePublished\":\"2020-05-25T14:44:22+00:00\",\"dateModified\":\"2020-05-25T14:50:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/turismo\\\/dal-regno-ditalia-ad-oggi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/turismo\\\/dal-regno-ditalia-ad-oggi\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/turismo\\\/dal-regno-ditalia-ad-oggi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dal Regno d\u2019Italia ad oggi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\",\"name\":\"Scandriglia\",\"description\":\"Ecco un altro sito ComunicaCity\",\"publisher\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#organization\",\"name\":\"ComunicaCity\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"ComunicaCity\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/scandriglia\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/facebook.com\\\/ComunicaCity\",\"https:\\\/\\\/x.com\\\/comunicacity\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dal Regno d\u2019Italia ad oggi - Scandriglia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/scandriglia\/turismo\/dal-regno-ditalia-ad-oggi\/","og_locale":"it_IT","og_type":"article","og_title":"Dal Regno d\u2019Italia ad oggi - Scandriglia","og_description":"Da sempre presente nello Stato Pontificio, nel 1860 Scandriglia entra a far parte del Regno d\u2019Italia come comune della provincia di Perugia e poi di Roma. Nel 1927 in seguito [&hellip;]","og_url":"https:\/\/comunicacity.net\/scandriglia\/turismo\/dal-regno-ditalia-ad-oggi\/","og_site_name":"Scandriglia","article_publisher":"http:\/\/facebook.com\/ComunicaCity","article_modified_time":"2020-05-25T14:50:28+00:00","og_image":[{"url":"https:\/\/comunicacity.net\/scandriglia\/wp-content\/uploads\/sites\/192\/2020\/05\/scandriglia.jpg","height":50,"width":50,"type":""}],"twitter_card":"summary_large_image","twitter_site":"@comunicacity","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/scandriglia\/turismo\/dal-regno-ditalia-ad-oggi\/","url":"https:\/\/comunicacity.net\/scandriglia\/turismo\/dal-regno-ditalia-ad-oggi\/","name":"Dal Regno d\u2019Italia ad oggi - Scandriglia","isPartOf":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#website"},"datePublished":"2020-05-25T14:44:22+00:00","dateModified":"2020-05-25T14:50:28+00:00","breadcrumb":{"@id":"https:\/\/comunicacity.net\/scandriglia\/turismo\/dal-regno-ditalia-ad-oggi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/scandriglia\/turismo\/dal-regno-ditalia-ad-oggi\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/scandriglia\/turismo\/dal-regno-ditalia-ad-oggi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/scandriglia\/"},{"@type":"ListItem","position":2,"name":"Dal Regno d\u2019Italia ad oggi"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/scandriglia\/#website","url":"https:\/\/comunicacity.net\/scandriglia\/","name":"Scandriglia","description":"Ecco un altro sito ComunicaCity","publisher":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/scandriglia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/comunicacity.net\/scandriglia\/#organization","name":"ComunicaCity","url":"https:\/\/comunicacity.net\/scandriglia\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"ComunicaCity"},"image":{"@id":"https:\/\/comunicacity.net\/scandriglia\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/facebook.com\/ComunicaCity","https:\/\/x.com\/comunicacity"]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/turismo\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/turismo"}],"about":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/types\/turismo"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/media?parent=50"}],"wp:term":[{"taxonomy":"plugin_turismo","embeddable":true,"href":"https:\/\/comunicacity.net\/scandriglia\/wp-json\/wp\/v2\/plugin_turismo?post=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}