{"id":1682,"date":"2019-01-05T11:00:56","date_gmt":"2019-01-05T10:00:56","guid":{"rendered":"https:\/\/comunicacity.net\/solofra\/?p=1682"},"modified":"2018-12-27T18:37:27","modified_gmt":"2018-12-27T17:37:27","slug":"orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/","title":{"rendered":"Orchestra da Camera Irpinia &#8211; Coro Polifonico della Cattedrale di Ariano Irpino &#8211; 5 gennaio 2019"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-1683\" src=\"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/Orchestra_Irpinia-1-1024x894.jpg\" alt=\"\" width=\"680\" height=\"594\" srcset=\"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/Orchestra_Irpinia-1-1024x894.jpg 1024w, https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/Orchestra_Irpinia-1-300x262.jpg 300w, https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/Orchestra_Irpinia-1-768x671.jpg 768w, https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/Orchestra_Irpinia-1-680x594.jpg 680w, https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/Orchestra_Irpinia-1-800x698.jpg 800w, https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/Orchestra_Irpinia-1.jpg 2048w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1684 aligncenter\" src=\"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/coro_polifonico-1.jpg\" alt=\"\" width=\"543\" height=\"339\" srcset=\"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/coro_polifonico-1.jpg 543w, https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/coro_polifonico-1-300x187.jpg 300w\" sizes=\"auto, (max-width: 543px) 100vw, 543px\" \/><\/p>\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":194,"featured_media":1685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1682","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Orchestra da Camera Irpinia - Coro Polifonico della Cattedrale di Ariano Irpino - 5 gennaio 2019 - Solofra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orchestra da Camera Irpinia - Coro Polifonico della Cattedrale di Ariano Irpino - 5 gennaio 2019 - Solofra\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Solofra\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-05T10:00:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/2019_05_01-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"656\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pasqualecorreale\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pasqualecorreale\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/01\\\/05\\\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/01\\\/05\\\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\\\/\"},\"author\":{\"name\":\"pasqualecorreale\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#\\\/schema\\\/person\\\/5d4ffd1ce31d95b751a00d878b7073bd\"},\"headline\":\"Orchestra da Camera Irpinia &#8211; Coro Polifonico della Cattedrale di Ariano Irpino &#8211; 5 gennaio 2019\",\"datePublished\":\"2019-01-05T10:00:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/01\\\/05\\\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\\\/\"},\"wordCount\":14,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/01\\\/05\\\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2018\\\/12\\\/2019_05_01-1.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/01\\\/05\\\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/01\\\/05\\\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\\\/\",\"name\":\"Orchestra da Camera Irpinia - Coro Polifonico della Cattedrale di Ariano Irpino - 5 gennaio 2019 - Solofra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/01\\\/05\\\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/01\\\/05\\\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2018\\\/12\\\/2019_05_01-1.jpg\",\"datePublished\":\"2019-01-05T10:00:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#\\\/schema\\\/person\\\/5d4ffd1ce31d95b751a00d878b7073bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/01\\\/05\\\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/01\\\/05\\\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/01\\\/05\\\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2018\\\/12\\\/2019_05_01-1.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2018\\\/12\\\/2019_05_01-1.jpg\",\"width\":656,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/01\\\/05\\\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Orchestra da Camera Irpinia &#8211; Coro Polifonico della Cattedrale di Ariano Irpino &#8211; 5 gennaio 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/\",\"name\":\"Solofra\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#\\\/schema\\\/person\\\/5d4ffd1ce31d95b751a00d878b7073bd\",\"name\":\"pasqualecorreale\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g\",\"caption\":\"pasqualecorreale\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/author\\\/pasqualecorreale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orchestra da Camera Irpinia - Coro Polifonico della Cattedrale di Ariano Irpino - 5 gennaio 2019 - Solofra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/","og_locale":"it_IT","og_type":"article","og_title":"Orchestra da Camera Irpinia - Coro Polifonico della Cattedrale di Ariano Irpino - 5 gennaio 2019 - Solofra","og_url":"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/","og_site_name":"Solofra","article_published_time":"2019-01-05T10:00:56+00:00","og_image":[{"width":656,"height":960,"url":"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/2019_05_01-1.jpg","type":"image\/jpeg"}],"author":"pasqualecorreale","twitter_misc":{"Scritto da":"pasqualecorreale"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/"},"author":{"name":"pasqualecorreale","@id":"https:\/\/comunicacity.net\/solofra\/#\/schema\/person\/5d4ffd1ce31d95b751a00d878b7073bd"},"headline":"Orchestra da Camera Irpinia &#8211; Coro Polifonico della Cattedrale di Ariano Irpino &#8211; 5 gennaio 2019","datePublished":"2019-01-05T10:00:56+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/"},"wordCount":14,"image":{"@id":"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/2019_05_01-1.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/","url":"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/","name":"Orchestra da Camera Irpinia - Coro Polifonico della Cattedrale di Ariano Irpino - 5 gennaio 2019 - Solofra","isPartOf":{"@id":"https:\/\/comunicacity.net\/solofra\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/2019_05_01-1.jpg","datePublished":"2019-01-05T10:00:56+00:00","author":{"@id":"https:\/\/comunicacity.net\/solofra\/#\/schema\/person\/5d4ffd1ce31d95b751a00d878b7073bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/#primaryimage","url":"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/2019_05_01-1.jpg","contentUrl":"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2018\/12\/2019_05_01-1.jpg","width":656,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/solofra\/2019\/01\/05\/orchestra-da-camera-irpinia-coro-polifonico-della-cattedrale-di-ariano-irpino-5-gennaio-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/solofra\/"},{"@type":"ListItem","position":2,"name":"Orchestra da Camera Irpinia &#8211; Coro Polifonico della Cattedrale di Ariano Irpino &#8211; 5 gennaio 2019"}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/solofra\/#website","url":"https:\/\/comunicacity.net\/solofra\/","name":"Solofra","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/solofra\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/solofra\/#\/schema\/person\/5d4ffd1ce31d95b751a00d878b7073bd","name":"pasqualecorreale","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g","caption":"pasqualecorreale"},"url":"https:\/\/comunicacity.net\/solofra\/author\/pasqualecorreale\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts\/1682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/users\/194"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/comments?post=1682"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts\/1682\/revisions"}],"predecessor-version":[{"id":1686,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts\/1682\/revisions\/1686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/media\/1685"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/media?parent=1682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/categories?post=1682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/tags?post=1682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}