{"id":2251,"date":"2019-12-11T09:48:04","date_gmt":"2019-12-11T08:48:04","guid":{"rendered":"https:\/\/comunicacity.net\/solofra\/?p=2251"},"modified":"2019-12-11T09:48:04","modified_gmt":"2019-12-11T08:48:04","slug":"3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine","status":"publish","type":"post","link":"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/","title":{"rendered":"3\u00b0Concorso a premi &#8211; Per i migliori addobbi natalizi di balconi e vetrine."},"content":{"rendered":"\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":194,"featured_media":2252,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-2251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3\u00b0Concorso a premi - Per i migliori addobbi natalizi di balconi e vetrine. - Solofra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3\u00b0Concorso a premi - Per i migliori addobbi natalizi di balconi e vetrine. - Solofra\" \/>\n<meta property=\"og:url\" content=\"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/\" \/>\n<meta property=\"og:site_name\" content=\"Solofra\" \/>\n<meta property=\"article:published_time\" content=\"2019-12-11T08:48:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2019\/12\/PHOTO-2019-12-11-09-37-33-e1576054064402.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"1072\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"pasqualecorreale\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"pasqualecorreale\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/12\\\/11\\\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/12\\\/11\\\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\\\/\"},\"author\":{\"name\":\"pasqualecorreale\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#\\\/schema\\\/person\\\/5d4ffd1ce31d95b751a00d878b7073bd\"},\"headline\":\"3\u00b0Concorso a premi &#8211; Per i migliori addobbi natalizi di balconi e vetrine.\",\"datePublished\":\"2019-12-11T08:48:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/12\\\/11\\\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\\\/\"},\"wordCount\":13,\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/12\\\/11\\\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2019\\\/12\\\/PHOTO-2019-12-11-09-37-33-e1576054064402.jpg\",\"articleSection\":[\"Eventi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/12\\\/11\\\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\\\/\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/12\\\/11\\\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\\\/\",\"name\":\"3\u00b0Concorso a premi - Per i migliori addobbi natalizi di balconi e vetrine. - Solofra\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/12\\\/11\\\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/12\\\/11\\\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2019\\\/12\\\/PHOTO-2019-12-11-09-37-33-e1576054064402.jpg\",\"datePublished\":\"2019-12-11T08:48:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#\\\/schema\\\/person\\\/5d4ffd1ce31d95b751a00d878b7073bd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/12\\\/11\\\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/12\\\/11\\\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/12\\\/11\\\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\\\/#primaryimage\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2019\\\/12\\\/PHOTO-2019-12-11-09-37-33-e1576054064402.jpg\",\"contentUrl\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2019\\\/12\\\/PHOTO-2019-12-11-09-37-33-e1576054064402.jpg\",\"width\":750,\"height\":1072},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/2019\\\/12\\\/11\\\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3\u00b0Concorso a premi &#8211; Per i migliori addobbi natalizi di balconi e vetrine.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#website\",\"url\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/\",\"name\":\"Solofra\",\"description\":\"Il Tuo Comune che Comunica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/#\\\/schema\\\/person\\\/5d4ffd1ce31d95b751a00d878b7073bd\",\"name\":\"pasqualecorreale\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g\",\"caption\":\"pasqualecorreale\"},\"url\":\"https:\\\/\\\/comunicacity.net\\\/solofra\\\/author\\\/pasqualecorreale\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3\u00b0Concorso a premi - Per i migliori addobbi natalizi di balconi e vetrine. - Solofra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/","og_locale":"it_IT","og_type":"article","og_title":"3\u00b0Concorso a premi - Per i migliori addobbi natalizi di balconi e vetrine. - Solofra","og_url":"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/","og_site_name":"Solofra","article_published_time":"2019-12-11T08:48:04+00:00","og_image":[{"width":750,"height":1072,"url":"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2019\/12\/PHOTO-2019-12-11-09-37-33-e1576054064402.jpg","type":"image\/jpeg"}],"author":"pasqualecorreale","twitter_misc":{"Scritto da":"pasqualecorreale"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/#article","isPartOf":{"@id":"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/"},"author":{"name":"pasqualecorreale","@id":"https:\/\/comunicacity.net\/solofra\/#\/schema\/person\/5d4ffd1ce31d95b751a00d878b7073bd"},"headline":"3\u00b0Concorso a premi &#8211; Per i migliori addobbi natalizi di balconi e vetrine.","datePublished":"2019-12-11T08:48:04+00:00","mainEntityOfPage":{"@id":"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/"},"wordCount":13,"image":{"@id":"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2019\/12\/PHOTO-2019-12-11-09-37-33-e1576054064402.jpg","articleSection":["Eventi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/","url":"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/","name":"3\u00b0Concorso a premi - Per i migliori addobbi natalizi di balconi e vetrine. - Solofra","isPartOf":{"@id":"https:\/\/comunicacity.net\/solofra\/#website"},"primaryImageOfPage":{"@id":"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/#primaryimage"},"image":{"@id":"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/#primaryimage"},"thumbnailUrl":"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2019\/12\/PHOTO-2019-12-11-09-37-33-e1576054064402.jpg","datePublished":"2019-12-11T08:48:04+00:00","author":{"@id":"https:\/\/comunicacity.net\/solofra\/#\/schema\/person\/5d4ffd1ce31d95b751a00d878b7073bd"},"breadcrumb":{"@id":"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/#primaryimage","url":"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2019\/12\/PHOTO-2019-12-11-09-37-33-e1576054064402.jpg","contentUrl":"https:\/\/comunicacity.net\/solofra\/wp-content\/uploads\/sites\/15\/2019\/12\/PHOTO-2019-12-11-09-37-33-e1576054064402.jpg","width":750,"height":1072},{"@type":"BreadcrumbList","@id":"https:\/\/comunicacity.net\/solofra\/2019\/12\/11\/3concorso-a-premi-per-i-migliori-addobbi-natalizi-di-balconi-e-vetrine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/comunicacity.net\/solofra\/"},{"@type":"ListItem","position":2,"name":"3\u00b0Concorso a premi &#8211; Per i migliori addobbi natalizi di balconi e vetrine."}]},{"@type":"WebSite","@id":"https:\/\/comunicacity.net\/solofra\/#website","url":"https:\/\/comunicacity.net\/solofra\/","name":"Solofra","description":"Il Tuo Comune che Comunica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/comunicacity.net\/solofra\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/comunicacity.net\/solofra\/#\/schema\/person\/5d4ffd1ce31d95b751a00d878b7073bd","name":"pasqualecorreale","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/981112a94e82ccdbfa3bafce9d53488e45b839da16f0defde9a6ca888d672a05?s=96&d=mm&r=g","caption":"pasqualecorreale"},"url":"https:\/\/comunicacity.net\/solofra\/author\/pasqualecorreale\/"}]}},"meta_box":{"cc4_urg_colore":"","cc4_urg_data_inizio":"","cc4_urg_data_fine":"","cc4_cor_positivi_oggi":"","cc4_cor_negativizzati_oggi":"","cc4_cor_deceduti_oggi":"","cc4_cor_positivi_totali":"","cc4_cor_negativizzati_totali":"","cc4_cor_deceduti_totali":"","cc4_cor_attualmente_positivi":"","cc4_eve_data_inizio":"","cc4_eve_data_fine":"","cc4_eve_indirizzo":"","cc4_eve_posizione":{"latitude":"","longitude":"","zoom":""},"cc4_eve_telefono":"","cc4_eve_email":"","cc4_eve_web":"","cc4_eve_fb":"","sitopa_id":""},"_links":{"self":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts\/2251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/users\/194"}],"replies":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/comments?post=2251"}],"version-history":[{"count":1,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts\/2251\/revisions"}],"predecessor-version":[{"id":2253,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/posts\/2251\/revisions\/2253"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/media\/2252"}],"wp:attachment":[{"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/media?parent=2251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/categories?post=2251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/comunicacity.net\/solofra\/wp-json\/wp\/v2\/tags?post=2251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}